{"id":77478,"date":"2020-01-17T00:56:39","date_gmt":"2020-01-17T04:56:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=77478"},"modified":"2020-01-17T00:56:39","modified_gmt":"2020-01-17T04:56:39","slug":"aguilas-demuestran-valia-en-el-valle-de-la-muerte-vencen-leones-y-se-miden-al-licey","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aguilas-demuestran-valia-en-el-valle-de-la-muerte-vencen-leones-y-se-miden-al-licey\/","title":{"rendered":"\u00c1guilas demuestran val\u00eda en \u201cEl Valle de la Muerte\u201d; vencen Leones y se miden al Licey"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/lidom-aguilas-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-77479\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/lidom-aguilas-4.jpg\" alt=\"\" width=\"770\" height=\"440\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/lidom-aguilas-4.jpg 770w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/lidom-aguilas-4-300x171.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/lidom-aguilas-4-768x439.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/lidom-aguilas-4-595x340.jpg 595w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/a>SANTIAGO.- Las \u00c1guilas Cibae\u00f1as demostraron este jueves su val\u00eda cuando juegan en casa \u201cEl Valle de la Muerte\u201d al vencer 9 carreras por 5 a los Leones del Escogido, en el partido extra del todos contra todos que disputaron en el Estadio Cibao, de esta ciudad.<!--more--><\/p>\n<p>Al salir airosos los cibae\u00f1os ante los capitalinos en partido extra, los ganadores enfrentar\u00e1n la noche de este viernes a los Tigres del Licey, en un choque -segundo juego extra seguido- que definir\u00e1 el boleto a la serie final ante los Toros del Este y que estar\u00e1 pactada al mejor de un 9-5.<\/p>\n<p>Ese juego ante el Licey ser\u00e1 en el Estadio Quisqueya Juan Marichal, de la Ciudad Capital, a las 7:15 de la noche, para cerrar el round robin del Torneo 2019-20 del B\u00e9isbol Profesional de la Rep\u00fablica Dominicana que le dedicaron In Memoriam a Carlos Morales Troncoso y en opci\u00f3n a la Copa BHD Le\u00f3n.<\/p>\n<p>Los Toros abrir\u00e1n en su parque, el Estadio Francisco Micheli, de La Romana, el primer encuentro de la ronda finalista, en un horario que ser\u00e1 programado m\u00e1s tarde cuando la Liga Dominicana de B\u00e9isbol (Lidom), a trav\u00e9s de la direcci\u00f3n t\u00e9cnica haga p\u00fablico el calendario.<\/p>\n<p>El lanzador ganador lo fue el relevista Michael Devine (1-0) con 2.0 entradas sin carreras y tres ponches.<\/p>\n<p>Perdi\u00f3 el abridor escarlata Michael Devine (1-0), tras una labor de 2.0 episodios sin libertades y abanic\u00f3 a tres contrarios.<\/p>\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\">\n<div class=\"wp-block-embed__wrapper\">\n<div class=\"et_post_video\">\n<div class=\"SandboxRoot env-bp-350\" data-twitter-event-id=\"0\">\n<div id=\"twitter-widget-0\" class=\"EmbeddedTweet EmbeddedTweet--cta js-clickToOpenTarget\" lang=\"en\" data-click-to-open-target=\"https:\/\/twitter.com\/LIDOMRD\/status\/1217997540114649088\" data-iframe-title=\"Twitter Tweet\" data-scribe=\"page:tweet\" data-twitter-event-id=\"1\">\n<div class=\"EmbeddedTweet-ancestor EmbeddedTweet-ancestor--repliesRefresh\" data-scribe=\"section:conversation\">\n<blockquote class=\"Tweet Tweet--compact h-entry reply js-tweetIdInfo\" cite=\"https:\/\/twitter.com\/LIDOMRD\/status\/1217977159547080705\" data-tweet-id=\"1217977159547080705\">\n<div class=\"Tweet-ancestorContainer Tweet-ancestorContainer--repliesRefresh\">\n<div class=\"Tweet-ancestorContents Tweet-ancestorContents--repliesRefresh\">\n<div class=\"Tweet-body e-entry-content\" data-scribe=\"component:tweet\">\n<div class=\"Tweet-card\">\n<article class=\"MediaCard\n\n           cards-multimedia\n           customisable-border\" dir=\"ltr\" data-scribe=\"component:card\"><\/p>\n<div class=\"MediaCard-media\">\n<div class=\"MediaCard-widthConstraint js-cspForcedStyle\" data-style=\"max-width: 2000px\">\n<div class=\"MediaCard-mediaContainer MediaCard--roundedTop MediaCard--roundedBottom js-cspForcedStyle\" data-style=\"padding-bottom: 56.2500%\">\n<div class=\"NaturalImage-ctaOverlay PlayButton PlayButton--centered\" data-scribe=\"element:play_button\">\n<div class=\"Icon Icon--playCircle \" title=\"Play Media\" role=\"img\" aria-label=\"Play Media\"><\/div>\n<\/div>\n<p><a class=\"MediaCard-mediaAsset MediaCard-mediaPlaceholder NaturalImage NaturalImage--fill js-playableMediaInterstitial\" href=\"https:\/\/twitter.com\/LIDOMRD\/status\/1217977159547080705\"><img decoding=\"async\" class=\"NaturalImage-image\" src=\"https:\/\/pbs.twimg.com\/ext_tw_video_thumb\/1217976944282734594\/pu\/img\/IMZldlMknoiobIuF?format=jpg&amp;name=small\" alt=\"Embedded video\" data-image=\"https:\/\/pbs.twimg.com\/ext_tw_video_thumb\/1217976944282734594\/pu\/img\/IMZldlMknoiobIuF\" data-scribe=\"element:poster_image\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<div class=\"EmbeddedTweet-tweetContainer\">\n<div class=\"EmbeddedTweet-tweet\">\n<blockquote class=\"Tweet h-entry js-tweetIdInfo subject expanded\" cite=\"https:\/\/twitter.com\/LIDOMRD\/status\/1217997540114649088\" data-tweet-id=\"1217997540114649088\" data-scribe=\"section:subject\">\n<div class=\"Tweet-body e-entry-content\" data-scribe=\"component:tweet\">\n<div class=\"Tweet-card\">\n<article class=\"MediaCard\n\n           cards-multimedia\n           customisable-border\" dir=\"ltr\" data-scribe=\"component:card\"><\/p>\n<div class=\"MediaCard-media\">\n<div class=\"MediaCard-widthConstraint js-cspForcedStyle\" data-style=\"max-width: 2000px\">\n<div class=\"MediaCard-mediaContainer MediaCard--roundedTop MediaCard--roundedBottom js-cspForcedStyle\" data-style=\"padding-bottom: 56.2500%\">\n<div class=\"NaturalImage-ctaOverlay PlayButton PlayButton--centered\" data-scribe=\"element:play_button\">\n<div class=\"Icon Icon--playCircle \" title=\"Play Media\" role=\"img\" aria-label=\"Play Media\"><\/div>\n<\/div>\n<p><a class=\"MediaCard-mediaAsset MediaCard-mediaPlaceholder NaturalImage NaturalImage--fill js-playableMediaInterstitial\" href=\"https:\/\/twitter.com\/LIDOMRD\/status\/1217997540114649088\"><img decoding=\"async\" class=\"NaturalImage-image\" src=\"https:\/\/pbs.twimg.com\/ext_tw_video_thumb\/1217996996461637632\/pu\/img\/kLBoHu-MSfUAR2WO?format=jpg&amp;name=small\" alt=\"Embedded video\" data-image=\"https:\/\/pbs.twimg.com\/ext_tw_video_thumb\/1217996996461637632\/pu\/img\/kLBoHu-MSfUAR2WO\" data-scribe=\"element:poster_image\" \/><\/a><\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"TweetInfo\"><\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/figure>\n<p>Los aguiluchos aseguraron la victoria en un decisivo rally de cinco carreras en el quinto episodio, al que llegaron arriba en el marcador 3-2.<\/p>\n<p>Con Di\u00f3genes Almengo en el mont\u00edculo por los Leones, Rangel Ravelo peg\u00f3 sencillo al right fielder, de inmediato los sustituye Edward Paredes y Jordan Patterson lo recibe con hit al prado derecho y Ravelo avanza a la antesala. Craig Stem entra a lanzar por Paredes y Carlos G\u00f3mez conecta un doble por el center fielder que impulsa a Ravelo y Patterson se cruza a la 3B. Wil\u00edn Rosario batea un incogible productor por el left y anota Patterson, G\u00f3mez a la 3B y luego pisa el plato por inatrapable remolcador de Rusney Castillo. Francisco Pe\u00f1a es golpeado y se llenan las bases, Alfredo F\u00edgaro sub el box por Stem y Diego Goris empuja a Rosario con rodado al segunda base y Ram\u00f3n Torres impulsa una vuelta con un fly de sacrificio al bosque izquierdo.<\/p>\n<p>Previo, en el tercer episodio, las cuyayas hab\u00eda anotado tres vueltas empujada cada uno por Ronny Rodr\u00edguez con rolata al siore y en la jugada anot\u00f3 Diego Goris, y Rangel Ravelo solt\u00f3 un sencillo productor en las piernas de Ram\u00f3n Torres y Carlos G\u00f3mez impuls\u00f3 una vuelta m\u00e1s singles con imparable al center fielder.<\/p>\n<p>En el octavo pisaron la goma una vez m\u00e1s, con sencillo remolcador de Rangel Ravelo al left que hizo anotar a Ram\u00f3n Torres.<\/p>\n<p>Los melenudos anotaron de a una carrera en el primer inning, quinto, sexto, s\u00e9ptimo y noveno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTIAGO.- Las \u00c1guilas Cibae\u00f1as demostraron este jueves su val\u00eda cuando juegan en casa \u201cEl Valle de la Muerte\u201d al vencer 9 carreras por 5 a los Leones del Escogido, en el partido extra del todos contra todos que disputaron en el Estadio Cibao, de esta ciudad.<\/p>\n","protected":false},"author":12,"featured_media":77479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-77478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=77478"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77478\/revisions"}],"predecessor-version":[{"id":77480,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77478\/revisions\/77480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/77479"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=77478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=77478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=77478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}