{"id":77664,"date":"2020-01-26T22:56:28","date_gmt":"2020-01-27T02:56:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=77664"},"modified":"2020-01-26T22:56:28","modified_gmt":"2020-01-27T02:56:28","slug":"magic-johnson-jordan-y-lebron-james-abatidos-con-la-muerte-de-kobe-bryant","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/magic-johnson-jordan-y-lebron-james-abatidos-con-la-muerte-de-kobe-bryant\/","title":{"rendered":"Magic Johnson, Jordan y LeBron James abatidos con la muerte de Kobe Bryant"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/bryant_kobe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-77666\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/bryant_kobe.jpg\" alt=\"\" width=\"610\" height=\"380\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/bryant_kobe.jpg 610w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/bryant_kobe-300x187.jpg 300w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/a>El comisionado de la NBA, Adam Silver, las exestrellas Magic Johnson y Michael Jordan y el actual astro de los Lakers, LeBron James, se manifestaron muy dolidos con el fallecimiento del tambi\u00e9n exestelar Kobe Bryant y su hija Gianna, de 13 a\u00f1os, en un accidente de helic\u00f3ptero este domingo.<\/p>\n<p>La impactante p\u00e9rdida de la superestrella que inspir\u00f3 e influy\u00f3 en la \u00faltima generaci\u00f3n de j\u00f3venes talentos de la NBA golpe\u00f3 duramente en la liga.<\/p>\n<div class=\"fa5b2699cddc88102eeb51989b6d133b\" data-index=\"1\"><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-391416 jetpack-lazy-image jetpack-lazy-image--handled\" src=\"https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?resize=696%2C417&amp;ssl=1\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" srcset=\"https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?w=1039&amp;ssl=1 1039w, https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?resize=300%2C180&amp;ssl=1 300w, https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?resize=1024%2C614&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?resize=768%2C461&amp;ssl=1 768w, https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?resize=696%2C417&amp;ssl=1 696w, https:\/\/i1.wp.com\/ensegundos.do\/wp-content\/uploads\/2020\/01\/Kobe-Lebron-.jpg?resize=700%2C420&amp;ssl=1 700w\" alt=\"\" width=\"696\" height=\"417\" data-recalc-dims=\"1\" data-lazy-loaded=\"1\" \/><\/p>\n<p><strong>Jordan, considerado el mejor basquetbolista de todos los tiempos, dijo estar \u201cconmocionado al enterarme de la tr\u00e1gica muerte de Kobe y (su hija) Gianna. Las palabras no son suficientes para describir mi dolor\u201d.<\/strong><\/p>\n<p><strong>\u201cAmaba a Kobe, era como un hermano peque\u00f1o para m\u00ed. Hablamos a menudo, extra\u00f1ar\u00e9 mucho estas conversaciones. Era un competidor feroz, uno de los mejores jugadores en este deporte y una fuerza creativa\u201d, escribi\u00f3 Jordan en Twitter.<\/strong><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/Kobe-640x400.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-77665\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/Kobe-640x400.jpg\" alt=\"\" width=\"640\" height=\"400\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/Kobe-640x400.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/Kobe-640x400-300x188.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>\u201cLa familia de la NBA est\u00e1 devastada\u201d, dijo a su vez el comisionado de la NBA, Adam Silver.<\/p>\n<p>Bryant, quien falleci\u00f3 a los 41 a\u00f1os, gan\u00f3 cinco t\u00edtulos de la NBA en sus 20 temporadas con los Lakers, terminando con 33.643 puntos, 7.047 rebotes y 6.306 asistencias en 1.346 juegos de la NBA en su carrera.<\/p>\n<p>Tambi\u00e9n ayud\u00f3 al equipo estadounidense a capturar el oro ol\u00edmpico en 2008 y 2012.<\/p>\n<p><strong>\u201cUno de los mejores jugadores de baloncesto de todos los tiempos\u201d, dijo por su parte LeBron, quien super\u00f3 a Bryant el s\u00e1bado ubic\u00e1ndose en el tercer lugar en la lista de todos los tiempos en anotaci\u00f3n, solo unas horas antes del accidente.<\/strong><\/p>\n<p>\u201cEstaba tratando de destruirte cuando estaba en el suelo, de eso se trataba\u201d. Bryant se autodenomin\u00f3 \u201cMamba Negra\u201d por su habilidad para atacar r\u00e1pidamente con una precisi\u00f3n mortal como anotador. \u201cNos re\u00edmos y bromeamos sobre la mentalidad de Mamba. Todos la vamos a necesitar en este momento\u201d, se\u00f1al\u00f3 por su parte el entrenador de Los Angeles Clippers, Doc Rivers.<\/p>\n<p><strong>\u201cEsta es una gran p\u00e9rdida. Hay tantas personas que toc\u00f3. Le quedaba mucho m\u00e1s por hacer y estaba empezando a hacerlo. Nunca lo hab\u00eda visto m\u00e1s feliz\u201d. \u201cEn este momento, todos somos fan\u00e1ticos de los Lakers, todos somos Lakers en este momento\u201d, a\u00f1adi\u00f3.<\/strong><\/p>\n<p>Johnson dijo que estaba \u201cdesconsolado\u201d y llam\u00f3 a Bryant \u201cel mejor Laker de todos los tiempos\u201d, y agreg\u00f3: \u201cEstoy incr\u00e9dulo y he estado llorando toda la ma\u00f1ana\u201d.<\/p>\n<p>Por otro lado, la leyenda Abdul-Jabbar apunt\u00f3 que \u201cesta p\u00e9rdida es dif\u00edcil de comprender\u201d.<\/p>\n<p>Bryant debut\u00f3 en la NBA como un adolescente muy promocionado en 1996, el jugador m\u00e1s joven en la historia de la liga en ese momento solo unos d\u00edas despu\u00e9s de cumplir 18 a\u00f1os, y se retir\u00f3 en 2016 a los 37 a\u00f1os.<\/p>\n<p>\u201cEsta es una p\u00e9rdida monumental para toda la comunidad del baloncesto\u201d, dijo la Asociaci\u00f3n Nacional de Jugadores de Baloncesto. \u201cNuestros corazones est\u00e1n simplemente rotos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El comisionado de la NBA, Adam Silver, las exestrellas Magic Johnson y Michael Jordan y el actual astro de los Lakers, LeBron James, se manifestaron muy dolidos con el fallecimiento del tambi\u00e9n exestelar Kobe Bryant y su hija Gianna, de 13 a\u00f1os, en un accidente de helic\u00f3ptero este domingo. La impactante p\u00e9rdida de la superestrella que inspir\u00f3 e influy\u00f3 en la \u00faltima generaci\u00f3n de j\u00f3venes talentos de la NBA golpe\u00f3 duramente en la liga. Jordan, considerado el mejor basquetbolista de todos los tiempos, dijo estar \u201cconmocionado al enterarme de la tr\u00e1gica muerte de Kobe y (su hija) Gianna. Las palabras no son suficientes para describir mi dolor\u201d. \u201cAmaba a Kobe, era como un hermano peque\u00f1o para m\u00ed. Hablamos a menudo, extra\u00f1ar\u00e9 mucho estas conversaciones. Era un competidor feroz, uno de los mejores jugadores en este deporte y una fuerza creativa\u201d, escribi\u00f3 Jordan en Twitter. \u201cLa familia de la NBA est\u00e1 devastada\u201d, dijo a su vez el comisionado de la NBA, Adam Silver. Bryant, quien falleci\u00f3 a los 41 a\u00f1os, gan\u00f3 cinco t\u00edtulos de la NBA en sus 20 temporadas con los Lakers, terminando con 33.643 puntos, 7.047 rebotes y 6.306 asistencias en 1.346 juegos de la NBA en su carrera. Tambi\u00e9n ayud\u00f3 al equipo estadounidense a capturar el oro ol\u00edmpico en 2008 y 2012. \u201cUno de los mejores jugadores de baloncesto de todos los tiempos\u201d, dijo por su parte LeBron, quien super\u00f3 a Bryant el s\u00e1bado ubic\u00e1ndose en el tercer lugar en la lista de todos los tiempos en anotaci\u00f3n, solo unas horas antes del accidente. \u201cEstaba tratando de destruirte cuando estaba en el suelo, de eso se trataba\u201d. Bryant se autodenomin\u00f3 \u201cMamba Negra\u201d por su habilidad para atacar r\u00e1pidamente con una precisi\u00f3n mortal como anotador. \u201cNos re\u00edmos y bromeamos sobre la mentalidad de Mamba. Todos la vamos a necesitar en este momento\u201d, se\u00f1al\u00f3 por su parte el entrenador de Los Angeles Clippers, Doc Rivers. \u201cEsta es una gran p\u00e9rdida. Hay tantas personas que toc\u00f3. Le quedaba mucho m\u00e1s por hacer y estaba empezando a hacerlo. Nunca lo hab\u00eda visto m\u00e1s feliz\u201d. \u201cEn este momento, todos somos fan\u00e1ticos de los Lakers, todos somos Lakers en este momento\u201d, a\u00f1adi\u00f3. Johnson dijo que estaba \u201cdesconsolado\u201d y llam\u00f3 a Bryant \u201cel mejor Laker de todos los tiempos\u201d, y agreg\u00f3: \u201cEstoy incr\u00e9dulo y he estado llorando toda la ma\u00f1ana\u201d. Por otro lado, la leyenda Abdul-Jabbar apunt\u00f3 que \u201cesta p\u00e9rdida es dif\u00edcil de comprender\u201d. Bryant debut\u00f3 en la NBA como un adolescente muy promocionado en 1996, el jugador m\u00e1s joven en la historia de la liga en ese momento solo unos d\u00edas despu\u00e9s de cumplir 18 a\u00f1os, y se retir\u00f3 en 2016 a los 37 a\u00f1os. \u201cEsta es una p\u00e9rdida monumental para toda la comunidad del baloncesto\u201d, dijo la Asociaci\u00f3n Nacional de Jugadores de Baloncesto. \u201cNuestros corazones est\u00e1n simplemente rotos\u201d.<\/p>\n","protected":false},"author":12,"featured_media":77666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-77664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=77664"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77664\/revisions"}],"predecessor-version":[{"id":77667,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77664\/revisions\/77667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/77666"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=77664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=77664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=77664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}