{"id":77679,"date":"2020-01-27T09:23:35","date_gmt":"2020-01-27T13:23:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=77679"},"modified":"2020-01-27T09:23:35","modified_gmt":"2020-01-27T13:23:35","slug":"taiwan-multa-con-10-000-dolares-a-un-infectado-con-el-coronavirus-por-ocultar-los-sintomas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/taiwan-multa-con-10-000-dolares-a-un-infectado-con-el-coronavirus-por-ocultar-los-sintomas\/","title":{"rendered":"Taiw\u00e1n multa con 10.000 d\u00f3lares a un infectado con el coronavirus por ocultar los s\u00edntomas"},"content":{"rendered":"<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/coronavirus-oculto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-77680\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/01\/coronavirus-oculto.jpg\" alt=\"\" width=\"300\" height=\"230\" \/><\/a>El Gobierno de Kaohsiung (Taiw\u00e1n, China) multar\u00e1 a un hombre\u00a0<strong>infectado por el coronavirus<\/strong>\u00a0por no informar\u00a0a las autoridades\u00a0que ten\u00eda s\u00edntomas de sufrir una infecci\u00f3n en las v\u00edas respiratorias superiores tras regresar de la ciudad de Wuhan.<!--more--><\/p>\n<p>Pan Chao-ying, especialista del Departamento de Salud de la ciudad, declar\u00f3 que ese var\u00f3n ser\u00e1 multado con 300,000 nuevos d\u00f3lares de Taiw\u00e1n, unos\u00a0<strong>10,000 d\u00f3lares estadounidenses<\/strong>, por violar la Ley de Control de Enfermedades Transmisibles,\u00a0<a href=\"https:\/\/focustaiwan.tw\/society\/202001250011\" target=\"_blank\" rel=\"noopener noreferrer\">informa<\/a>\u00a0CNA.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\">\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\"><picture class=\"Picture-root Picture-default\"><source srcset=\" \nhttps:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/thumbnail\/5e28bd93e9ff71672f3b92a4.JPG 850w,\n                https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/article\/5e28bd92e9ff71672f3b92a3.JPG 1960w,\n            \" media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" sizes=\"280px\" data-srcset=\"\n                https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/thumbnail\/5e28bd93e9ff71672f3b92a4.JPG 850w,\n                https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/article\/5e28bd92e9ff71672f3b92a3.JPG 1960w,\n            \" \/><source srcset=\" \nhttps:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/thumbnail\/5e28bd93e9ff71672f3b92a4.JPG 460w,\n              https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/article\/5e28bd92e9ff71672f3b92a3.JPG 980w,\n            \" sizes=\"280px\" data-srcset=\"\n              https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/thumbnail\/5e28bd93e9ff71672f3b92a4.JPG 460w,\n              https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/article\/5e28bd92e9ff71672f3b92a3.JPG 980w,\n            \" \/><img decoding=\"async\" class=\"Picture-root Picture-default lazyautosizes lazyloaded\" src=\"https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/thumbnail\/5e28bd93e9ff71672f3b92a4.JPG\" sizes=\"280px\" alt=\"\u00bfQu\u00e9 son los s\u00faper propagadores del coronavirus y por qu\u00e9 son cruciales para atajar la enfermedad?\" data-sizes=\"auto\" data-src=\"https:\/\/cdni.rt.com\/actualidad\/public_images\/2020.01\/thumbnail\/5e28bd93e9ff71672f3b92a4.JPG\" \/><\/picture><\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<p>Adem\u00e1s, este hombre de unos 50 a\u00f1os\u00a0<strong>visit\u00f3 un club de baile<\/strong>\u00a0un d\u00eda despu\u00e9s de regresar de Wuhan sin usar una m\u00e1scara facial y, posteriormente, una trabajadora de ese local sufri\u00f3\u00a0<strong>s\u00edntomas de tener virus<\/strong>\u00a0y tuvo que recibir tratamiento m\u00e9dico.<\/p>\n<p>Esos hechos provocaron que el establecimiento fuera cerrado y desinfectado a partir del 25 de enero, mientras que se vigilar\u00e1 la salud de las personas con las que el var\u00f3n estuvo en contacto\u00a0<strong>hasta el 5 de febrero<\/strong>.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-youtube\">\n<div class=\"YouTubeEmbed\">\n<div class=\"YouTubeEmbed-cover lazyloaded\" data-youtubesrc=\"\/\/www.youtube.com\/embed\/19snznDGMAY\" data-youtubeid=\"19snznDGMAY\"><button class=\"YouTubeEmbed-button\"><\/button><picture class=\"YouTubeEmbed-image YouTubeEmbed-image--visible\"><source srcset=\"https:\/\/i.ytimg.com\/vi\/19snznDGMAY\/hqdefault.jpg\" media=\"(max-width: 600px)\" data-srcset=\"https:\/\/i.ytimg.com\/vi\/19snznDGMAY\/hqdefault.jpg\" \/><source srcset=\"https:\/\/i.ytimg.com\/vi\/19snznDGMAY\/sddefault.jpg\" media=\"(max-width: 900px)\" data-srcset=\"https:\/\/i.ytimg.com\/vi\/19snznDGMAY\/sddefault.jpg\" \/><img decoding=\"async\" class=\" lazyloaded\" src=\"https:\/\/i.ytimg.com\/vi\/19snznDGMAY\/sddefault.jpg\" data-src=\"https:\/\/i.ytimg.com\/vi\/19snznDGMAY\/sddefault.jpg\" \/><\/picture><\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"ArticleView-googleNewsBanner\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Kaohsiung (Taiw\u00e1n, China) multar\u00e1 a un hombre\u00a0infectado por el coronavirus\u00a0por no informar\u00a0a las autoridades\u00a0que ten\u00eda s\u00edntomas de sufrir una infecci\u00f3n en las v\u00edas respiratorias superiores tras regresar de la ciudad de Wuhan.<\/p>\n","protected":false},"author":12,"featured_media":77680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-77679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=77679"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77679\/revisions"}],"predecessor-version":[{"id":77681,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/77679\/revisions\/77681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/77680"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=77679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=77679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=77679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}