{"id":78069,"date":"2020-04-29T09:49:35","date_gmt":"2020-04-29T13:49:35","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78069"},"modified":"2020-04-29T09:49:39","modified_gmt":"2020-04-29T13:49:39","slug":"ministro-de-educacion-asegura-ano-escolar-esta-pautado-finalizar-el-19-de-junio","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ministro-de-educacion-asegura-ano-escolar-esta-pautado-finalizar-el-19-de-junio\/","title":{"rendered":"Ministro de Educaci\u00f3n asegura a\u00f1o escolar est\u00e1 pautado finalizar el 19 de junio"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/04\/202004281928431.jpeg\" alt=\"\" class=\"wp-image-78070\" width=\"195\" height=\"100\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/04\/202004281928431.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/04\/202004281928431-300x155.jpeg 300w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nEl ministro de Educaci\u00f3n, Antonio Pe\u00f1a Mirabal, afirm\u00f3 que tal y como estableci\u00f3 el Consejo Nacional de Educaci\u00f3n (CNE), el presente a\u00f1o escolar 2019-2020 tiene previsto concluir el pr\u00f3ximo 19 de junio como est\u00e1 establecido en el calendario escolar.<br \/>Precis\u00f3, adem\u00e1s, detalles de cara al siguiente a\u00f1o lectivo y la posibilidad de que se tenga que adelantar el inicio para contemplar el contenido curricular pendiente.<ins><\/ins>Explic\u00f3 que hasta el 12 de marzo, \u00faltimo d\u00eda de clases presenciales, se hab\u00eda impartido el 70 por ciento del contenido curricular, por lo que se busca la forma de priorizar los elementos fundamentales del 30 por ciento restante para hacer un reforzamiento.\u00bbVeremos si el pr\u00f3ximo a\u00f1o escolar lo podemos adelantar un poco y dar en los primeros 30 o 45 d\u00edas ese reforzamiento de los contenidos que no hemos podido dar de manera virtual, correspondiente a ese 30 por ciento y, de esa manera, poder complementar la conclusi\u00f3n de este a\u00f1o escolar con el pr\u00f3ximo\u201d, explic\u00f3 el titular de Educaci\u00f3n.Pe\u00f1a Mirabal aclar\u00f3 que el Ministerio de Educaci\u00f3n (MINERD) nunca se ha referido a la extensi\u00f3n del presente a\u00f1o escolar, sino que lo que se est\u00e1 haciendo en este per\u00edodo de cuarentena es que los docentes han creado un ambiente de escolaridad con los estudiantes en sus hogares, a trav\u00e9s de la plataforma en linea.minerd.gob.do que la instituci\u00f3n ha puesto a disposici\u00f3n o mediante las redes sociales.Dijo que en el portal habilitado por el MINERD hay contenido permanente del curr\u00edculo educativo, y el cual ha recibido 600 mil visitas en el periodo de cuarentena.&nbsp; \u00abEs decir, que en el Ministerio de Educaci\u00f3n no se ha hablado de extender el a\u00f1o escolar\u00bb, precis\u00f3 el funcionario.El MINERD ha comprobado que alrededor del 80 por ciento de las familias de los estudiantes a nivel nacional han recibido los contenidos educativos, colgados en las diferentes plataformas digitales.\u00bbGracias a todas esas computadoras que se han entregado y a las laptops a nuestros maestros y maestras es que nuestros estudiantes han podido estar accesando de manera permanente a la p\u00e1gina que hemos puesto a su disposici\u00f3n, es decir, no se puede hablar de p\u00e9rdida del a\u00f1o escolar porque hemos avanzado en m\u00e1s del 70 por ciento en el contenido curricular\u00bb, afirmo Pe\u00f1a Mirabal.<strong><em>Gu\u00edas did\u00e1cticas<\/em><\/strong>El ministro inform\u00f3 que para los estudiantes que no tienen acceso a Internet, el Viceministro T\u00e9cnico-Pedag\u00f3gico ha elaborado unas gu\u00edas did\u00e1cticas para que las familias puedan ayudar a sus hijos respecto a los contenidos impartidos y los que est\u00e1n en el curr\u00edculo.Asegur\u00f3 que se han distribuido m\u00e1s de tres millones de ejemplares de esas gu\u00edas did\u00e1cticas en todo el territorio nacional \u00abde tal manera que el que no pueda conectarse, pueda tener la orientaci\u00f3n de lugar\u00bb.Dijo que el Gobierno, a trav\u00e9s del MINERD ha entregado de manera gratuita m\u00e1s de 300 mil computadoras a estudiantes de Secundaria y que la meta para agosto de este a\u00f1o es llegar a las 650 mil.<strong><em>Pruebas Nacionales<\/em><\/strong>Con relaci\u00f3n a las Pruebas Nacionales, el ministro dijo que deben aplicarse de manera obligatoria, aunque no con la misma rigurosidad; sin embargo, precis\u00f3 que el curso de la pandemia dir\u00e1 si se imparten de manera presencial o virtual.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro de Educaci\u00f3n, Antonio Pe\u00f1a Mirabal, afirm\u00f3 que tal y como estableci\u00f3 el Consejo Nacional de Educaci\u00f3n (CNE), el presente a\u00f1o escolar 2019-2020 tiene previsto concluir el pr\u00f3ximo 19 de junio como est\u00e1 establecido en el calendario escolar.Precis\u00f3, adem\u00e1s, detalles de cara al siguiente a\u00f1o lectivo y la posibilidad de que se tenga que adelantar el inicio para contemplar el contenido curricular pendiente.Explic\u00f3 que hasta el 12 de marzo, \u00faltimo d\u00eda de clases presenciales, se hab\u00eda impartido el 70 por ciento del contenido curricular, por lo que se busca la forma de priorizar los elementos fundamentales del 30 por ciento restante para hacer un reforzamiento.\u00bbVeremos si el pr\u00f3ximo a\u00f1o escolar lo podemos adelantar un poco y dar en los primeros 30 o 45 d\u00edas ese reforzamiento de los contenidos que no hemos podido dar de manera virtual, correspondiente a ese 30 por ciento y, de esa manera, poder complementar la conclusi\u00f3n de este a\u00f1o escolar con el pr\u00f3ximo\u201d, explic\u00f3 el titular de Educaci\u00f3n.Pe\u00f1a Mirabal aclar\u00f3 que el Ministerio de Educaci\u00f3n (MINERD) nunca se ha referido a la extensi\u00f3n del presente a\u00f1o escolar, sino que lo que se est\u00e1 haciendo en este per\u00edodo de cuarentena es que los docentes han creado un ambiente de escolaridad con los estudiantes en sus hogares, a trav\u00e9s de la plataforma en linea.minerd.gob.do que la instituci\u00f3n ha puesto a disposici\u00f3n o mediante las redes sociales.Dijo que en el portal habilitado por el MINERD hay contenido permanente del curr\u00edculo educativo, y el cual ha recibido 600 mil visitas en el periodo de cuarentena.&nbsp; \u00abEs decir, que en el Ministerio de Educaci\u00f3n no se ha hablado de extender el a\u00f1o escolar\u00bb, precis\u00f3 el funcionario.El MINERD ha comprobado que alrededor del 80 por ciento de las familias de los estudiantes a nivel nacional han recibido los contenidos educativos, colgados en las diferentes plataformas digitales.\u00bbGracias a todas esas computadoras que se han entregado y a las laptops a nuestros maestros y maestras es que nuestros estudiantes han podido estar accesando de manera permanente a la p\u00e1gina que hemos puesto a su disposici\u00f3n, es decir, no se puede hablar de p\u00e9rdida del a\u00f1o escolar porque hemos avanzado en m\u00e1s del 70 por ciento en el contenido curricular\u00bb, afirmo Pe\u00f1a Mirabal.Gu\u00edas did\u00e1cticasEl ministro inform\u00f3 que para los estudiantes que no tienen acceso a Internet, el Viceministro T\u00e9cnico-Pedag\u00f3gico ha elaborado unas gu\u00edas did\u00e1cticas para que las familias puedan ayudar a sus hijos respecto a los contenidos impartidos y los que est\u00e1n en el curr\u00edculo.Asegur\u00f3 que se han distribuido m\u00e1s de tres millones de ejemplares de esas gu\u00edas did\u00e1cticas en todo el territorio nacional \u00abde tal manera que el que no pueda conectarse, pueda tener la orientaci\u00f3n de lugar\u00bb.Dijo que el Gobierno, a trav\u00e9s del MINERD ha entregado de manera gratuita m\u00e1s de 300 mil computadoras a estudiantes de Secundaria y que la meta para agosto de este a\u00f1o es llegar a las 650 mil.Pruebas NacionalesCon relaci\u00f3n a las Pruebas Nacionales, el ministro dijo que deben aplicarse de manera obligatoria, aunque no con la misma rigurosidad; sin embargo, precis\u00f3 que el curso de la pandemia dir\u00e1 si se imparten de manera presencial o virtual.<\/p>\n","protected":false},"author":9,"featured_media":78070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[459],"tags":[],"class_list":["post-78069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78069"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78069\/revisions"}],"predecessor-version":[{"id":78071,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78069\/revisions\/78071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78070"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}