{"id":78460,"date":"2020-05-21T08:12:17","date_gmt":"2020-05-21T12:12:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78460"},"modified":"2020-05-21T08:12:20","modified_gmt":"2020-05-21T12:12:20","slug":"ee-uu-se-plantea-restringir-los-viajes-desde-varios-paises-de-suramerica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ee-uu-se-plantea-restringir-los-viajes-desde-varios-paises-de-suramerica\/","title":{"rendered":"EE.UU. se plantea restringir los viajes desde varios pa\u00edses de Suram\u00e9rica"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"195\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/05\/202005201941591.jpeg\" alt=\"\" class=\"wp-image-78461\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos no solo se plantea restringir los viajes desde Brasil, sino tambi\u00e9n desde otros pa\u00edses de Suram\u00e9rica, con el objetivo de contener la expansi\u00f3n del COVID-19, dijo este mi\u00e9rcoles en Orlando (Florida), el vicepresidente estadounidense, Mike Pence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstamos observando con mucho cuidado lo que est\u00e1 ocurriendo en Suram\u00e9rica, incluyendo a Brasil. En los \u00faltimos d\u00edas hemos visto un aumento significativo de los casos\u00bb, dijo Pence en declaraciones a la prensa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pence agreg\u00f3 que el presidente de EE.UU., Donald Trump, ha considerado estas \u00abrestricciones de viajes adicionales\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump dijo este martes que se plantea vetar la entrada a su pa\u00eds de los extranjeros procedentes de Brasil, el tercer pa\u00eds del mundo con m\u00e1s contagios de COVID-19 despu\u00e9s de EE.UU. y Rusia, y que le gustar\u00eda eliminar la prohibici\u00f3n a los viajes desde Europa \u00ablo m\u00e1s pronto posible\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompa\u00f1ado del gobernador de Florida, Ron DeSantis, Pence llev\u00f3 este mi\u00e9rcoles m\u00e1scaras al hogar de la tercera edad Westminster Baldwin Park, en Orlando, en el centro de Florida, y tiene previsto reuniones con el empresarios hoteleros y tur\u00edsticos para hablar de la reactivaci\u00f3n de este sector, uno de los m\u00e1s afectados en el llamado \u00abestado del sol\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando a\u00fan permanecen cerrados los parques tem\u00e1ticos de Disney y Universal, como tambi\u00e9n las playas del condados como Broward y Miami-Dade, motores importantes de la industria tur\u00edstica de Florida, Pence elogi\u00f3 el plan de reapertura econ\u00f3mica de DeSantis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYo realmente creo que Florida ha marcado el ritmo\u00bb, manifest\u00f3 Pence.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido DeSantis, dijo que Florida no solo hab\u00eda bajado la tasa de muertes, sino que ten\u00eda \u00abmucho menos muertes en general\u00bb, al reiterar que hab\u00edan pasado \u00abocho semanas\u00bb desde que los periodistas dijeron que el estado iba a ser el pr\u00f3ximo Nueva York o Italia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abFlorida tiene la tasa de mortalidad m\u00e1s baja y el estado fue el centro de llegada de decenas de miles de gente provenientes de focos de contagio en el mundo\u00bb, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEntonces, hemos tenido \u00e9xito\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mayor\u00eda de los 67 condados de Florida, exceptuando Miami-Dade y Broward, est\u00e1n al \u00abpleno\u00bb de la implementaci\u00f3n de la primera fase de reactivaci\u00f3n, que incluye la apertura de restaurantes, tiendas, gimnasios, museos y peluquer\u00edas, todos a la mitad de su capacidad, como tambi\u00e9n ciertas cirug\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Miami-Dade y Broward, los m\u00e1s afectados por la pandemia con 22.441 casos confirmados de los 47.741 del estado, est\u00e1n en la misma fase, pero a un ritmo m\u00e1s lento de apertura de negocios y a un cuarto de su capacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La visita de Pence coincide con la apertura parcial del centro comercial de Disney Springs, que este mi\u00e9rcoles se uni\u00f3 a la de CitiWalk, el complejo de compras y restaurantes de Universal, que abri\u00f3 el jueves pasado tambi\u00e9n con una capacidad limitada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acompa\u00f1ado de DeSantis y Seema Verma, miembro del grupo de trabajo sobre coronavirus de la Casa Blanca, el vicepresidente estuvo de paso por el Westminster Baldwin Park, en el que dijo no se ha presentado ning\u00fan caso de COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pence llev\u00f3 m\u00e1scaras y guantes, entre otros equipos de protecci\u00f3n personal, para un periodo de dos semana, como parte de una iniciativa que dotar\u00e1 con estos materiales a 15.000 de estos hogares de la tercera edad en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAhora que Florida comienza a abrir vamos a seguir colaborando con usted para proteger a sus m\u00e1s vulnerables\u00bb, le dijo Pence a DeSantis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto los hogares geri\u00e1tricos como los parques tem\u00e1ticos aun no hacen parte de la reactivaci\u00f3n econ\u00f3mica del estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos deber\u00e1n enviar al gobernador DeSantis sus planes de apertura para volver a recibir las visitas de familiares, en el caso de los geri\u00e1tricos, y turistas, en el de los parque tem\u00e1ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta vez el vicepresidente Pence, cuya jefe de prensa Katie Miller contrajo recientemente el nuevo coronavirus, s\u00ed us\u00f3 m\u00e1scara despu\u00e9s de las cr\u00edticas que ha recibido por no hacerlo durante una visita en abril pasado a la Cl\u00ednica Mayo en Rochester (Minesota).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, en el Aeropuerto Internacional de Orlando estuvieron conversando sin m\u00e1scara Pence, DeSantis, Verma y el secretario de Trabajo, Eugene Scalia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos no solo se plantea restringir los viajes desde Brasil, sino tambi\u00e9n desde otros pa\u00edses de Suram\u00e9rica, con el objetivo de contener la expansi\u00f3n del COVID-19, dijo este mi\u00e9rcoles en Orlando (Florida), el vicepresidente estadounidense, Mike Pence. \u00abEstamos observando con mucho cuidado lo que est\u00e1 ocurriendo en Suram\u00e9rica, incluyendo a Brasil. En los \u00faltimos d\u00edas hemos visto un aumento significativo de los casos\u00bb, dijo Pence en declaraciones a la prensa. Pence agreg\u00f3 que el presidente de EE.UU., Donald Trump, ha considerado estas \u00abrestricciones de viajes adicionales\u00bb. Trump dijo este martes que se plantea vetar la entrada a su pa\u00eds de los extranjeros procedentes de Brasil, el tercer pa\u00eds del mundo con m\u00e1s contagios de COVID-19 despu\u00e9s de EE.UU. y Rusia, y que le gustar\u00eda eliminar la prohibici\u00f3n a los viajes desde Europa \u00ablo m\u00e1s pronto posible\u00bb. Acompa\u00f1ado del gobernador de Florida, Ron DeSantis, Pence llev\u00f3 este mi\u00e9rcoles m\u00e1scaras al hogar de la tercera edad Westminster Baldwin Park, en Orlando, en el centro de Florida, y tiene previsto reuniones con el empresarios hoteleros y tur\u00edsticos para hablar de la reactivaci\u00f3n de este sector, uno de los m\u00e1s afectados en el llamado \u00abestado del sol\u00bb. Cuando a\u00fan permanecen cerrados los parques tem\u00e1ticos de Disney y Universal, como tambi\u00e9n las playas del condados como Broward y Miami-Dade, motores importantes de la industria tur\u00edstica de Florida, Pence elogi\u00f3 el plan de reapertura econ\u00f3mica de DeSantis. \u00abYo realmente creo que Florida ha marcado el ritmo\u00bb, manifest\u00f3 Pence. En ese sentido DeSantis, dijo que Florida no solo hab\u00eda bajado la tasa de muertes, sino que ten\u00eda \u00abmucho menos muertes en general\u00bb, al reiterar que hab\u00edan pasado \u00abocho semanas\u00bb desde que los periodistas dijeron que el estado iba a ser el pr\u00f3ximo Nueva York o Italia. \u00abFlorida tiene la tasa de mortalidad m\u00e1s baja y el estado fue el centro de llegada de decenas de miles de gente provenientes de focos de contagio en el mundo\u00bb, subray\u00f3. \u00abEntonces, hemos tenido \u00e9xito\u00bb, agreg\u00f3. La mayor\u00eda de los 67 condados de Florida, exceptuando Miami-Dade y Broward, est\u00e1n al \u00abpleno\u00bb de la implementaci\u00f3n de la primera fase de reactivaci\u00f3n, que incluye la apertura de restaurantes, tiendas, gimnasios, museos y peluquer\u00edas, todos a la mitad de su capacidad, como tambi\u00e9n ciertas cirug\u00edas. Miami-Dade y Broward, los m\u00e1s afectados por la pandemia con 22.441 casos confirmados de los 47.741 del estado, est\u00e1n en la misma fase, pero a un ritmo m\u00e1s lento de apertura de negocios y a un cuarto de su capacidad. La visita de Pence coincide con la apertura parcial del centro comercial de Disney Springs, que este mi\u00e9rcoles se uni\u00f3 a la de CitiWalk, el complejo de compras y restaurantes de Universal, que abri\u00f3 el jueves pasado tambi\u00e9n con una capacidad limitada. Acompa\u00f1ado de DeSantis y Seema Verma, miembro del grupo de trabajo sobre coronavirus de la Casa Blanca, el vicepresidente estuvo de paso por el Westminster Baldwin Park, en el que dijo no se ha presentado ning\u00fan caso de COVID-19. Pence llev\u00f3 m\u00e1scaras y guantes, entre otros equipos de protecci\u00f3n personal, para un periodo de dos semana, como parte de una iniciativa que dotar\u00e1 con estos materiales a 15.000 de estos hogares de la tercera edad en todo el pa\u00eds. \u00abAhora que Florida comienza a abrir vamos a seguir colaborando con usted para proteger a sus m\u00e1s vulnerables\u00bb, le dijo Pence a DeSantis. Tanto los hogares geri\u00e1tricos como los parques tem\u00e1ticos aun no hacen parte de la reactivaci\u00f3n econ\u00f3mica del estado. Ambos deber\u00e1n enviar al gobernador DeSantis sus planes de apertura para volver a recibir las visitas de familiares, en el caso de los geri\u00e1tricos, y turistas, en el de los parque tem\u00e1ticos. Esta vez el vicepresidente Pence, cuya jefe de prensa Katie Miller contrajo recientemente el nuevo coronavirus, s\u00ed us\u00f3 m\u00e1scara despu\u00e9s de las cr\u00edticas que ha recibido por no hacerlo durante una visita en abril pasado a la Cl\u00ednica Mayo en Rochester (Minesota). Sin embargo, en el Aeropuerto Internacional de Orlando estuvieron conversando sin m\u00e1scara Pence, DeSantis, Verma y el secretario de Trabajo, Eugene Scalia.<\/p>\n","protected":false},"author":9,"featured_media":78461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[460],"tags":[],"class_list":["post-78460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78460"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78460\/revisions"}],"predecessor-version":[{"id":78462,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78460\/revisions\/78462"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78461"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}