{"id":78463,"date":"2020-05-21T08:16:38","date_gmt":"2020-05-21T12:16:38","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78463"},"modified":"2020-05-21T08:16:41","modified_gmt":"2020-05-21T12:16:41","slug":"una-pelicula-dominicana-gana-premio-del-panama-international-film-festival","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/una-pelicula-dominicana-gana-premio-del-panama-international-film-festival\/","title":{"rendered":"Una pel\u00edcula dominicana gana premio del Panam\u00e1 International Film Festival"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/05\/escena-de-rafaela-20052020-facebook-rafaela-pelicula-300x158-1.jpg\" alt=\"\" class=\"wp-image-78464\" width=\"528\" height=\"278\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- El largometraje dominicano \u201cRafaela\u201d recibi\u00f3 el primer lugar de \u201cPrimera Miranda\u201d que desde 2915 otorga el Panam\u00e1 International Film Festival (IFF Panam\u00e1), como apoyo a la cinematograf\u00eda de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cinta, que cuenta una historia de venganza, es dirigido por el dominicano Tito Rodr\u00edguez y protagonizado por su compatriota Judith Rodr\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a un documento enviado por los productores del filme, \u201cRafaela\u201d recibir\u00e1 10.000 d\u00f3lares como premio, mientras que el segundo lugar fue otorgado al documental cubano \u201cLa selva\u201d, que recibir\u00e1 5.000 d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn medio de toda esta crisis mundial, recibir esta noticia es un signo de esperanza y aliento para no desfallecer. \u2018Rafaela\u2019 es un proyecto anhelado y amado por todos nosotros, duramos 8 a\u00f1os para poder realizarla, pero el tiempo y el esfuerzo van dando sus frutos\u201d, dijo Rodr\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El IFF Panam\u00e1 estaba programado para celebrarse del 26 de marzo al 1 de abril, pero fue pospuesto debido a la crisis del COVID-19. El festival ha utilizado herramientas en l\u00ednea para mantener su \u201cpapel crucial\u201d en el apoyo a estos \u201cimportantes\u201d proyectos de la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIFF Panam\u00e1 es uno de los festivales que m\u00e1s amo, y es un honor haber sido seleccionados para \u2018Primera Mirada\u2019, ganar es un lujo, y lo agradecemos enormemente. Seguimos trabajando duro para terminar nuestra pel\u00edcula y estrenarla con todas las de la ley; agradecida es poco\u201d, agreg\u00f3 Rodr\u00edguez, quien tambi\u00e9n es co-productora de la pel\u00edcula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La informaci\u00f3n destac\u00f3 que \u201cPrimera Miranda\u201d ha servido como un trampol\u00edn importante para proyectos de la regi\u00f3n, proporcionando \u201cfondos vitales\u201d de pos producci\u00f3n a los mismos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- El largometraje dominicano \u201cRafaela\u201d recibi\u00f3 el primer lugar de \u201cPrimera Miranda\u201d que desde 2915 otorga el Panam\u00e1 International Film Festival (IFF Panam\u00e1), como apoyo a la cinematograf\u00eda de la regi\u00f3n. La cinta, que cuenta una historia de venganza, es dirigido por el dominicano Tito Rodr\u00edguez y protagonizado por su compatriota Judith Rodr\u00edguez. De acuerdo a un documento enviado por los productores del filme, \u201cRafaela\u201d recibir\u00e1 10.000 d\u00f3lares como premio, mientras que el segundo lugar fue otorgado al documental cubano \u201cLa selva\u201d, que recibir\u00e1 5.000 d\u00f3lares. \u201cEn medio de toda esta crisis mundial, recibir esta noticia es un signo de esperanza y aliento para no desfallecer. \u2018Rafaela\u2019 es un proyecto anhelado y amado por todos nosotros, duramos 8 a\u00f1os para poder realizarla, pero el tiempo y el esfuerzo van dando sus frutos\u201d, dijo Rodr\u00edguez. El IFF Panam\u00e1 estaba programado para celebrarse del 26 de marzo al 1 de abril, pero fue pospuesto debido a la crisis del COVID-19. El festival ha utilizado herramientas en l\u00ednea para mantener su \u201cpapel crucial\u201d en el apoyo a estos \u201cimportantes\u201d proyectos de la regi\u00f3n. \u201cIFF Panam\u00e1 es uno de los festivales que m\u00e1s amo, y es un honor haber sido seleccionados para \u2018Primera Mirada\u2019, ganar es un lujo, y lo agradecemos enormemente. Seguimos trabajando duro para terminar nuestra pel\u00edcula y estrenarla con todas las de la ley; agradecida es poco\u201d, agreg\u00f3 Rodr\u00edguez, quien tambi\u00e9n es co-productora de la pel\u00edcula. La informaci\u00f3n destac\u00f3 que \u201cPrimera Miranda\u201d ha servido como un trampol\u00edn importante para proyectos de la regi\u00f3n, proporcionando \u201cfondos vitales\u201d de pos producci\u00f3n a los mismos.<\/p>\n","protected":false},"author":9,"featured_media":78464,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[387],"tags":[],"class_list":["post-78463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78463"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78463\/revisions"}],"predecessor-version":[{"id":78465,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78463\/revisions\/78465"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78464"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}