{"id":7855,"date":"2014-08-31T19:00:40","date_gmt":"2014-08-31T23:00:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=7855"},"modified":"2014-08-30T21:58:33","modified_gmt":"2014-08-31T01:58:33","slug":"un-matrimonio-heterosexual-con-dos-novias","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-matrimonio-heterosexual-con-dos-novias\/","title":{"rendered":"Un matrimonio heterosexual con \u00bfdos novias?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/596x372_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7856 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/596x372_2-300x200.jpg\" alt=\"596x372_2\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/596x372_2-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/08\/596x372_2.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Una pareja \u201cheterosexual\u201d rusa, Dmitry Kozhukhov, tambi\u00e9n conocido como Alina Davis, y su\u00a0<label style=\"color: #0000ff;\">esposa<\/label>\u00a0Alison Brooks confundieron una oficina de\u00a0<label style=\"color: #0000ff;\">registro<\/label>\u00a0de bodas de Mosc\u00fa porque Davis es un andr\u00f3gino<!--more--><\/p>\n<p>El matrimonio del mismo sexo es totalmente rechazado en Rusia por lo que se pueden imaginar la mirada en los rostros de los trabajadores de la oficina del registro cuando los contrayentes se presentaron en\u00a0<label style=\"color: #0000ff;\">vestidos<\/label>\u00a0de\u00a0<label style=\"color: #0000ff;\">novia<\/label>.<\/p>\n<p>Davis se siente m\u00e1s c\u00f3modo como\u00a0<label style=\"color: #0000ff;\">mujer<\/label>, no tiene operaciones y se siente atra\u00eddo por las mujeres. Su matrimonio establece un precedente importante en Rusia, donde las parejas no convencionales a menudo se enfrentan a la hostilidad.<\/p>\n<p>El jefe del registro de boda discuti\u00f3 con la pareja porque en Rusia es ilegal el matrimonio entre personas del mismo sexo, pero la pareja insisti\u00f3 en que eran, de hecho, hombre y mujer hasta que el registro finalmente admiti\u00f3. Sin embargo dijo a la pareja que avergonzaban el concepto de \u201cfamilia\u201d.<\/p>\n<p>Fuente:\u00a0<a style=\"color: #006e94;\" href=\"http:\/\/www.zocalo.com.mx\/seccion\/articulo\/fotos-androgino-se-casa-con-mujer-parecido-a-el-ambos-vestidos-de-novia-140\" target=\"_blank\">Zocalo<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una pareja \u201cheterosexual\u201d rusa, Dmitry Kozhukhov, tambi\u00e9n conocido como Alina Davis, y su\u00a0esposa\u00a0Alison Brooks confundieron una oficina de\u00a0registro\u00a0de bodas de Mosc\u00fa porque Davis es un andr\u00f3gino<\/p>\n","protected":false},"author":3,"featured_media":7856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-7855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=7855"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7855\/revisions"}],"predecessor-version":[{"id":7857,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7855\/revisions\/7857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/7856"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=7855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=7855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=7855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}