{"id":78785,"date":"2020-06-20T08:35:42","date_gmt":"2020-06-20T12:35:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78785"},"modified":"2020-06-20T08:35:44","modified_gmt":"2020-06-20T12:35:44","slug":"cantante-sange-promociona-su-reciente-sencillo-locura","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cantante-sange-promociona-su-reciente-sencillo-locura\/","title":{"rendered":"Cantante Sange promociona su reciente sencillo \u201cLocura\u201d"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/06\/Sange-1-300x169-1.jpeg\" alt=\"\" class=\"wp-image-78786\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.-&nbsp; Con una propuesta musical diferente y jovial, el cantante Sange busca reafirmar sus pasos en la industria musical nacional con su tercer sencillo titulado \u201cLocura\u201d, junto a Emmcode, Carlos Uzi y Mc Gero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Producido por Fat Daddy, el tema trata de \u201cesa persona que te gusta, que no puedes sacar de tu cabeza y quieres que est\u00e9 contigo; algo que le pasa muy a menudo a muchas personas cuando nos enamoramos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mismo cuenta con un material audiovisual dirigido por Joseph Castro, disponible en Youtube.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sange destaca que con apenas pocas semanas de haber salido al ruedo musical, \u201cLocura\u201d cuenta con m\u00e1s de 400 mil visualizaciones en Youtube, lo que considera \u201ces una gran cifra para un artista independiente\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que dio sus primeros pininos en la m\u00fasica, en el 2015, Sange se ha caracterizado por el Latin Urban, pero no descarta, en un futuro, entregar a su p\u00fablico algunos temas en g\u00e9neros como la bachata y el merengue, lo cual asegura \u201char\u00eda con mucho amor y a mi manera, porque aqu\u00ed quien manda es el p\u00fablico\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luis \u00c1ngel Ruiz, nombre de pila del cantante, considera que \u201cla m\u00fasica anda tan r\u00e1pido, que el que se duerme se lo lleva la corriente\u201d, por eso ya tiene preparado su pr\u00f3ximo sencillo, \u201cTu actitud\u201d, el cual saldr\u00e1 al mercado en la primera semana de julio; mientras contin\u00faa desarrollando mucha m\u00fasica para los meses siguientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-&nbsp; Con una propuesta musical diferente y jovial, el cantante Sange busca reafirmar sus pasos en la industria musical nacional con su tercer sencillo titulado \u201cLocura\u201d, junto a Emmcode, Carlos Uzi y Mc Gero. Producido por Fat Daddy, el tema trata de \u201cesa persona que te gusta, que no puedes sacar de tu cabeza y quieres que est\u00e9 contigo; algo que le pasa muy a menudo a muchas personas cuando nos enamoramos\u201d. El mismo cuenta con un material audiovisual dirigido por Joseph Castro, disponible en Youtube. Sange destaca que con apenas pocas semanas de haber salido al ruedo musical, \u201cLocura\u201d cuenta con m\u00e1s de 400 mil visualizaciones en Youtube, lo que considera \u201ces una gran cifra para un artista independiente\u201d. Desde que dio sus primeros pininos en la m\u00fasica, en el 2015, Sange se ha caracterizado por el Latin Urban, pero no descarta, en un futuro, entregar a su p\u00fablico algunos temas en g\u00e9neros como la bachata y el merengue, lo cual asegura \u201char\u00eda con mucho amor y a mi manera, porque aqu\u00ed quien manda es el p\u00fablico\u201d, dijo. Luis \u00c1ngel Ruiz, nombre de pila del cantante, considera que \u201cla m\u00fasica anda tan r\u00e1pido, que el que se duerme se lo lleva la corriente\u201d, por eso ya tiene preparado su pr\u00f3ximo sencillo, \u201cTu actitud\u201d, el cual saldr\u00e1 al mercado en la primera semana de julio; mientras contin\u00faa desarrollando mucha m\u00fasica para los meses siguientes.<\/p>\n","protected":false},"author":9,"featured_media":78786,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-78785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78785"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78785\/revisions"}],"predecessor-version":[{"id":78787,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78785\/revisions\/78787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78786"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}