{"id":78819,"date":"2020-06-22T09:22:01","date_gmt":"2020-06-22T13:22:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78819"},"modified":"2020-06-22T09:22:05","modified_gmt":"2020-06-22T13:22:05","slug":"un-helicoptero-antiincendios-con-cocaina-en-republica-dominicana-llevo-a-la-incautacion-de-3-800-kilos-en-espana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-helicoptero-antiincendios-con-cocaina-en-republica-dominicana-llevo-a-la-incautacion-de-3-800-kilos-en-espana\/","title":{"rendered":"Un helic\u00f3ptero antiincendios con coca\u00edna en Rep\u00fablica Dominicana llev\u00f3 a la incautaci\u00f3n de 3.800 kilos en Espa\u00f1a"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/06\/un-helicoptero-antiincendios-con-cocaina-en-republica-dominicana-llevo-a-la-incautacion-de-3-800-kilos-en-espana.jpeg\" alt=\"\" class=\"wp-image-78820\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/06\/un-helicoptero-antiincendios-con-cocaina-en-republica-dominicana-llevo-a-la-incautacion-de-3-800-kilos-en-espana.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/06\/un-helicoptero-antiincendios-con-cocaina-en-republica-dominicana-llevo-a-la-incautacion-de-3-800-kilos-en-espana-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El uso como &#8216;gancho ciego&#8217; de un helic\u00f3ptero antiincendios con 200 kilos de coca\u00edna escondida en su armaz\u00f3n llev\u00f3 a los agentes especializados en la lucha contra el tr\u00e1fico de drogas a extremar la vigilancia en el Puerto de Valencia, donde este primer hallazgo en un contenedor permiti\u00f3 la incautaci\u00f3n de un total de 3.800 kilos de coca\u00edna en una operaci\u00f3n con once detenidos desarrollada en un mes y en plena emergencia sanitaria por el COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De la operaci\u00f3n explotada en Espa\u00f1a informaron este viernes de forma conjunta los especialistas de la UCO de la Guardia Civil y UDYCO de Polic\u00eda Nacional, pero hay dos vertientes de la investigaci\u00f3n que contin\u00faan abiertas: una es la posible ayuda de trabajadores del Puerto de Valencia para introducir la sustancia estupefaciente y otra la estructura que desde Sudam\u00e9rica realizaba el env\u00edo a Espa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La operaci\u00f3n &#8216;Crankbrook Marchica&#8217; se ha saldado con once detenidos por pertenecer a una organizaci\u00f3n transnacional con todos sus integrantes espa\u00f1oles, excepto dos holandeses y un s\u00fabdito de Costa de Marfil. En un mes se han intervenido seis contenedores en los que se escond\u00eda la sustancia estupefaciente mediante distintos m\u00e9todos de ocultaci\u00f3n como paquetes de folios, sacos de az\u00facar, pulpa de pi\u00f1a e incluso entre el armaz\u00f3n de un autogiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el primero contenedor fue en el que se descubri\u00f3 el &#8216;gancho ciego&#8217;. Rep\u00fablica Dominicana mantiene abierta una investigaci\u00f3n en paralelo porque fue en este pa\u00eds donde se detect\u00f3 en origen que desconocidos hab\u00edan violentado los precintos de seguridad para introducir en Chile 200 kilos de coca\u00edna en un helic\u00f3ptero que regresaba a Espa\u00f1a tras ser cedido para la campa\u00f1a contra incendios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los narcos, seg\u00fan detallan fuentes de la investigaci\u00f3n, aprovecharon el tr\u00e1nsito en Rep\u00fablica Dominicana del contenedor procedente de Chile para forzar los precintos y colocar junto al fuselaje la coca\u00edna introducida en mochilas en el sistema conocido como &#8216;gancho ciego&#8217;: el propietario del autogiro desconoc\u00eda que estaba transportando la sustancia il\u00edcita para que fuera recogida en Espa\u00f1a por la organizaci\u00f3n desarticulada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>COLABORACI\u00d3N CON OTROS PA\u00cdSES<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La incautaci\u00f3n de la coca\u00edna introducida en el helic\u00f3ptero ha llevado a la Direcci\u00f3n Nacional de Control de Drogas (DNCD) de Rep\u00fablica Dominicana a abrir una investigaci\u00f3n centrada en el puerto de Caucedo. El exponencial aumento del tr\u00e1fico mar\u00edtimo de contenedores y la situaci\u00f3n extraordinaria del Covid-19 ha intensificado la colaboraci\u00f3n con pa\u00edses de Sudam\u00e9rica. Tambi\u00e9n se ha reforzado el control ante posibles colaboradores entre los trabajadores de los puerto de origen y destino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la rueda de prensa en Valencia con la presencia del comisario principal jefe de la UDYCO Central de Polic\u00eda Nacional, Santos Bernal, y del responsable antidrogas en la UCO de la Guardia Civil, Jes\u00fas Garc\u00eda, se puso en relieve la importancia de la colaboraci\u00f3n con otros pa\u00edses y con las agencias DEA y HSI de Estados Unidos, as\u00ed como el fiscal delegado especial antidroga de Valencia y la Agencia Tributaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mando de la UCO homenaje\u00f3 a dos v\u00edctimas del coronavirus, la fiscal antidroga Cristina Toro y Jes\u00fas Gayoso, jefe del GAR, unidad que no colabor\u00f3 en esta \u00faltima operaci\u00f3n en el Puerto de Valencia pero que fue citada en homenaje al teniente coronel y por sus servicios en innumerables intervenciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Polic\u00eda Nacional y la Guardia Civil han alertado de que varias organizaciones criminales internacionales han aprovechado la situaci\u00f3n en Espa\u00f1a derivada del estado de alerta por el COVID-19 que ha concluido este 21 de junio para intentar introducir importantes partidas de coca\u00edna procedente de Sudam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo, dicen, es su almacenamiento y posterior distribuci\u00f3n por toda Europa, todo ello ante la suposici\u00f3n de las organizaciones delictivas de que los controles y actividad de investigaci\u00f3n ser\u00eda menor por parte de las autoridades espa\u00f1olas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El uso como &#8216;gancho ciego&#8217; de un helic\u00f3ptero antiincendios con 200 kilos de coca\u00edna escondida en su armaz\u00f3n llev\u00f3 a los agentes especializados en la lucha contra el tr\u00e1fico de drogas a extremar la vigilancia en el Puerto de Valencia, donde este primer hallazgo en un contenedor permiti\u00f3 la incautaci\u00f3n de un total de 3.800 kilos de coca\u00edna en una operaci\u00f3n con once detenidos desarrollada en un mes y en plena emergencia sanitaria por el COVID-19. De la operaci\u00f3n explotada en Espa\u00f1a informaron este viernes de forma conjunta los especialistas de la UCO de la Guardia Civil y UDYCO de Polic\u00eda Nacional, pero hay dos vertientes de la investigaci\u00f3n que contin\u00faan abiertas: una es la posible ayuda de trabajadores del Puerto de Valencia para introducir la sustancia estupefaciente y otra la estructura que desde Sudam\u00e9rica realizaba el env\u00edo a Espa\u00f1a. La operaci\u00f3n &#8216;Crankbrook Marchica&#8217; se ha saldado con once detenidos por pertenecer a una organizaci\u00f3n transnacional con todos sus integrantes espa\u00f1oles, excepto dos holandeses y un s\u00fabdito de Costa de Marfil. En un mes se han intervenido seis contenedores en los que se escond\u00eda la sustancia estupefaciente mediante distintos m\u00e9todos de ocultaci\u00f3n como paquetes de folios, sacos de az\u00facar, pulpa de pi\u00f1a e incluso entre el armaz\u00f3n de un autogiro. En el primero contenedor fue en el que se descubri\u00f3 el &#8216;gancho ciego&#8217;. Rep\u00fablica Dominicana mantiene abierta una investigaci\u00f3n en paralelo porque fue en este pa\u00eds donde se detect\u00f3 en origen que desconocidos hab\u00edan violentado los precintos de seguridad para introducir en Chile 200 kilos de coca\u00edna en un helic\u00f3ptero que regresaba a Espa\u00f1a tras ser cedido para la campa\u00f1a contra incendios. Los narcos, seg\u00fan detallan fuentes de la investigaci\u00f3n, aprovecharon el tr\u00e1nsito en Rep\u00fablica Dominicana del contenedor procedente de Chile para forzar los precintos y colocar junto al fuselaje la coca\u00edna introducida en mochilas en el sistema conocido como &#8216;gancho ciego&#8217;: el propietario del autogiro desconoc\u00eda que estaba transportando la sustancia il\u00edcita para que fuera recogida en Espa\u00f1a por la organizaci\u00f3n desarticulada. COLABORACI\u00d3N CON OTROS PA\u00cdSES La incautaci\u00f3n de la coca\u00edna introducida en el helic\u00f3ptero ha llevado a la Direcci\u00f3n Nacional de Control de Drogas (DNCD) de Rep\u00fablica Dominicana a abrir una investigaci\u00f3n centrada en el puerto de Caucedo. El exponencial aumento del tr\u00e1fico mar\u00edtimo de contenedores y la situaci\u00f3n extraordinaria del Covid-19 ha intensificado la colaboraci\u00f3n con pa\u00edses de Sudam\u00e9rica. Tambi\u00e9n se ha reforzado el control ante posibles colaboradores entre los trabajadores de los puerto de origen y destino. En la rueda de prensa en Valencia con la presencia del comisario principal jefe de la UDYCO Central de Polic\u00eda Nacional, Santos Bernal, y del responsable antidrogas en la UCO de la Guardia Civil, Jes\u00fas Garc\u00eda, se puso en relieve la importancia de la colaboraci\u00f3n con otros pa\u00edses y con las agencias DEA y HSI de Estados Unidos, as\u00ed como el fiscal delegado especial antidroga de Valencia y la Agencia Tributaria. El mando de la UCO homenaje\u00f3 a dos v\u00edctimas del coronavirus, la fiscal antidroga Cristina Toro y Jes\u00fas Gayoso, jefe del GAR, unidad que no colabor\u00f3 en esta \u00faltima operaci\u00f3n en el Puerto de Valencia pero que fue citada en homenaje al teniente coronel y por sus servicios en innumerables intervenciones. La Polic\u00eda Nacional y la Guardia Civil han alertado de que varias organizaciones criminales internacionales han aprovechado la situaci\u00f3n en Espa\u00f1a derivada del estado de alerta por el COVID-19 que ha concluido este 21 de junio para intentar introducir importantes partidas de coca\u00edna procedente de Sudam\u00e9rica. El objetivo, dicen, es su almacenamiento y posterior distribuci\u00f3n por toda Europa, todo ello ante la suposici\u00f3n de las organizaciones delictivas de que los controles y actividad de investigaci\u00f3n ser\u00eda menor por parte de las autoridades espa\u00f1olas.<\/p>\n","protected":false},"author":9,"featured_media":78820,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-78819","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78819"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78819\/revisions"}],"predecessor-version":[{"id":78821,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78819\/revisions\/78821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78820"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}