{"id":78831,"date":"2020-06-24T07:45:03","date_gmt":"2020-06-24T11:45:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78831"},"modified":"2020-06-24T07:45:06","modified_gmt":"2020-06-24T11:45:06","slug":"hija-de-gata-anota-el-balon-julady-zapata-quiere-emular-a-su-progenitora","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hija-de-gata-anota-el-balon-julady-zapata-quiere-emular-a-su-progenitora\/","title":{"rendered":"Hija de gata, anota el bal\u00f3n: Julady Zapata quiere emular a su progenitora"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"195\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/06\/hija-de-gata-anota-el-balon-julady-zapata-quiere-emular-a-su-progenitora.jpeg\" alt=\"\" class=\"wp-image-78832\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Al m\u00e1ximo galard\u00f3n que puede aspirar un depor\u00adtista es a ser ingresado al Pabell\u00f3n de la Fama. Y que la hija de alguien con esa estampa se intere\u00adse por seguir los pasos de su madre puede suponer una carga bien pesada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero en el caso de Julady Zapata m\u00e1s que de obs\u00adt\u00e1culo le ha servido de inspiraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs como un est\u00edmulo, me ayuda a querer lle\u00adgar a ser igual que ella\u201d, declara con relaci\u00f3n a Altagracia Zapata, re\u00adconocida como una de las mejores tiradoras en la historia, un t\u00edtulo que ahora tiene su hija.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En selecci\u00f3n nacional<\/strong><br \/>Julady ha representado al pa\u00eds en m\u00e1s de una do\u00adcena de ocasiones, inclu\u00adyendo las categor\u00edas me\u00adnores de Sub 15 y Sub 16.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es considerada como una de las mejores tira\u00addoras con las que cuenta el equipo criollo.\u201cMi madre siempre estaba encima de m\u00ed cuando ten\u00eda que ir a las pr\u00e1cticas para que no me quedara en casa. Al prin\u00adcipio me molestaba, pero ahora puedo ver los frutos del sacrificio\u201d, agrega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jugadora de 5-9 de esta\u00adtura y 27 a\u00f1os es la figu\u00adra prin\u00adcipal de las Indias del Sur en la Li\u00adga Nacio\u00adnal de Ba\u00adloncesto, jug\u00f3 en el torneo distrital con Los Mina, as\u00ed como en las justas universitarias y las organizadas por la Fede\u00adraci\u00f3n Dominicana de Clu\u00adbes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agradece a su madre, Te\u00adresa Dur\u00e1n, Juan Francisco Zapata (su t\u00edo) entre otras personas que la han ayuda\u00addo. Cree que naci\u00f3 con un don, pero que sin la pr\u00e1cti\u00adca no le servir\u00eda de nada. A pesar de su calidad de selec\u00adci\u00f3n nacional ahora mismo no se encuentra protegida por el Programa de Atletas de Alto Rendimiento, Nue\u00advos Valores e Inmortales (Parni).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su m\u00e1s reciente actua\u00adci\u00f3n en la selecci\u00f3n nacio\u00adnal, en la AmeriCup del a\u00f1o pasado fue la tercera mejor ano\u00adtadora con prome\u00addio de 9.4 puntos por par\u00adtido, ade\u00adm\u00e1s de en\u00adcestar el 43,8 por ciento de sus lances de tres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue la segunda mejor en asistencias (2.8) y la cuarta en rebotes (4.8).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un privilegio para m\u00ed que me haya seguido los pa\u00adsos. Una gran satisfacci\u00f3n ya que desde los 5 a\u00f1os co\u00admenz\u00f3 a picar una pelo\u00adta. Asist\u00eda a cada recono\u00adcimiento que me hac\u00edan. Tenemos una bonita rela\u00adci\u00f3n. Es mi hija, mi amiga y mi compa\u00f1era\u201d, dice Al\u00adtagracia, inmortal del De\u00adporte Dominicano en softbol, pero quien tam\u00adbi\u00e9n fue selecci\u00f3n nacio\u00adnal en baloncesto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entiende que Julady pu\u00addo heredar algunas cosas o aprender otras, pero que Dios le ha dado el talento y que ha podido desarrollar\u00adlo a trav\u00e9s de los a\u00f1os gra\u00adcias a su empe\u00f1o y entrena\u00admientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Disciplina y entrega<\/strong><br \/>\u201cYo era m\u00e1s agresiva. Ella es muy inteligente, discipli\u00adnada y entregada. Si no de\u00adsarrollas tu talento no est\u00e1s en nada. No falta a ninguna pr\u00e1ctica y asume el entrena\u00admiento como indispensable para ella y para aportar al equipo\u201d, agrega la directo\u00adra provincial de deportes en Peravia y directora de una escuela de baloncesto feme\u00adnino en esa provincia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTiene una mec\u00e1nica de tiro impresionante. Es una juga\u00addora s\u00faper importante en el equipo nacional. Posee ju\u00adventud y disciplina, adem\u00e1s de ser una buena compa\u00f1e\u00adra\u201d, declara Yohanna Mor\u00adton, la armador titular del quinteto nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong>SEPA M\u00c1S<br \/>Otras parejas en la selecci\u00f3n<\/strong><br \/><strong>Padre e hijo.<\/strong><br \/>Tito y Al Horford no so\u00adlo estuvieron en el equi\u00adpo nacional si no que ambos han jugado en la NBA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Madre e hijo.<\/strong><br \/>Dania Santos estuvo con la selecci\u00f3n en cua\u00adtro oportunidades y es la madre de Ronald Ro\u00adberts Jr.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Madre e hijo II.<\/strong><br \/>Dagoberto Pe\u00f1a defien\u00adde los colores nacionales tal como en varios a\u00f1os lo hizo Cristina Montilla.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al m\u00e1ximo galard\u00f3n que puede aspirar un depor\u00adtista es a ser ingresado al Pabell\u00f3n de la Fama. Y que la hija de alguien con esa estampa se intere\u00adse por seguir los pasos de su madre puede suponer una carga bien pesada. Pero en el caso de Julady Zapata m\u00e1s que de obs\u00adt\u00e1culo le ha servido de inspiraci\u00f3n. \u201cEs como un est\u00edmulo, me ayuda a querer lle\u00adgar a ser igual que ella\u201d, declara con relaci\u00f3n a Altagracia Zapata, re\u00adconocida como una de las mejores tiradoras en la historia, un t\u00edtulo que ahora tiene su hija. En selecci\u00f3n nacionalJulady ha representado al pa\u00eds en m\u00e1s de una do\u00adcena de ocasiones, inclu\u00adyendo las categor\u00edas me\u00adnores de Sub 15 y Sub 16. Es considerada como una de las mejores tira\u00addoras con las que cuenta el equipo criollo.\u201cMi madre siempre estaba encima de m\u00ed cuando ten\u00eda que ir a las pr\u00e1cticas para que no me quedara en casa. Al prin\u00adcipio me molestaba, pero ahora puedo ver los frutos del sacrificio\u201d, agrega. La jugadora de 5-9 de esta\u00adtura y 27 a\u00f1os es la figu\u00adra prin\u00adcipal de las Indias del Sur en la Li\u00adga Nacio\u00adnal de Ba\u00adloncesto, jug\u00f3 en el torneo distrital con Los Mina, as\u00ed como en las justas universitarias y las organizadas por la Fede\u00adraci\u00f3n Dominicana de Clu\u00adbes. Agradece a su madre, Te\u00adresa Dur\u00e1n, Juan Francisco Zapata (su t\u00edo) entre otras personas que la han ayuda\u00addo. Cree que naci\u00f3 con un don, pero que sin la pr\u00e1cti\u00adca no le servir\u00eda de nada. A pesar de su calidad de selec\u00adci\u00f3n nacional ahora mismo no se encuentra protegida por el Programa de Atletas de Alto Rendimiento, Nue\u00advos Valores e Inmortales (Parni). En su m\u00e1s reciente actua\u00adci\u00f3n en la selecci\u00f3n nacio\u00adnal, en la AmeriCup del a\u00f1o pasado fue la tercera mejor ano\u00adtadora con prome\u00addio de 9.4 puntos por par\u00adtido, ade\u00adm\u00e1s de en\u00adcestar el 43,8 por ciento de sus lances de tres. Fue la segunda mejor en asistencias (2.8) y la cuarta en rebotes (4.8). \u201cEs un privilegio para m\u00ed que me haya seguido los pa\u00adsos. Una gran satisfacci\u00f3n ya que desde los 5 a\u00f1os co\u00admenz\u00f3 a picar una pelo\u00adta. Asist\u00eda a cada recono\u00adcimiento que me hac\u00edan. Tenemos una bonita rela\u00adci\u00f3n. Es mi hija, mi amiga y mi compa\u00f1era\u201d, dice Al\u00adtagracia, inmortal del De\u00adporte Dominicano en softbol, pero quien tam\u00adbi\u00e9n fue selecci\u00f3n nacio\u00adnal en baloncesto. Entiende que Julady pu\u00addo heredar algunas cosas o aprender otras, pero que Dios le ha dado el talento y que ha podido desarrollar\u00adlo a trav\u00e9s de los a\u00f1os gra\u00adcias a su empe\u00f1o y entrena\u00admientos. Disciplina y entrega\u201cYo era m\u00e1s agresiva. Ella es muy inteligente, discipli\u00adnada y entregada. Si no de\u00adsarrollas tu talento no est\u00e1s en nada. No falta a ninguna pr\u00e1ctica y asume el entrena\u00admiento como indispensable para ella y para aportar al equipo\u201d, agrega la directo\u00adra provincial de deportes en Peravia y directora de una escuela de baloncesto feme\u00adnino en esa provincia. \u201cTiene una mec\u00e1nica de tiro impresionante. Es una juga\u00addora s\u00faper importante en el equipo nacional. Posee ju\u00adventud y disciplina, adem\u00e1s de ser una buena compa\u00f1e\u00adra\u201d, declara Yohanna Mor\u00adton, la armador titular del quinteto nacional. &nbsp;SEPA M\u00c1SOtras parejas en la selecci\u00f3nPadre e hijo.Tito y Al Horford no so\u00adlo estuvieron en el equi\u00adpo nacional si no que ambos han jugado en la NBA. Madre e hijo.Dania Santos estuvo con la selecci\u00f3n en cua\u00adtro oportunidades y es la madre de Ronald Ro\u00adberts Jr. Madre e hijo II.Dagoberto Pe\u00f1a defien\u00adde los colores nacionales tal como en varios a\u00f1os lo hizo Cristina Montilla.<\/p>\n","protected":false},"author":9,"featured_media":78832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-78831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78831"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78831\/revisions"}],"predecessor-version":[{"id":78833,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78831\/revisions\/78833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78832"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}