{"id":78885,"date":"2020-06-28T08:34:11","date_gmt":"2020-06-28T12:34:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78885"},"modified":"2020-06-28T08:34:14","modified_gmt":"2020-06-28T12:34:14","slug":"permitiran-entrenamientos-de-atletas-nacionales-no-eventos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/permitiran-entrenamientos-de-atletas-nacionales-no-eventos\/","title":{"rendered":"Permitir\u00e1n entrenamientos de atletas nacionales, no eventos."},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/06\/permitiran-entrenamientos-de-atletas-nacionales-no-eventos-.jpeg\" alt=\"\" class=\"wp-image-78886\" width=\"229\" height=\"213\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministro de Salud P\u00fablica ha dado su consentimiento para la realizaci\u00f3n de actividades relacionadas con la preparaci\u00f3n f\u00edsica en aquellos deportes cuya reglas permiten distanciamiento f\u00edsico y que cumplen los protocolos establecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mediante la&nbsp;<strong>resoluci\u00f3n n\u00famero 000018 dada a conocer este s\u00e1bado&nbsp;<\/strong>y que busca \u201cseguir controlando y mitigando el COVID-19\u201d, tras finalizar el toque de queda y la finalizaci\u00f3n del Estado de Emergencia, el doctor Rafael S\u00e1nchez C\u00e1rdenas, dio a conocer un conjunto de medidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan S\u00e1nchez C\u00e1rdenas a\u00fan continuar\u00e1n suspendidos los eventos deportivos, aunque s\u00ed se permitir\u00e1 la preparaci\u00f3n f\u00edsica y pr\u00e1ctica de aquellas disciplinas cuyas reglas garanticen distanciamiento entre las personas y que cumplan con los protocolos establecidos por las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe permiten las actividades de entrenamientos, preparaci\u00f3n f\u00edsica de atletas y la pr\u00e1ctica de deportes cuyas reglas permiten el distanciamiento f\u00edsico con estricto cumplimiento de los protocolos establecidos\u201d, dice S\u00e1nchez C\u00e1rdenas en la resoluci\u00f3n evacuada luego que la noche de este viernes el Presidente Danilo Medina anticipara las medidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Deja al Ministerio de Deportes con la responsabilidad de implementar la disposici\u00f3n.<\/strong>&nbsp;Ese organismo, junto al Comit\u00e9 Ol\u00edmpico Dominicano tiene elaborado un protocolo para ser aplicado cuando se inicie la desescalada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta medida se aplica a deportes y otras actividades por considerarse actividades que pudieran convertirse en focos de contagio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estos momentos se busca permitir que el pa\u00eds pueda seguir con el proceso de apertura paulatina de las actividades, sin poner en riesgo la salud individual y colectiva de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Federados acogen medidas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luis Mej\u00eda, presidente del Comit\u00e9 Ol\u00edmpico Dominicano, dijo que las federaciones deportivas nacionales ejecutar\u00e1n las medidas como lo han establecido las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cVamos a ejecutar la reapertura conforme lo han dicho las autoridades\u201d, sostuvo el tambi\u00e9n miembro del Comit\u00e9 Ol\u00edmpico Internacional y presidente de la Organizaci\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deportiva Centroamericana y del Caribe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto que Persio Maldonado, quien preside la Federaci\u00f3n Dominicana de Tenis manifest\u00f3 que la resoluci\u00f3n es una buena noticia para que todo comience a normalizarse con las medidas anunciadas por las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maldonado dijo que \u201ccada disciplina debe asegurarse de tener el mejor control posible\u201d para evitar los contagios, precisando que el tenis siempre ha cre\u00eddo que tiene que estar sometido a las normas de las autoridades\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Expres\u00f3 que ha habido mucha impaciencia \u201cpero prefiero que sea as\u00ed y que no haya mucha gente contagiada\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carlos Elm\u00fadesi, presidente de la Federaci\u00f3n Dominicana de Golf dijo que lo de la apertura planteada en la resoluci\u00f3n \u201cno est\u00e1 clara\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Considera que \u201chay una serie de deportes que tienen que estar abiertos y tienen que estar en la desescalada que empieza el 1 julio\u201d, se\u00f1alando que con el protocolo que se ha establecido \u201cel golf garantiza no va a ver problema en ning\u00fan sitio\u201d, refiri\u00e9ndose a los campos de golf del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA nuestro pa\u00eds le conviene que el mundo sepa que aqu\u00ed se est\u00e1 jugando golf\u2026. tenemos enviar un mensaje al mundo y con esto ayudamos al turismo\u201d dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministro de Salud P\u00fablica ha dado su consentimiento para la realizaci\u00f3n de actividades relacionadas con la preparaci\u00f3n f\u00edsica en aquellos deportes cuya reglas permiten distanciamiento f\u00edsico y que cumplen los protocolos establecidos. Mediante la&nbsp;resoluci\u00f3n n\u00famero 000018 dada a conocer este s\u00e1bado&nbsp;y que busca \u201cseguir controlando y mitigando el COVID-19\u201d, tras finalizar el toque de queda y la finalizaci\u00f3n del Estado de Emergencia, el doctor Rafael S\u00e1nchez C\u00e1rdenas, dio a conocer un conjunto de medidas. Seg\u00fan S\u00e1nchez C\u00e1rdenas a\u00fan continuar\u00e1n suspendidos los eventos deportivos, aunque s\u00ed se permitir\u00e1 la preparaci\u00f3n f\u00edsica y pr\u00e1ctica de aquellas disciplinas cuyas reglas garanticen distanciamiento entre las personas y que cumplan con los protocolos establecidos por las autoridades. \u201cSe permiten las actividades de entrenamientos, preparaci\u00f3n f\u00edsica de atletas y la pr\u00e1ctica de deportes cuyas reglas permiten el distanciamiento f\u00edsico con estricto cumplimiento de los protocolos establecidos\u201d, dice S\u00e1nchez C\u00e1rdenas en la resoluci\u00f3n evacuada luego que la noche de este viernes el Presidente Danilo Medina anticipara las medidas. Deja al Ministerio de Deportes con la responsabilidad de implementar la disposici\u00f3n.&nbsp;Ese organismo, junto al Comit\u00e9 Ol\u00edmpico Dominicano tiene elaborado un protocolo para ser aplicado cuando se inicie la desescalada. Esta medida se aplica a deportes y otras actividades por considerarse actividades que pudieran convertirse en focos de contagio. En estos momentos se busca permitir que el pa\u00eds pueda seguir con el proceso de apertura paulatina de las actividades, sin poner en riesgo la salud individual y colectiva de la ciudadan\u00eda. Federados acogen medidas Luis Mej\u00eda, presidente del Comit\u00e9 Ol\u00edmpico Dominicano, dijo que las federaciones deportivas nacionales ejecutar\u00e1n las medidas como lo han establecido las autoridades. \u201cVamos a ejecutar la reapertura conforme lo han dicho las autoridades\u201d, sostuvo el tambi\u00e9n miembro del Comit\u00e9 Ol\u00edmpico Internacional y presidente de la Organizaci\u00f3n Deportiva Centroamericana y del Caribe. En tanto que Persio Maldonado, quien preside la Federaci\u00f3n Dominicana de Tenis manifest\u00f3 que la resoluci\u00f3n es una buena noticia para que todo comience a normalizarse con las medidas anunciadas por las autoridades. Maldonado dijo que \u201ccada disciplina debe asegurarse de tener el mejor control posible\u201d para evitar los contagios, precisando que el tenis siempre ha cre\u00eddo que tiene que estar sometido a las normas de las autoridades\u201d. Expres\u00f3 que ha habido mucha impaciencia \u201cpero prefiero que sea as\u00ed y que no haya mucha gente contagiada\u201d. Carlos Elm\u00fadesi, presidente de la Federaci\u00f3n Dominicana de Golf dijo que lo de la apertura planteada en la resoluci\u00f3n \u201cno est\u00e1 clara\u201d. Considera que \u201chay una serie de deportes que tienen que estar abiertos y tienen que estar en la desescalada que empieza el 1 julio\u201d, se\u00f1alando que con el protocolo que se ha establecido \u201cel golf garantiza no va a ver problema en ning\u00fan sitio\u201d, refiri\u00e9ndose a los campos de golf del pa\u00eds. \u201cA nuestro pa\u00eds le conviene que el mundo sepa que aqu\u00ed se est\u00e1 jugando golf\u2026. tenemos enviar un mensaje al mundo y con esto ayudamos al turismo\u201d dijo.<\/p>\n","protected":false},"author":9,"featured_media":78886,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-78885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78885"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78885\/revisions"}],"predecessor-version":[{"id":78887,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78885\/revisions\/78887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78886"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}