{"id":78916,"date":"2020-07-01T07:01:56","date_gmt":"2020-07-01T11:01:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=78916"},"modified":"2020-07-01T07:02:00","modified_gmt":"2020-07-01T11:02:00","slug":"lionel-messi-llega-a-700-goles-pero-barcelona-cede-mas-puntos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lionel-messi-llega-a-700-goles-pero-barcelona-cede-mas-puntos\/","title":{"rendered":"Lionel Messi llega a 700 goles pero Bar\u00e7elona cede m\u00e1s puntos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"195\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/07\/lionel-messi-llega-a-700-goles-pero-barelona-cede-mas-puntos.jpeg\" alt=\"\" class=\"wp-image-78917\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Lionel Messi celebr\u00f3 con un penal a lo \u201cPanenka\u201d su diana 700 con el Barcelona y la selecci\u00f3n argentina, pero su magia no impidi\u00f3 que el conjunto catal\u00e1n cediera puntos de nuevo en su lucha por un t\u00edtulo de La Liga espa\u00f1ola que parece ahora m\u00e1s lejano, al empatar el martes 2-2 con el Atl\u00e9tico de Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Messi alcanz\u00f3 el hito con un suave disparo que pas\u00f3 casi por el centro mientras el arquero esloveno Jan Oblak se tiraba a su lado izquierdo a los 50. El astro argentino provoc\u00f3 adem\u00e1s un autogol de Diego Costa con un cobro de tiro de esquina para abrir el marcador a los 11.Sa\u00fal \u00d1\u00edguez marc\u00f3 un doblete con sendos penales a los 19 y 62. En el caso del primero lo convirti\u00f3 en una segunda oportunidad despu\u00e9s de que Costa err\u00f3 el primero, pero la ejecuci\u00f3n se repiti\u00f3 porque el arquero Marc-Andr\u00e9 ter Stegen se adelant\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su segunda diana, el portero alem\u00e1n alcanz\u00f3 a tocar el esf\u00e9rico, que termin\u00f3 por meterse a las redes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El club azulgrana, campe\u00f3n defensor, dej\u00f3 m\u00e1s puntos en el camino y se estanc\u00f3 con 70 unidades, una menos de las que tiene el Real Madrid, que afrontar\u00e1 su duelo por la 33ra jornada el jueves ante el Getafe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl equipo ha dado la cara y ha competido, pero por un motivo u otro no hemos podido llevarnos los dos puntos (adicionales) y eso dice que nos aleja un poco m\u00e1s del liderato si el Real Madrid gana. Nosotros tenemos que seguir a lo nuestro, intentar ganar que es lo primordial\u201d, dijo el centrocampista azulgrana Sergio Busquets.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los colchoneros extendieron a seis fechas su paso invicto \u2014cuatro triunfos y dos empates\u2014 desde que se reanud\u00f3 la liga interrumpida un trimestre debido a la pandemia de coronavirus. Se mantienen en la tercera posici\u00f3n con 59 unidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el t\u00e9cnico colchonero Diego Simeone no pudo romper la maldici\u00f3n. Jam\u00e1s ha vencido al Barcelona en el Camp Nou en La Liga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Messi ha labrado su exitoso paso hacia los 700 goles desde hace 15 a\u00f1os, cuando obtuvo el primero con el Bar\u00e7a el 1 de mayo de 2005 ante el Albacete. Con los azulgrana tiene 630 y 70 con Argentina. Ha celebrado 441 en 479 duelos de la liga. Contra el Atleti cuenta con 32 dianas en todas las competencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero la magia del 10 del Barsa no fue suficiente para marcar la ruta de la victoria y en un par de intentos antes del descanso sus disparos pasaron a un lado de la puerta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Atleti no cay\u00f3 en desesperaci\u00f3n, a pesar de verse en un par de desventajas supo reaccionar por conducto de Yannick Carrasco, quien en dos incursiones al \u00e1rea fue derribado por el chileno Arturo Vidal y el portugu\u00e9s Nelson Semedo con lo que se marcaron las faltas que convirti\u00f3 \u00d1\u00edguez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cobro del primer penal del duelo se repiti\u00f3 despu\u00e9s de que el videoarbitraje (VAR) determin\u00f3 que Ter Stegen se hab\u00eda adelantado. El alem\u00e1n jug\u00f3 condicionado el resto del duelo despu\u00e9s de ver un cart\u00f3n amarillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El astro franc\u00e9s Antoine Griezmann volvi\u00f3 a ser banca de arranque y entr\u00f3 de cambio en la reposici\u00f3n ante el equipo con el que milit\u00f3 hasta la campa\u00f1a pasada y al que dej\u00f3 mediante una operaci\u00f3n de compra por 120 millones de euros (134,8 millones de d\u00f3lares).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">SEVILLA ALLANA CAMINO A LA CHAMPIONS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un doblete de \u00d3liver Torres (23 y 35) y otro tanto m\u00e1s del hispano-marroqu\u00ed Munir El Haddadi (82) el Sevilla gole\u00f3 3-0 al Legan\u00e9s para afianzarse en la cuarta posici\u00f3n.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cuadro sevillista tiene 57 puntos, cinco m\u00e1s que el Getafe en la lucha por el \u00faltimo sitio que da pase a la Liga de Campeones. El Legan\u00e9s parece condenado al descenso al quedarse como pen\u00faltimo con 25 unidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">MALLORCA GOLEA EN CASA<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante Budimir (13 de penal, y 52), Cucho Hern\u00e1ndez (27), Alejandro Pozo (40) y Salva Sevilla (60) marcaron en la goleada que firm\u00f3 el Mallorca en casa 5-1 sobre el Celta de Vigo, por los que descont\u00f3 Iago Aspas (50 de penal).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Mallorca logr\u00f3 su primera victoria tras la reanudaci\u00f3n de la liga y sigue en la zona de descenso, en el 18vo sitio con 29 unidades. El Celta desperdici\u00f3 una opci\u00f3n para dar un paso a la salvaci\u00f3n. Se ubica un escal\u00f3n arriba con 34.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lionel Messi celebr\u00f3 con un penal a lo \u201cPanenka\u201d su diana 700 con el Barcelona y la selecci\u00f3n argentina, pero su magia no impidi\u00f3 que el conjunto catal\u00e1n cediera puntos de nuevo en su lucha por un t\u00edtulo de La Liga espa\u00f1ola que parece ahora m\u00e1s lejano, al empatar el martes 2-2 con el Atl\u00e9tico de Madrid. Messi alcanz\u00f3 el hito con un suave disparo que pas\u00f3 casi por el centro mientras el arquero esloveno Jan Oblak se tiraba a su lado izquierdo a los 50. El astro argentino provoc\u00f3 adem\u00e1s un autogol de Diego Costa con un cobro de tiro de esquina para abrir el marcador a los 11.Sa\u00fal \u00d1\u00edguez marc\u00f3 un doblete con sendos penales a los 19 y 62. En el caso del primero lo convirti\u00f3 en una segunda oportunidad despu\u00e9s de que Costa err\u00f3 el primero, pero la ejecuci\u00f3n se repiti\u00f3 porque el arquero Marc-Andr\u00e9 ter Stegen se adelant\u00f3. En su segunda diana, el portero alem\u00e1n alcanz\u00f3 a tocar el esf\u00e9rico, que termin\u00f3 por meterse a las redes. El club azulgrana, campe\u00f3n defensor, dej\u00f3 m\u00e1s puntos en el camino y se estanc\u00f3 con 70 unidades, una menos de las que tiene el Real Madrid, que afrontar\u00e1 su duelo por la 33ra jornada el jueves ante el Getafe. \u201cEl equipo ha dado la cara y ha competido, pero por un motivo u otro no hemos podido llevarnos los dos puntos (adicionales) y eso dice que nos aleja un poco m\u00e1s del liderato si el Real Madrid gana. Nosotros tenemos que seguir a lo nuestro, intentar ganar que es lo primordial\u201d, dijo el centrocampista azulgrana Sergio Busquets. Los colchoneros extendieron a seis fechas su paso invicto \u2014cuatro triunfos y dos empates\u2014 desde que se reanud\u00f3 la liga interrumpida un trimestre debido a la pandemia de coronavirus. Se mantienen en la tercera posici\u00f3n con 59 unidades. Pero el t\u00e9cnico colchonero Diego Simeone no pudo romper la maldici\u00f3n. Jam\u00e1s ha vencido al Barcelona en el Camp Nou en La Liga. Messi ha labrado su exitoso paso hacia los 700 goles desde hace 15 a\u00f1os, cuando obtuvo el primero con el Bar\u00e7a el 1 de mayo de 2005 ante el Albacete. Con los azulgrana tiene 630 y 70 con Argentina. Ha celebrado 441 en 479 duelos de la liga. Contra el Atleti cuenta con 32 dianas en todas las competencias. Pero la magia del 10 del Barsa no fue suficiente para marcar la ruta de la victoria y en un par de intentos antes del descanso sus disparos pasaron a un lado de la puerta. El Atleti no cay\u00f3 en desesperaci\u00f3n, a pesar de verse en un par de desventajas supo reaccionar por conducto de Yannick Carrasco, quien en dos incursiones al \u00e1rea fue derribado por el chileno Arturo Vidal y el portugu\u00e9s Nelson Semedo con lo que se marcaron las faltas que convirti\u00f3 \u00d1\u00edguez. El cobro del primer penal del duelo se repiti\u00f3 despu\u00e9s de que el videoarbitraje (VAR) determin\u00f3 que Ter Stegen se hab\u00eda adelantado. El alem\u00e1n jug\u00f3 condicionado el resto del duelo despu\u00e9s de ver un cart\u00f3n amarillo. El astro franc\u00e9s Antoine Griezmann volvi\u00f3 a ser banca de arranque y entr\u00f3 de cambio en la reposici\u00f3n ante el equipo con el que milit\u00f3 hasta la campa\u00f1a pasada y al que dej\u00f3 mediante una operaci\u00f3n de compra por 120 millones de euros (134,8 millones de d\u00f3lares). SEVILLA ALLANA CAMINO A LA CHAMPIONS Con un doblete de \u00d3liver Torres (23 y 35) y otro tanto m\u00e1s del hispano-marroqu\u00ed Munir El Haddadi (82) el Sevilla gole\u00f3 3-0 al Legan\u00e9s para afianzarse en la cuarta posici\u00f3n. El cuadro sevillista tiene 57 puntos, cinco m\u00e1s que el Getafe en la lucha por el \u00faltimo sitio que da pase a la Liga de Campeones. El Legan\u00e9s parece condenado al descenso al quedarse como pen\u00faltimo con 25 unidades. MALLORCA GOLEA EN CASA Ante Budimir (13 de penal, y 52), Cucho Hern\u00e1ndez (27), Alejandro Pozo (40) y Salva Sevilla (60) marcaron en la goleada que firm\u00f3 el Mallorca en casa 5-1 sobre el Celta de Vigo, por los que descont\u00f3 Iago Aspas (50 de penal). El Mallorca logr\u00f3 su primera victoria tras la reanudaci\u00f3n de la liga y sigue en la zona de descenso, en el 18vo sitio con 29 unidades. El Celta desperdici\u00f3 una opci\u00f3n para dar un paso a la salvaci\u00f3n. Se ubica un escal\u00f3n arriba con 34.<\/p>\n","protected":false},"author":9,"featured_media":78917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-78916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=78916"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78916\/revisions"}],"predecessor-version":[{"id":78918,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/78916\/revisions\/78918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/78917"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=78916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=78916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=78916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}