{"id":79198,"date":"2020-08-13T15:24:44","date_gmt":"2020-08-13T19:24:44","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79198"},"modified":"2020-08-13T15:26:11","modified_gmt":"2020-08-13T19:26:11","slug":"lapiz-conciente-supera-a-anuel-aa-en-instagram-mira-como","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lapiz-conciente-supera-a-anuel-aa-en-instagram-mira-como\/","title":{"rendered":"L\u00e1piz Conciente Supera A Anuel AA En Instagram (Mira C\u00f3mo)"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"251\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/08\/anuel-y-lapiz.jpg\" alt=\"\" class=\"wp-image-79200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/08\/anuel-y-lapiz.jpg 539w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/08\/anuel-y-lapiz-300x140.jpg 300w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><figcaption>L\u00e1piz supera a Anuel en la redes<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> El rapero dominicano L\u00e1piz Conciente ha superado al trapero boricua Anuel AA en influencia en la red social Instagram, hecho notado, ya que Anuel AA solicit\u00f3 medio mill\u00f3n de comentarios para lanzar el tema \u201cLa beb\u00e9 remix\u201d y le tom\u00f3 cerca de 12 horas lograrlo, sin embargo, el Pap\u00e1 del Rap solicit\u00f3 un mill\u00f3n de comentarios y lo logr\u00f3 a los 2 d\u00edas, y luego solicit\u00f3 2 millones para lanzar la respuesta a Mozart La Para y lo consigui\u00f3 en menos de 24 horas. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rapero dominicano L\u00e1piz Conciente ha superado al trapero boricua Anuel AA en influencia en la red social Instagram, hecho notado, ya que Anuel AA solicit\u00f3 medio mill\u00f3n de comentarios para lanzar el tema \u201cLa beb\u00e9 remix\u201d y le tom\u00f3 cerca de 12 horas lograrlo, sin embargo, el Pap\u00e1 del Rap solicit\u00f3 un mill\u00f3n de comentarios y lo logr\u00f3 a los 2 d\u00edas, y luego solicit\u00f3 2 millones para lanzar la respuesta a Mozart La Para y lo consigui\u00f3 en menos de 24 horas.<\/p>\n","protected":false},"author":12,"featured_media":79200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-79198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79198"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79198\/revisions"}],"predecessor-version":[{"id":79202,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79198\/revisions\/79202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79200"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}