{"id":79257,"date":"2020-08-26T07:48:02","date_gmt":"2020-08-26T11:48:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79257"},"modified":"2020-08-26T07:48:05","modified_gmt":"2020-08-26T11:48:05","slug":"hector-acosta-entre-el-arte-y-la-politica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hector-acosta-entre-el-arte-y-la-politica\/","title":{"rendered":"H\u00e9ctor Acosta: Entre el arte y la pol\u00edtica"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"167\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/08\/tori.jpg\" alt=\"\" class=\"wp-image-79258\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/08\/tori.jpg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/08\/tori-300x152.jpg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C<\/strong>omo a to\u00addos, la pan\u00addemia por el Covid-19 ha afectado a H\u00e9ctor Acosta (Bonao, 1967), quien no ve una sali\u00adda cercana a esta situaci\u00f3n. El reci\u00e9n juramentado sena\u00addor por la provincia Monse\u00ad\u00f1or Nouel entiende que por un buen tiempo no podr\u00e1 reunir a sus seguidores para disfrutar de su m\u00fasica, bai\u00adlarla, escucharla con la rica experiencia del sonido en directo y, por supuesto, ver en escena a su artista favo\u00adrito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHa sido duro\u201d, comen\u00adta El Torito, y pasa a con\u00adtar esos aspectos en qu\u00e9 el coronavirus ha trastocado su vida, empezando por lo econ\u00f3mico, porque ha de\u00adjado de percibir un dinero mensual, y no puede echar\u00adle la culpa a nadie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero esto no es exclusi\u00advo suyo, sino para todos los artistas que como \u00e9l, se dedican al g\u00e9nero tropical. \u201cTrabajamos para mucha gente\u201d, a\u00f1ade, y que desde el 29 de febrero los m\u00fasicos que integran su orquesta no han tocado una nota.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por esto, y como una for\u00adma de llevar alegr\u00eda a sus fans y al mismo tiempo dar\u00adle movimiento a su carrera art\u00edstica y ponerla al d\u00eda con lo digital, presentar\u00e1 el con\u00adcierto \u201cTorito Mundial\u201d, que se transmitir\u00e1 en streaming.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La producci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ren\u00e9 Brea produce el show est\u00e1 programado para este domingo 30 de agosto a las 8:00 de la noche, hora local, y podr\u00e1 ser disfrutado en to\u00addo el mundo a trav\u00e9s de la plataforma&nbsp;<a href=\"https:\/\/www.adnstreamconcerts.com\/\">www.adnstrea\u00admconcerts.com.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un espect\u00e1culo del que dice estar\u00e1 su orquesta completa, con juego de lu\u00adces, bailarinas, y en el que intepretar\u00e1 todos los \u00e9xitos que han dado forma a su re\u00adpertorio durante las \u00faltimas tres d\u00e9cadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un concierto en el que el artista enfatiza, se ten\u00addr\u00e1 un protocolo de seguri\u00addad acorde con la situaci\u00f3n. En ese sentido, el distancia\u00admiento de los instrumentis\u00adtas y el uso de mascarillas ser\u00e1n parte de las normas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El cantante de temas co\u00admo \u201cEl Mujer\u00f3n\u201d y Amorci\u00adto enfermito\u201d, entiende que los conciertos en linea pue\u00adden ser una salida para los artistas en esta pandemia.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brea, quien tiene a su cargo la parte creativa y la puesta en escena, explica que este show de H\u00e9ctor Acosta ser\u00e1 un contenido totalmente original y exclu\u00adsivo para los usuarios de es\u00adte nuevo servicio de strea\u00adming, el cual puede ser visto &nbsp;&nbsp;desde tel\u00e9fonos inteligen\u00adtes, computadoras, tablets, SmartTV y otros dispositi\u00advos con acceso a internet en cualquier parte del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCreo que por un buen rato la gente va a tener que acostumbrarse a ver este ti\u00adpo de evento para ver y es\u00adcuchar a sus artistas, por\u00adque nadie sabe la fecha en que puedas volver a ver cien personas juntas escuchando al Torito o a otros artistas\u201d, considera Acosta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En sus redes sociales, El Torito ha generado algunas controversias al momen\u00adto de ofrecer sus opiniones sobre temas de inter\u00e9s so\u00adcial, algo que le ha genera\u00addo unas veces el aplauso y otras tantas criticas. \u201cMi Instagram y mi Twitter es por donde yo mando mis vejigazos, mis cosas del arte y hasta politicos, soy yo quien lo maneja, y enfrento mis consecuencias\u201d, dice.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esos espacios fueron tam\u00adbi\u00e9n dejando ver sus pre\u00adocupaciones sociales, las mismas que lo han llevado a ser senador de su pueblo, Bonao.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Su papel pol\u00edtico<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el pasado 16 de agos\u00adto, H\u00e9ctor Elpidio Acosta Restituyo, nombre comple\u00adto del artista, ocupa el cargo de senador de su provincia. algo que encarar\u00e1, seg\u00fan di\u00adce, siguiendo el consejo de gente que sabe m\u00e1s que \u00e9l de pol\u00edtica. \u201cMe gusta eso, escuchar a los dem\u00e1s, a los que saben. Creo que, con Dios delante, lo que me pro\u00adpuse, que fue ayudar a mi gente, lo he empezado a lo\u00adgrar\u201d, asegura satisfecho de saber que mucha gente le ha abierto las puertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong>DETALLES<\/strong><br \/><strong>Novedad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La promoci\u00f3n de \u201cTori\u00adto Mundial\u201d est\u00e1 basada una estrategia que se di\u00adfundir\u00e1 por diversos pa\u00ed\u00adses del continente y que comprende medios tra\u00addicionales y digitales, explicaron sus promo\u00adtores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La cita.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El show est\u00e1 programa\u00addo para las 8:00 de la noche del domingo 30 de agosto, siendo este el primero de una serie de espect\u00e1culos que podr\u00e1n verse a trav\u00e9s de ADN Stream Concerts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los accesos para el con\u00adcierto est\u00e1n disponibles desde ya en el portal de internet www.adns\u00adtreamconcerts.com, la cual tiene un costo de US$12.00 d\u00f3lares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como a to\u00addos, la pan\u00addemia por el Covid-19 ha afectado a H\u00e9ctor Acosta (Bonao, 1967), quien no ve una sali\u00adda cercana a esta situaci\u00f3n. El reci\u00e9n juramentado sena\u00addor por la provincia Monse\u00ad\u00f1or Nouel entiende que por un buen tiempo no podr\u00e1 reunir a sus seguidores para disfrutar de su m\u00fasica, bai\u00adlarla, escucharla con la rica experiencia del sonido en directo y, por supuesto, ver en escena a su artista favo\u00adrito. \u201cHa sido duro\u201d, comen\u00adta El Torito, y pasa a con\u00adtar esos aspectos en qu\u00e9 el coronavirus ha trastocado su vida, empezando por lo econ\u00f3mico, porque ha de\u00adjado de percibir un dinero mensual, y no puede echar\u00adle la culpa a nadie. Pero esto no es exclusi\u00advo suyo, sino para todos los artistas que como \u00e9l, se dedican al g\u00e9nero tropical. \u201cTrabajamos para mucha gente\u201d, a\u00f1ade, y que desde el 29 de febrero los m\u00fasicos que integran su orquesta no han tocado una nota. Por esto, y como una for\u00adma de llevar alegr\u00eda a sus fans y al mismo tiempo dar\u00adle movimiento a su carrera art\u00edstica y ponerla al d\u00eda con lo digital, presentar\u00e1 el con\u00adcierto \u201cTorito Mundial\u201d, que se transmitir\u00e1 en streaming. La producci\u00f3n Ren\u00e9 Brea produce el show est\u00e1 programado para este domingo 30 de agosto a las 8:00 de la noche, hora local, y podr\u00e1 ser disfrutado en to\u00addo el mundo a trav\u00e9s de la plataforma&nbsp;www.adnstrea\u00admconcerts.com. Un espect\u00e1culo del que dice estar\u00e1 su orquesta completa, con juego de lu\u00adces, bailarinas, y en el que intepretar\u00e1 todos los \u00e9xitos que han dado forma a su re\u00adpertorio durante las \u00faltimas tres d\u00e9cadas. Un concierto en el que el artista enfatiza, se ten\u00addr\u00e1 un protocolo de seguri\u00addad acorde con la situaci\u00f3n. En ese sentido, el distancia\u00admiento de los instrumentis\u00adtas y el uso de mascarillas ser\u00e1n parte de las normas. El cantante de temas co\u00admo \u201cEl Mujer\u00f3n\u201d y Amorci\u00adto enfermito\u201d, entiende que los conciertos en linea pue\u00adden ser una salida para los artistas en esta pandemia. Brea, quien tiene a su cargo la parte creativa y la puesta en escena, explica que este show de H\u00e9ctor Acosta ser\u00e1 un contenido totalmente original y exclu\u00adsivo para los usuarios de es\u00adte nuevo servicio de strea\u00adming, el cual puede ser visto &nbsp;&nbsp;desde tel\u00e9fonos inteligen\u00adtes, computadoras, tablets, SmartTV y otros dispositi\u00advos con acceso a internet en cualquier parte del mundo. \u201cCreo que por un buen rato la gente va a tener que acostumbrarse a ver este ti\u00adpo de evento para ver y es\u00adcuchar a sus artistas, por\u00adque nadie sabe la fecha en que puedas volver a ver cien personas juntas escuchando al Torito o a otros artistas\u201d, considera Acosta. En sus redes sociales, El Torito ha generado algunas controversias al momen\u00adto de ofrecer sus opiniones sobre temas de inter\u00e9s so\u00adcial, algo que le ha genera\u00addo unas veces el aplauso y otras tantas criticas. \u201cMi Instagram y mi Twitter es por donde yo mando mis vejigazos, mis cosas del arte y hasta politicos, soy yo quien lo maneja, y enfrento mis consecuencias\u201d, dice. En esos espacios fueron tam\u00adbi\u00e9n dejando ver sus pre\u00adocupaciones sociales, las mismas que lo han llevado a ser senador de su pueblo, Bonao. Su papel pol\u00edtico Desde el pasado 16 de agos\u00adto, H\u00e9ctor Elpidio Acosta Restituyo, nombre comple\u00adto del artista, ocupa el cargo de senador de su provincia. algo que encarar\u00e1, seg\u00fan di\u00adce, siguiendo el consejo de gente que sabe m\u00e1s que \u00e9l de pol\u00edtica. \u201cMe gusta eso, escuchar a los dem\u00e1s, a los que saben. Creo que, con Dios delante, lo que me pro\u00adpuse, que fue ayudar a mi gente, lo he empezado a lo\u00adgrar\u201d, asegura satisfecho de saber que mucha gente le ha abierto las puertas. &nbsp;DETALLESNovedad La promoci\u00f3n de \u201cTori\u00adto Mundial\u201d est\u00e1 basada una estrategia que se di\u00adfundir\u00e1 por diversos pa\u00ed\u00adses del continente y que comprende medios tra\u00addicionales y digitales, explicaron sus promo\u00adtores. La cita. El show est\u00e1 programa\u00addo para las 8:00 de la noche del domingo 30 de agosto, siendo este el primero de una serie de espect\u00e1culos que podr\u00e1n verse a trav\u00e9s de ADN Stream Concerts. Los accesos para el con\u00adcierto est\u00e1n disponibles desde ya en el portal de internet www.adns\u00adtreamconcerts.com, la cual tiene un costo de US$12.00 d\u00f3lares.<\/p>\n","protected":false},"author":9,"featured_media":79258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-79257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79257"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79257\/revisions"}],"predecessor-version":[{"id":79259,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79257\/revisions\/79259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79258"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}