{"id":79301,"date":"2020-09-30T15:30:27","date_gmt":"2020-09-30T19:30:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79301"},"modified":"2020-09-30T15:30:33","modified_gmt":"2020-09-30T19:30:33","slug":"tiktok-edita-guia-para-las-elecciones-en-eeuu-a-pesar-de-su-precaria-situacion-en-el-pais","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tiktok-edita-guia-para-las-elecciones-en-eeuu-a-pesar-de-su-precaria-situacion-en-el-pais\/","title":{"rendered":"TikTok edita gu\u00eda para las elecciones en EEUU a pesar de su precaria situaci\u00f3n en el pa\u00eds"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/09\/gggg.jpg\" alt=\"\" class=\"wp-image-79303\" width=\"422\" height=\"239\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n de videos&nbsp;<strong>TikTok&nbsp;<\/strong>estableci\u00f3 el martes una \u00abgu\u00eda\u00bb para las elecciones estadounidense, al igual que otras redes sociales importantes, a pesar de la incertidumbre sobre su futuro en el pa\u00eds norteamericano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta secci\u00f3n de la plataforma proporciona informaci\u00f3n sobre los candidatos (a nivel local y federal), explica c\u00f3mo votar y brinda enlaces a sitios \u00fatiles, por ejemplo para verificar la inscripci\u00f3n de un ciudadano en el censo electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El contenido informativo proviene de autoridades u organismos independientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Facebook, Twitter, YouTube&nbsp;<\/strong>(<strong>Google<\/strong>) y otros han tomado medidas similares para garantizar que los votantes tengan acceso prioritario a informaci\u00f3n confiable antes de una elecci\u00f3n que se anuncia muy disputada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero para TikTok, este anuncio llega en un contexto de tensiones con el presidente y candidato a la reelecci\u00f3n Donald Trump, quien acusa, sin pruebas, a la aplicaci\u00f3n de espiar para Pek\u00edn, por pertenecer al grupo chino ByteDance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Departamento de Comercio dijo que la plataforma quedar\u00e1 prohibida en Estados Unidos el 12 de noviembre si antes de ese d\u00eda no es adquirida por una empresa local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las negociaciones que ha mantenido con algunas compa\u00f1\u00edas (especialmente Oracle y Walmart) y diversas acciones legales le han permitido hasta ahora ganar tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n es seguida por 100 millones de personas en Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPor supuesto, TikTok no es la aplicaci\u00f3n de referencia para noticias o para pol\u00edtica\u00bb, admite Michael Beckerman, vicepresidente de la compa\u00f1\u00eda encargado de las regulaciones den Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abY no aceptamos anuncios pol\u00edticos pagados en nuestra aplicaci\u00f3n\u00bb, agreg\u00f3, aludiendo a Facebook, muy criticado por permitirlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPero sabemos que TikTok es un lugar para que los estadounidenses hablen. Con esta realidad en mente, queremos apoyar a nuestros usuarios con informaci\u00f3n autorizada sobre temas importantes para el debate p\u00fablico\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La aplicaci\u00f3n de videos&nbsp;TikTok&nbsp;estableci\u00f3 el martes una \u00abgu\u00eda\u00bb para las elecciones estadounidense, al igual que otras redes sociales importantes, a pesar de la incertidumbre sobre su futuro en el pa\u00eds norteamericano. Esta secci\u00f3n de la plataforma proporciona informaci\u00f3n sobre los candidatos (a nivel local y federal), explica c\u00f3mo votar y brinda enlaces a sitios \u00fatiles, por ejemplo para verificar la inscripci\u00f3n de un ciudadano en el censo electoral. El contenido informativo proviene de autoridades u organismos independientes. Facebook, Twitter, YouTube&nbsp;(Google) y otros han tomado medidas similares para garantizar que los votantes tengan acceso prioritario a informaci\u00f3n confiable antes de una elecci\u00f3n que se anuncia muy disputada. Pero para TikTok, este anuncio llega en un contexto de tensiones con el presidente y candidato a la reelecci\u00f3n Donald Trump, quien acusa, sin pruebas, a la aplicaci\u00f3n de espiar para Pek\u00edn, por pertenecer al grupo chino ByteDance. El Departamento de Comercio dijo que la plataforma quedar\u00e1 prohibida en Estados Unidos el 12 de noviembre si antes de ese d\u00eda no es adquirida por una empresa local. Las negociaciones que ha mantenido con algunas compa\u00f1\u00edas (especialmente Oracle y Walmart) y diversas acciones legales le han permitido hasta ahora ganar tiempo. La aplicaci\u00f3n es seguida por 100 millones de personas en Estados Unidos. \u00abPor supuesto, TikTok no es la aplicaci\u00f3n de referencia para noticias o para pol\u00edtica\u00bb, admite Michael Beckerman, vicepresidente de la compa\u00f1\u00eda encargado de las regulaciones den Estados Unidos. \u00abY no aceptamos anuncios pol\u00edticos pagados en nuestra aplicaci\u00f3n\u00bb, agreg\u00f3, aludiendo a Facebook, muy criticado por permitirlo. \u00abPero sabemos que TikTok es un lugar para que los estadounidenses hablen. Con esta realidad en mente, queremos apoyar a nuestros usuarios con informaci\u00f3n autorizada sobre temas importantes para el debate p\u00fablico\u00bb.<\/p>\n","protected":false},"author":9,"featured_media":79303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-79301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79301"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79301\/revisions"}],"predecessor-version":[{"id":79304,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79301\/revisions\/79304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79303"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}