{"id":79330,"date":"2020-10-02T17:11:39","date_gmt":"2020-10-02T21:11:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79330"},"modified":"2020-10-02T17:11:42","modified_gmt":"2020-10-02T21:11:42","slug":"ozuna-y-los-bravos-barren-a-cincinnati","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ozuna-y-los-bravos-barren-a-cincinnati\/","title":{"rendered":"Ozuna y los Bravos barren a Cincinnati"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"296\" height=\"237\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/10\/poe.jpg\" alt=\"\" class=\"wp-image-79331\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hab\u00eda transcurrido tanto tiempo desde que los Bra\u00advos de Atlanta ganaron una serie de postempora\u00adda, as\u00ed que Marcell Ozuna quer\u00eda asegurarse de gra\u00adbar el momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adam Duvall tambi\u00e9n quiso sumarse a la tanda de selfies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ronald Acu\u00f1a Jr. co\u00adnect\u00f3 tres hits e Ian An\u00adderson encandil\u00f3 en otra blanqueada de Atlanta, y los Bravos ganaron una se\u00adrie de playoffs por primera vez en casi dos d\u00e9cadas al barrer a los Rojos de Cinci\u00adnatti al vencerles el jueves por 5-0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acu\u00f1a conect\u00f3 un do\u00adblete remolcador en el quinto episodio por los campeones de la Divisi\u00f3n Este de la Liga Nacional. Luego de llevarse el pri\u00admer juego el mi\u00e9rcoles 1-0 en 13 innings, Atlan\u00adta liquid\u00f3 el segundo due\u00adlo con un par de jonrones de dos carreras de Ozuna y Adam Duvall ante Raisel Iglesias en el octavo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras su imparable a la izquierda del campo, Ozu\u00adna se detuvo en su trote a la primera base para le\u00advantar el brazo y preten\u00adder que se tomaba una foto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando Duvall tambi\u00e9n la desapareci\u00f3, Ozuna le pi\u00addi\u00f3 que se acercara al final del dugout para otra foto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Duvall dijo que su com\u00adpa\u00f1ero dominicano \u201cme puso en los reflectores\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMe divert\u00ed con eso. No es mi fuerte, creo que no soy muy vistoso, pero nos est\u00e1bamos divirtiendo\u201d.<ins><\/ins><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciertamente fue un d\u00eda divertido para Ozuna y sus compa\u00f1eros. No tanto as\u00ed para Joey Votto y los Rojos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anderson recet\u00f3 nue\u00adve ponches en seis innings. Los Bravos rompieron as\u00ed<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;una racha de debacles en 10 rondas consecutivas de postemporada desde su \u00fal\u00adtima victoria en los playoffs en 2001.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atlanta enfrentar\u00e1 al ga\u00adnador del duelo entre los Marlins de Miami y los Ca\u00adchorros de Chicago, en una serie divisional que se dis\u00adputar\u00e1 en Houston.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que en 2001, cuando sus ases Greg Maddux, Tom Glavine y Jo\u00adhn Smoltz, los tres en el Sa\u00adl\u00f3n de la Fama, marcaron la pauta, los pitchers de Atlan\u00adta respondieron ante las cir\u00adcunstancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&nbsp;SEPA M\u00c1S<br \/>Buena apertura.<\/strong><br \/>Cincinnati desperdici\u00f3 una buena apertura del dominicano Luis Casti\u00adllo, quien ponch\u00f3 a siete en 5 1\/3 innings al estre\u00adnarse en la postempora\u00adda. Trevor Bauer ponch\u00f3 a 12 en 7 2\/3 en blanco cuando los Rojos acaba\u00adron perdiendo el primer choque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los Bravos, el domini\u00adcano Ozuna de 4-1, una anotada y dos remolca\u00addas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hab\u00eda transcurrido tanto tiempo desde que los Bra\u00advos de Atlanta ganaron una serie de postempora\u00adda, as\u00ed que Marcell Ozuna quer\u00eda asegurarse de gra\u00adbar el momento. Adam Duvall tambi\u00e9n quiso sumarse a la tanda de selfies. Ronald Acu\u00f1a Jr. co\u00adnect\u00f3 tres hits e Ian An\u00adderson encandil\u00f3 en otra blanqueada de Atlanta, y los Bravos ganaron una se\u00adrie de playoffs por primera vez en casi dos d\u00e9cadas al barrer a los Rojos de Cinci\u00adnatti al vencerles el jueves por 5-0. Acu\u00f1a conect\u00f3 un do\u00adblete remolcador en el quinto episodio por los campeones de la Divisi\u00f3n Este de la Liga Nacional. Luego de llevarse el pri\u00admer juego el mi\u00e9rcoles 1-0 en 13 innings, Atlan\u00adta liquid\u00f3 el segundo due\u00adlo con un par de jonrones de dos carreras de Ozuna y Adam Duvall ante Raisel Iglesias en el octavo. Tras su imparable a la izquierda del campo, Ozu\u00adna se detuvo en su trote a la primera base para le\u00advantar el brazo y preten\u00adder que se tomaba una foto. Cuando Duvall tambi\u00e9n la desapareci\u00f3, Ozuna le pi\u00addi\u00f3 que se acercara al final del dugout para otra foto. Duvall dijo que su com\u00adpa\u00f1ero dominicano \u201cme puso en los reflectores\u201d. \u201cMe divert\u00ed con eso. No es mi fuerte, creo que no soy muy vistoso, pero nos est\u00e1bamos divirtiendo\u201d. Ciertamente fue un d\u00eda divertido para Ozuna y sus compa\u00f1eros. No tanto as\u00ed para Joey Votto y los Rojos. Anderson recet\u00f3 nue\u00adve ponches en seis innings. Los Bravos rompieron as\u00ed &nbsp;una racha de debacles en 10 rondas consecutivas de postemporada desde su \u00fal\u00adtima victoria en los playoffs en 2001. Atlanta enfrentar\u00e1 al ga\u00adnador del duelo entre los Marlins de Miami y los Ca\u00adchorros de Chicago, en una serie divisional que se dis\u00adputar\u00e1 en Houston. Al igual que en 2001, cuando sus ases Greg Maddux, Tom Glavine y Jo\u00adhn Smoltz, los tres en el Sa\u00adl\u00f3n de la Fama, marcaron la pauta, los pitchers de Atlan\u00adta respondieron ante las cir\u00adcunstancias. &nbsp;SEPA M\u00c1SBuena apertura.Cincinnati desperdici\u00f3 una buena apertura del dominicano Luis Casti\u00adllo, quien ponch\u00f3 a siete en 5 1\/3 innings al estre\u00adnarse en la postempora\u00adda. Trevor Bauer ponch\u00f3 a 12 en 7 2\/3 en blanco cuando los Rojos acaba\u00adron perdiendo el primer choque. Por los Bravos, el domini\u00adcano Ozuna de 4-1, una anotada y dos remolca\u00addas.<\/p>\n","protected":false},"author":9,"featured_media":79331,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-79330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79330"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79330\/revisions"}],"predecessor-version":[{"id":79332,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79330\/revisions\/79332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79331"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}