{"id":79339,"date":"2020-10-02T17:22:52","date_gmt":"2020-10-02T21:22:52","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79339"},"modified":"2020-10-02T17:22:55","modified_gmt":"2020-10-02T21:22:55","slug":"facebook-borra-anuncios-trump","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/facebook-borra-anuncios-trump\/","title":{"rendered":"Facebook borra anuncios Trump"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/10\/tron.jpg\" alt=\"\" class=\"wp-image-79340\" width=\"424\" height=\"279\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook dijo que elimi\u00adn\u00f3 anuncios de campa\u00f1a del presidente de Estados Unidos, Donald Trump, en los que se dec\u00eda que su rival dem\u00f3crata Joe Bi\u00adden es \u201cpeligroso\u201d para el pa\u00eds por querer permitir una mayor inmigraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta medida, to\u00admada a \u00faltima hora del mi\u00e9rcoles, la que la red social trata de frenar la desinformaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los anuncios retirados dec\u00edan que Biden era \u201cpe\u00adligroso para Estados Uni\u00addos\u201d y denunciaba que el dem\u00f3crata permitir\u00eda un \u201caumento\u201d de la inmigra\u00adci\u00f3n, sugiriendo que esto podr\u00eda provocar un ma\u00adyor riesgo en la seguridad y frente al coronavirus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRechazamos estos anuncios porque no per\u00admitimos afirmaciones de que la seguridad f\u00edsica, la salud o la supervivencia de las personas se vea amena\u00adzada por personas en base a su origen nacional o estado de inmigraci\u00f3n\u201d, dijo Face\u00adbook en una declaraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La retirada de estos anun\u00adcios subray\u00f3 el desaf\u00edo para las plataformas de redes so\u00adciales que buscan depurar el mont\u00f3n de afirmaciones falsas que surgen durante la acalorada campa\u00f1a elec\u00adtoral, muchas de las cuales provienen de Trump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Facebook retir\u00f3 a princi\u00adpios de este a\u00f1o un anuncio del presidente que conten\u00eda un s\u00edmbolo usado en la Ale\u00admania Nazi para designar a prisioneros pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, Facebo\u00adok dijo tambi\u00e9n que esta\u00adba aclarando sus reglas so\u00adbre los anuncios que buscan cuestionar la legitimidad del proceso electoral, en medio de comentarios re\u00adcientes de Trump que sugie\u00adren que no puede confiar en el recuento de votos.<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facebook dijo que elimi\u00adn\u00f3 anuncios de campa\u00f1a del presidente de Estados Unidos, Donald Trump, en los que se dec\u00eda que su rival dem\u00f3crata Joe Bi\u00adden es \u201cpeligroso\u201d para el pa\u00eds por querer permitir una mayor inmigraci\u00f3n. Con esta medida, to\u00admada a \u00faltima hora del mi\u00e9rcoles, la que la red social trata de frenar la desinformaci\u00f3n. Los anuncios retirados dec\u00edan que Biden era \u201cpe\u00adligroso para Estados Uni\u00addos\u201d y denunciaba que el dem\u00f3crata permitir\u00eda un \u201caumento\u201d de la inmigra\u00adci\u00f3n, sugiriendo que esto podr\u00eda provocar un ma\u00adyor riesgo en la seguridad y frente al coronavirus. \u201cRechazamos estos anuncios porque no per\u00admitimos afirmaciones de que la seguridad f\u00edsica, la salud o la supervivencia de las personas se vea amena\u00adzada por personas en base a su origen nacional o estado de inmigraci\u00f3n\u201d, dijo Face\u00adbook en una declaraci\u00f3n. La retirada de estos anun\u00adcios subray\u00f3 el desaf\u00edo para las plataformas de redes so\u00adciales que buscan depurar el mont\u00f3n de afirmaciones falsas que surgen durante la acalorada campa\u00f1a elec\u00adtoral, muchas de las cuales provienen de Trump. Facebook retir\u00f3 a princi\u00adpios de este a\u00f1o un anuncio del presidente que conten\u00eda un s\u00edmbolo usado en la Ale\u00admania Nazi para designar a prisioneros pol\u00edticos. Por otro lado, Facebo\u00adok dijo tambi\u00e9n que esta\u00adba aclarando sus reglas so\u00adbre los anuncios que buscan cuestionar la legitimidad del proceso electoral, en medio de comentarios re\u00adcientes de Trump que sugie\u00adren que no puede confiar en el recuento de votos.<\/p>\n","protected":false},"author":9,"featured_media":79340,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-79339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79339"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79339\/revisions"}],"predecessor-version":[{"id":79341,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79339\/revisions\/79341"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79340"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}