{"id":79574,"date":"2020-11-05T17:29:19","date_gmt":"2020-11-05T21:29:19","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79574"},"modified":"2020-11-05T17:29:23","modified_gmt":"2020-11-05T21:29:23","slug":"solo-para-recordar-el-lunes-feriado-el-toque-de-queda-inicia-a-las-700-de-la-noche","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/solo-para-recordar-el-lunes-feriado-el-toque-de-queda-inicia-a-las-700-de-la-noche\/","title":{"rendered":"Solo para recordar: El lunes feriado el toque de queda inicia a las 7:00 de la noche"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/11\/202011051947161.jpeg\" alt=\"\" class=\"wp-image-79575\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/11\/202011051947161.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/11\/202011051947161-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado a\u00f1o el Ministerio de Trabajo al anunciar los d\u00edas feriados para&nbsp; 2020 indic\u00f3 que el viernes 6 de noviembre, D\u00eda de la Constituci\u00f3n, se trabaja y se cambia el d\u00eda de fiesta para el lunes 9 del mismo mes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Debido a los efectos de la pandemia del Covid-19 y las medidas para evitar la propagaci\u00f3n del virus<\/strong>, el Poder Ejecutivo mediante el decreto 554-20, emitido el pasado 16 de octubre, estableci\u00f3 que el toque de queda durante los d\u00edas s\u00e1bados, domingos y feriados iniciar\u00e1 a las 7:00 de la semana y concluir\u00e1 a la 5:00 de la ma\u00f1ana del siguiente d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA partir del 18 de octubre del a\u00f1o en curos se extiende por 25 d\u00edas el toque de queda establecido en el territorio nacional mediante el Decreto n\u00fam. 504-20, del 28 de septiembre de 2020, cuyo horario queda modificado de la siguiente manera:&nbsp; a) de lunes a viernes de 9:00 p.m. a 5: 00 a.m.; b) Los s\u00e1bados, domingos y feriados de 7:00 p. m. a 5:00 a. m.\u201d, establece el decreto en el art\u00edculo 1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este toque de queda vence el pr\u00f3ximo 12 del mes de noviembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado a\u00f1o el Ministerio de Trabajo al anunciar los d\u00edas feriados para&nbsp; 2020 indic\u00f3 que el viernes 6 de noviembre, D\u00eda de la Constituci\u00f3n, se trabaja y se cambia el d\u00eda de fiesta para el lunes 9 del mismo mes. Debido a los efectos de la pandemia del Covid-19 y las medidas para evitar la propagaci\u00f3n del virus, el Poder Ejecutivo mediante el decreto 554-20, emitido el pasado 16 de octubre, estableci\u00f3 que el toque de queda durante los d\u00edas s\u00e1bados, domingos y feriados iniciar\u00e1 a las 7:00 de la semana y concluir\u00e1 a la 5:00 de la ma\u00f1ana del siguiente d\u00eda. \u201cA partir del 18 de octubre del a\u00f1o en curos se extiende por 25 d\u00edas el toque de queda establecido en el territorio nacional mediante el Decreto n\u00fam. 504-20, del 28 de septiembre de 2020, cuyo horario queda modificado de la siguiente manera:&nbsp; a) de lunes a viernes de 9:00 p.m. a 5: 00 a.m.; b) Los s\u00e1bados, domingos y feriados de 7:00 p. m. a 5:00 a. m.\u201d, establece el decreto en el art\u00edculo 1. Este toque de queda vence el pr\u00f3ximo 12 del mes de noviembre.<\/p>\n","protected":false},"author":9,"featured_media":79575,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-79574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79574"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79574\/revisions"}],"predecessor-version":[{"id":79576,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79574\/revisions\/79576"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79575"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}