{"id":79649,"date":"2020-11-18T09:24:01","date_gmt":"2020-11-18T13:24:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79649"},"modified":"2020-11-18T09:24:04","modified_gmt":"2020-11-18T13:24:04","slug":"ensalada-de-tomate-y-pepino","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ensalada-de-tomate-y-pepino\/","title":{"rendered":"Ensalada de tomate y pepino"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/11\/tomato-and-cucumber-salad-.jpg\" alt=\"\" class=\"wp-image-79650\" width=\"369\" height=\"206\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Una ensalada que toda la familia puede preparar. Los padres pueden cortar los tomates y los pepinos, y dejar que los ni\u00f1os corten los cebollines con tijeras de cocina limpias. Luego, permita que los ni\u00f1os mezclen el resto de los ingredientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Nivel:&nbsp;F\u00e1cil<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ingredientes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Porciones:&nbsp;4<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>3 tomates cortados en rodajas finas<\/li><li>3 cebollines verdes picados<\/li><li>\u00bc taza de hojas picadas de menta, albahaca o perejil<\/li><li>1 pepino ingl\u00e9s, en rodajas<\/li><li>\u00bc taza de vinagre de vino de arroz<\/li><li>2 cucharadas de aceite de oliva<\/li><li>Sal y pimienta al gusto<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/>Preparaci\u00f3n<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>TIEMPO TOTAL:&nbsp;20&nbsp;minutos<\/li><li>Tiempo de preparaci\u00f3n:&nbsp;5&nbsp;minutos<\/li><li>Tiempo de cocci\u00f3n:&nbsp;15&nbsp;minutos<\/li><\/ul>\n\n\n\n<ol class=\"wp-block-list\"><li>Mezcle todos los ingredientes en un taz\u00f3n para servir y revuelva suavemente. Sazone al gusto. Deje marinar durante al menos diez minutos y hasta dos horas antes de servir.<\/li><\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Una ensalada que toda la familia puede preparar. Los padres pueden cortar los tomates y los pepinos, y dejar que los ni\u00f1os corten los cebollines con tijeras de cocina limpias. Luego, permita que los ni\u00f1os mezclen el resto de los ingredientes. Nivel:&nbsp;F\u00e1cil Ingredientes Porciones:&nbsp;4 3 tomates cortados en rodajas finas 3 cebollines verdes picados \u00bc taza de hojas picadas de menta, albahaca o perejil 1 pepino ingl\u00e9s, en rodajas \u00bc taza de vinagre de vino de arroz 2 cucharadas de aceite de oliva Sal y pimienta al gusto Preparaci\u00f3n TIEMPO TOTAL:&nbsp;20&nbsp;minutos Tiempo de preparaci\u00f3n:&nbsp;5&nbsp;minutos Tiempo de cocci\u00f3n:&nbsp;15&nbsp;minutos Mezcle todos los ingredientes en un taz\u00f3n para servir y revuelva suavemente. Sazone al gusto. Deje marinar durante al menos diez minutos y hasta dos horas antes de servir.<\/p>\n","protected":false},"author":9,"featured_media":79650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-79649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79649"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79649\/revisions"}],"predecessor-version":[{"id":79651,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79649\/revisions\/79651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79650"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}