{"id":7971,"date":"2014-09-03T09:49:46","date_gmt":"2014-09-03T13:49:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=7971"},"modified":"2015-09-20T18:19:44","modified_gmt":"2015-09-20T22:19:44","slug":"medina-devuelve-y-observa-la-ley-sobre-loma-miranda","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/medina-devuelve-y-observa-la-ley-sobre-loma-miranda\/","title":{"rendered":"Medina devuelve y observa la Ley sobre Loma Miranda."},"content":{"rendered":"<p style=\"color: #000000;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/DANILO.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-7972\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/DANILO-300x200.jpg\" alt=\"DANILO\" width=\"365\" height=\"243\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/DANILO-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/DANILO.jpg 348w\" sizes=\"auto, (max-width: 365px) 100vw, 365px\" \/><\/a>SANTO DOMINGO. El presidente Danilo Medina devolvi\u00f3 al Senado, sin promulgar, y observ\u00f3 en su totalidad la Ley que crea el Parque Nacional Loma Miranda, por entender que viola varios art\u00edculos de la Constituci\u00f3n, y que conllevar\u00eda el desconocimiento de compromisos internacionales asumidos por el Estado dominicano en materia de protecci\u00f3n de inversiones.<\/p>\n<p style=\"color: #000000;\">En una carta a la presidenta del Senado, Cristina Lizardo, que fue le\u00edda por el vocero de la Presidencia, Roberto Rodr\u00edguez Marchena, en rueda de prensa en el Sal\u00f3n Orlando Mart\u00ednez del Palacio Nacional, el mandatario cita las razones que lo llevaron a observar la referida ley.<\/p>\n<p style=\"color: #000000;\">El Jefe del Estado argument\u00f3 que la creaci\u00f3n del Parque Nacional Loma Miranda en un \u00e1rea que las autoridades competentes tienen identificada como de gran potencial minero (art\u00edculos 1 y 2), es contraria al mandato constitucional de aprovechamiento de los recursos naturales.<\/p>\n<p style=\"color: #000000;\">De igual manera, plantea que en la legislaci\u00f3n observada se establece como Parque Nacional un \u00e1rea sobre la que existe un contrato de concesi\u00f3n minera consentido por el Estado dominicano, y advierte sobre las consecuencias que traer\u00eda su extinci\u00f3n, y c\u00f3mo afectar\u00eda la seguridad jur\u00eddica y el clima futuro de inversi\u00f3n en la Rep\u00fablica Dominicana.<\/p>\n<p style=\"color: #000000;\">\u201cLa aprobaci\u00f3n fue una acci\u00f3n legislativa extempor\u00e1nea, debido a que ha sido la voluntad del constituyente de 2010, que lo relativo al uso eficiente y sostenible de los recursos naturales de la naci\u00f3n, se haga en el marco del Plan de Ordenamiento Territorial, que mediante ley debe expedir ese poder del Estado\u201d, refiere en la misiva.<\/p>\n<p style=\"color: #000000;\"><!--more--><\/p>\n<p style=\"color: #000000;\">En ese sentido, solicit\u00f3 al Congreso Nacional no solamente rechazar esta ley, sino, adem\u00e1s, \u201cpostergar cualquier decisi\u00f3n sobre Loma Miranda, y sobre cualquier otro \u00e1mbito del territorio nacional, de potencialidad minera, hasta que el Poder Legislativo dicte la ley que manda la Constituci\u00f3n sobre el Plan de Ordenamiento Territorial, a fin de que de manera racional, se maximice la protecci\u00f3n de nuestros recursos naturales, y se propicie un desarrollo minero responsable\u201d.<\/p>\n<p style=\"color: #000000;\">El Ejecutivo ponder\u00f3 el efecto adverso para el desarrollo del pa\u00eds que tendr\u00eda una ley que establezca un Parque Nacional que veda la posibilidad futura de aprovechamiento de los recursos naturales existentes dentro de su per\u00edmetro, aun cuando las condiciones socioecon\u00f3micas y ambientales, y las tecnolog\u00edas de explotaci\u00f3n minera, garanticen su sostenibilidad.<\/p>\n<p style=\"color: #000000;\">Tambi\u00e9n llam\u00f3 la atenci\u00f3n sobre el derecho de propiedad de particulares dentro del \u00e1mbito del Parque Nacional Loma Miranda, que no pueden ser afectados por expropiaci\u00f3n.<\/p>\n<p style=\"color: #000000;\"><strong><em>Cristina y Abel fueron a palacio<\/em><\/strong><\/p>\n<p style=\"color: #000000;\"><em>Previo a la rueda de prensa del portavoz del Gobierno, el presidente Danilo Medina recibi\u00f3 en su despacho a la presidenta del Senado, Cristina Lizardo y al titular de la C\u00e1mara de Diputados, Abel Mart\u00ednez, con quienes el mandatario habr\u00eda consultado sobre el plazo que establece la Constituci\u00f3n para la promulgaci\u00f3n de la ley sobre Loma Miranda, seg\u00fan inform\u00f3 la legisladora. De acuerdo con Lizardo, al mandatario supuestamente le interesaba saber cu\u00e1l era el l\u00edmite de espera que ten\u00eda. Sin embargo, minutos despu\u00e9s de \u00e9sta retirarse de la casa de gobierno, Roberto Rodr\u00edguez Marchena inform\u00f3 de las observaciones del gobernante a dicha ley.<\/em><\/p>\n<p style=\"color: #000000;\"><strong>Observaci\u00f3n no autoriza explotaci\u00f3n de Miranda<\/strong><\/p>\n<p style=\"color: #000000;\">En la carta a la presidenta del Senado, Medina aclara que su decisi\u00f3n no representa una expresi\u00f3n de voluntad del Gobierno de autorizar la explotaci\u00f3n de Loma Miranda.<\/p>\n<p style=\"color: #000000;\">Consider\u00f3 que una decisi\u00f3n de esta naturaleza \u00a0debe ser tomada luego que se hayan completado todos los estudios de impacto ambiental y validados los t\u00e9rminos de referencia de la explotaci\u00f3n bajo los m\u00e1s rigurosos est\u00e1ndares medio ambientales.<\/p>\n<p style=\"color: #000000;\">Garantiz\u00f3 al pueblo y a los sectores defensores de los recursos naturales, de los que apunt\u00f3 estaba consciente de que no recibir\u00edan bien la observaci\u00f3n, que bajo su presidencia no se autorizar\u00e1 ninguna explotaci\u00f3n minera en Loma Miranda, ni en ning\u00fan otro lugar del territorio nacional, \u201csin que se cumpla de manera estricta con los requerimientos de un aprovechamiento medioambientalmente sostenible, y que la empresa beneficiaria de la concesi\u00f3n, se gane leg\u00edtimamente, con sus acciones, la licencia social que amerita una explotaci\u00f3n de esta naturaleza\u201d.<\/p>\n<p style=\"color: #000000;\">El presidente Medina resalt\u00f3 que al asumir la primera magistratura del Estado el 16 de agosto de 2012, jur\u00f3 en cumplimiento del mandato establecido en el art\u00edculo 127 de la Carta Magna \u201ccumplir y hacer cumplir la Constituci\u00f3n y las leyes de la Rep\u00fablica\u201d.<\/p>\n<p style=\"color: #000000;\"><strong>Ni fundamentalismo ni capitalismo minero salvaje<\/strong><\/p>\n<p style=\"color: #000000;\">Danilo \u00a0Medina dijo que como Presidente de la Rep\u00fablica no se considera \u201cadherido ni al fundamentalismo medioambientalista ni al capitalismo minero salvaje\u201d.<\/p>\n<p style=\"color: #000000;\">Sostuvo que su responsabilidad como primer mandatario lo obliga a ponderar necesariamente entre la necesidad del aprovechamiento de nuestros recursos naturales y la protecci\u00f3n adecuada de los mismos en provecho de la presente y de las futuras generaciones.<\/p>\n<p style=\"color: #000000;\">Expres\u00f3 que esa ponderaci\u00f3n, ordenada por la Carta Sustantiva del Estado en su art\u00edculo 74.4, lo obliga \u00a0a una acci\u00f3n presidencial que armonice ambos bienes constitucionales sin necesidad de sacrificar uno u otro.<\/p>\n<p style=\"color: #000000;\">\u201cEs pol\u00edtica p\u00fablica de esta administraci\u00f3n en el \u00e1mbito del medio ambiente y los recursos naturales, el conferir exclusivamente los t\u00edtulos habilitantes medioambientales exigidos por la normativa vigente, a los proyectos que sean sostenibles, as\u00ed como promover redes sociales de moniotoreo en las que, aparte del control regulatorio de los \u00f3rganos p\u00fablicos, participe activamente la comunidad en celosa vigilancia de los compromisos ambientales que procuran el uso sostenible de recursos naturales a trav\u00e9s de Consejos de Cuencas\u201d, precis\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. El presidente Danilo Medina devolvi\u00f3 al Senado, sin promulgar, y observ\u00f3 en su totalidad la Ley que crea el Parque Nacional Loma Miranda, por entender que viola varios art\u00edculos de la Constituci\u00f3n, y que conllevar\u00eda el desconocimiento de compromisos internacionales asumidos por el Estado dominicano en materia de protecci\u00f3n de inversiones. En una carta a la presidenta del Senado, Cristina Lizardo, que fue le\u00edda por el vocero de la Presidencia, Roberto Rodr\u00edguez Marchena, en rueda de prensa en el Sal\u00f3n Orlando Mart\u00ednez del Palacio Nacional, el mandatario cita las razones que lo llevaron a observar la referida ley. El Jefe del Estado argument\u00f3 que la creaci\u00f3n del Parque Nacional Loma Miranda en un \u00e1rea que las autoridades competentes tienen identificada como de gran potencial minero (art\u00edculos 1 y 2), es contraria al mandato constitucional de aprovechamiento de los recursos naturales. De igual manera, plantea que en la legislaci\u00f3n observada se establece como Parque Nacional un \u00e1rea sobre la que existe un contrato de concesi\u00f3n minera consentido por el Estado dominicano, y advierte sobre las consecuencias que traer\u00eda su extinci\u00f3n, y c\u00f3mo afectar\u00eda la seguridad jur\u00eddica y el clima futuro de inversi\u00f3n en la Rep\u00fablica Dominicana. \u201cLa aprobaci\u00f3n fue una acci\u00f3n legislativa extempor\u00e1nea, debido a que ha sido la voluntad del constituyente de 2010, que lo relativo al uso eficiente y sostenible de los recursos naturales de la naci\u00f3n, se haga en el marco del Plan de Ordenamiento Territorial, que mediante ley debe expedir ese poder del Estado\u201d, refiere en la misiva.<\/p>\n","protected":false},"author":12,"featured_media":7972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-7971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=7971"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7971\/revisions"}],"predecessor-version":[{"id":7973,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/7971\/revisions\/7973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/7972"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=7971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=7971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=7971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}