{"id":79831,"date":"2020-11-26T09:07:39","date_gmt":"2020-11-26T13:07:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=79831"},"modified":"2020-11-26T09:07:43","modified_gmt":"2020-11-26T13:07:43","slug":"a-166-anos-del-merengue-nuevos-exponentes-batallan-junto-con-los-veteranos-para-mantenerlo-vigente","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/a-166-anos-del-merengue-nuevos-exponentes-batallan-junto-con-los-veteranos-para-mantenerlo-vigente\/","title":{"rendered":"A 166 a\u00f1os del merengue: Nuevos exponentes batallan junto con los veteranos para mantenerlo vigente"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"298\" height=\"222\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/11\/esdr.jpg\" alt=\"\" class=\"wp-image-79832\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>E<\/strong>l merengue ha experimenta\u00addo varios proce\u00adsos en sus 166 a\u00f1os de vida. Sus protagonistas han lle\u00advado el ritmo por una gran transformaci\u00f3n tanto en su estructura musical como en la manera de presentarlo al p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin dudas, en el siglo XX se registra el epicentro de su pegada, pero en los 20 a\u00f1os que lleva el siglo XXI una mezcla de veteranos y j\u00f3venes m\u00fasicos y cantan\u00adtes mantienen su vigencia contra el viento y la marea que en los \u00faltimos a\u00f1os ha desatado la m\u00fasica urbana desde el mismo centro del Caribe, un basti\u00f3n tradicio\u00adnal de la m\u00fasica tropical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los nuevos tiempos del presente siglo trajeron va\u00adriantes y fusiones que son cimentadas en lo que se denomina \u201cmerengue de calle\u201d o \u201cmerengue de mambo\u201d, teniendo como representante a Omega, El Sujeto, Juliana y Al\u00e1 Jaz\u00e1.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la par, el merengue m\u00e1s tradicional ha sido re\u00adnovado por j\u00f3venes como Manny Cruz, Rafely Rosa\u00adrio, Le\u00f3n Yamil (Be Crazy) y Gabriel, as\u00ed como la m\u00e1s joven de todas: Steffany Constanza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Omega viene marcando desde 2006 una tendencia natural dentro del g\u00e9nero, aunque su estilo mantie\u00adne divididos a los expertos sobre si en realidad su pro\u00adpuesta puede denominarse merengue. El gran p\u00fablico parece aceptarlo como tal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al\u00e1 Jaz\u00e1<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otro impulsor de estos tiempos es Al\u00e1 Jaz\u00e1, nativo de Jarabacoa, quien ha lo\u00adgrado un mayor nicho no solo en la juventud, sino lo\u00adgrando una diversidad de p\u00fablico. La pandemia fren\u00f3 el empuje que ven\u00eda regis\u00adtrando desde el 2019 con merengues como \u201cSi no me amas\u201d y \u201cNadie se meta\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;En el caso de Gabriel Pa\u00adg\u00e1n, \u00e9l ha apostado al me\u00adrengue fusionado, buscan\u00addo conectar con el p\u00fablico joven.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manny Cruz es una cara actual de nuestra m\u00fasica. Con una pegada extraordi\u00adnaria, ha contado con el fa\u00advor del p\u00fablico, logrando una conexi\u00f3n como hac\u00eda tiempo no se observaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Merengues como \u201cSa\u00adbes enamorarme\u201d, \u201cBailan\u00addo contigo\u201d , entre otros, han puesto la atenci\u00f3n sobre Manny en su faceta meren\u00adguera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Por igual, Steffany Cons\u00adtanza ha apostado al me\u00adrengue tradicional y se le ha escuchado con temas como \u201cDestino o casualidad\u201d, junto al veterano Fernando Villalo\u00adna, o su m\u00e1s reciente \u201cElla di\u00adce\u201d, a d\u00fao con Omega.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>De frente a urbanos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos j\u00f3venes merengue\u00adros batallan en medio del vendaval urbano. El meren\u00adgue, al igual que otros rit\u00admos tropicales, se ha man\u00adtenido en segundo plano. Ya no representa, como en el siglo pasado, a la mayo\u00adr\u00eda de la juventud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, para el maestro Dioni Fern\u00e1ndez, pianista y arreglista mu\u00adsical de grandes \u00e9xitos de merengue, nuestra m\u00fasica se ha quedado impregna\u00adda en todas las fusiones que se observan en las expresio\u00adnes de los ritmos tropicales &nbsp;que consume la juventud hoy d\u00eda. En esta actual eta\u00adpa, el ritmo dominicano se mantiene vigente gracias a estos j\u00f3venes y a un pu\u00f1ado de sus m\u00e1s veteranos prota\u00adgonistas del siglo pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Activos que conforma\u00adron la \u00e9poca de oro siguen gravitando hoy d\u00eda y sus nombres est\u00e1n ah\u00ed: Johnny Ventura, Juan Luis Guerra, Wilfrido Vargas, Milly Que\u00adzada, los Hermanos Rosa\u00adrio, To\u00f1o Rosario, Miriam Cruz, Sergio Vargas, Fer\u00adnando Villalona, Eddy He\u00adrrera, Alex Bueno, Ram\u00f3n Orlando, Jos\u00e9 Virgilio Pe\u00f1a Suazo, Kinito M\u00e9ndez, Po\u00adchy Familia&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ellos a\u00fan cargan en sus hombros al ritmo local y han elevado la bandera de la m\u00fasica dominicana por el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong>HISTORIA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Etapas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su primera fase fue sacado del campo a gran\u00addes salones de la ciudad, y vivi\u00f3 su primera transfor\u00admaci\u00f3n musical de ser una m\u00e9trica interpretada de guitarra, g\u00fcira, tambora o acorde\u00f3n a ser ejecuta\u00addo por grandes orquestas y experimentar una modi\u00adficaci\u00f3n en su base r\u00edtmi\u00adca y en su presentaci\u00f3n or\u00adquestar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Momentos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego llegaron las fu\u00adsiones con otros ritmos, las coreograf\u00edas, una pre\u00adsentaci\u00f3n orquestal con menos m\u00fasicos y otros conceptos, los que conti\u00adn\u00faan al d\u00eda de hoy como una modalidad del meren\u00adgue. Despu\u00e9s de ese tra\u00adyecto el ritmo dominica\u00adno vivi\u00f3 tambi\u00e9n su \u00e9poca de oro en los a\u00f1os 70, 80 y mediado de los 90.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El merengue ha experimenta\u00addo varios proce\u00adsos en sus 166 a\u00f1os de vida. Sus protagonistas han lle\u00advado el ritmo por una gran transformaci\u00f3n tanto en su estructura musical como en la manera de presentarlo al p\u00fablico. Sin dudas, en el siglo XX se registra el epicentro de su pegada, pero en los 20 a\u00f1os que lleva el siglo XXI una mezcla de veteranos y j\u00f3venes m\u00fasicos y cantan\u00adtes mantienen su vigencia contra el viento y la marea que en los \u00faltimos a\u00f1os ha desatado la m\u00fasica urbana desde el mismo centro del Caribe, un basti\u00f3n tradicio\u00adnal de la m\u00fasica tropical. Los nuevos tiempos del presente siglo trajeron va\u00adriantes y fusiones que son cimentadas en lo que se denomina \u201cmerengue de calle\u201d o \u201cmerengue de mambo\u201d, teniendo como representante a Omega, El Sujeto, Juliana y Al\u00e1 Jaz\u00e1. A la par, el merengue m\u00e1s tradicional ha sido re\u00adnovado por j\u00f3venes como Manny Cruz, Rafely Rosa\u00adrio, Le\u00f3n Yamil (Be Crazy) y Gabriel, as\u00ed como la m\u00e1s joven de todas: Steffany Constanza. Omega viene marcando desde 2006 una tendencia natural dentro del g\u00e9nero, aunque su estilo mantie\u00adne divididos a los expertos sobre si en realidad su pro\u00adpuesta puede denominarse merengue. El gran p\u00fablico parece aceptarlo como tal. Al\u00e1 Jaz\u00e1 Otro impulsor de estos tiempos es Al\u00e1 Jaz\u00e1, nativo de Jarabacoa, quien ha lo\u00adgrado un mayor nicho no solo en la juventud, sino lo\u00adgrando una diversidad de p\u00fablico. La pandemia fren\u00f3 el empuje que ven\u00eda regis\u00adtrando desde el 2019 con merengues como \u201cSi no me amas\u201d y \u201cNadie se meta\u201d. &nbsp;En el caso de Gabriel Pa\u00adg\u00e1n, \u00e9l ha apostado al me\u00adrengue fusionado, buscan\u00addo conectar con el p\u00fablico joven. Manny Cruz es una cara actual de nuestra m\u00fasica. Con una pegada extraordi\u00adnaria, ha contado con el fa\u00advor del p\u00fablico, logrando una conexi\u00f3n como hac\u00eda tiempo no se observaba. Merengues como \u201cSa\u00adbes enamorarme\u201d, \u201cBailan\u00addo contigo\u201d , entre otros, han puesto la atenci\u00f3n sobre Manny en su faceta meren\u00adguera. &nbsp;Por igual, Steffany Cons\u00adtanza ha apostado al me\u00adrengue tradicional y se le ha escuchado con temas como \u201cDestino o casualidad\u201d, junto al veterano Fernando Villalo\u00adna, o su m\u00e1s reciente \u201cElla di\u00adce\u201d, a d\u00fao con Omega. De frente a urbanos Estos j\u00f3venes merengue\u00adros batallan en medio del vendaval urbano. El meren\u00adgue, al igual que otros rit\u00admos tropicales, se ha man\u00adtenido en segundo plano. Ya no representa, como en el siglo pasado, a la mayo\u00adr\u00eda de la juventud. Sin embargo, para el maestro Dioni Fern\u00e1ndez, pianista y arreglista mu\u00adsical de grandes \u00e9xitos de merengue, nuestra m\u00fasica se ha quedado impregna\u00adda en todas las fusiones que se observan en las expresio\u00adnes de los ritmos tropicales &nbsp;que consume la juventud hoy d\u00eda. En esta actual eta\u00adpa, el ritmo dominicano se mantiene vigente gracias a estos j\u00f3venes y a un pu\u00f1ado de sus m\u00e1s veteranos prota\u00adgonistas del siglo pasado. Activos que conforma\u00adron la \u00e9poca de oro siguen gravitando hoy d\u00eda y sus nombres est\u00e1n ah\u00ed: Johnny Ventura, Juan Luis Guerra, Wilfrido Vargas, Milly Que\u00adzada, los Hermanos Rosa\u00adrio, To\u00f1o Rosario, Miriam Cruz, Sergio Vargas, Fer\u00adnando Villalona, Eddy He\u00adrrera, Alex Bueno, Ram\u00f3n Orlando, Jos\u00e9 Virgilio Pe\u00f1a Suazo, Kinito M\u00e9ndez, Po\u00adchy Familia&#8230; Ellos a\u00fan cargan en sus hombros al ritmo local y han elevado la bandera de la m\u00fasica dominicana por el mundo. &nbsp;HISTORIA Etapas. En su primera fase fue sacado del campo a gran\u00addes salones de la ciudad, y vivi\u00f3 su primera transfor\u00admaci\u00f3n musical de ser una m\u00e9trica interpretada de guitarra, g\u00fcira, tambora o acorde\u00f3n a ser ejecuta\u00addo por grandes orquestas y experimentar una modi\u00adficaci\u00f3n en su base r\u00edtmi\u00adca y en su presentaci\u00f3n or\u00adquestar. Momentos. Luego llegaron las fu\u00adsiones con otros ritmos, las coreograf\u00edas, una pre\u00adsentaci\u00f3n orquestal con menos m\u00fasicos y otros conceptos, los que conti\u00adn\u00faan al d\u00eda de hoy como una modalidad del meren\u00adgue. Despu\u00e9s de ese tra\u00adyecto el ritmo dominica\u00adno vivi\u00f3 tambi\u00e9n su \u00e9poca de oro en los a\u00f1os 70, 80 y mediado de los 90.<\/p>\n","protected":false},"author":9,"featured_media":79832,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-79831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=79831"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79831\/revisions"}],"predecessor-version":[{"id":79833,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/79831\/revisions\/79833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/79832"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=79831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=79831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=79831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}