{"id":80071,"date":"2020-12-24T09:49:03","date_gmt":"2020-12-24T13:49:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80071"},"modified":"2020-12-24T09:49:07","modified_gmt":"2020-12-24T13:49:07","slug":"el-licey-se-despide-con-un-triunfo-frente-a-las-estrellas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-licey-se-despide-con-un-triunfo-frente-a-las-estrellas\/","title":{"rendered":"El Licey se despide con un triunfo frente a las Estrellas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"291\" height=\"188\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/asde.jpg\" alt=\"\" class=\"wp-image-80072\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Vladimir Guti\u00e9rrez lanz\u00f3 cinco entradas sin hit y &nbsp;Dennicher Carrasco bate\u00f3 triple y doble para que el Licey se impusiera 6 vueltas por una a las Estrellas en el partido que cerr\u00f3 la Serie Regular efectuado en el Estadio Quisqueya Juan Marichal.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guti\u00e9rrez se despide con lo que fue su mejor presentaci\u00f3n de la campa\u00f1a, tras lanzar cinco actos, concedi\u00f3 dos boletos y abanic\u00f3 a 8, encontr\u00f3 un gran rival en Andy Otero, quien tambi\u00e9n permaneci\u00f3 5.0 entradas en el box, permiti\u00f3 cinco hits y ponch\u00f3 a nueve.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carrasco fue el mejor a la ofensiva por los azules con sus dos extrabases, produjo un par de vueltas, en tanto que Erick Mej\u00eda y Anderson Tejeda tambi\u00e9n remolcaron dos carreras cada uno.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Tigres, que&nbsp; el pasado lunes fueron descalificados de participar en la postemporada se despidieron con dos triunfos seguidos, ante las Aguilas el martes y contra las Estrellas anoche.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un rally de cinco vueltas marcadas por los Tigres en el s\u00e9ptimo episodio asegur\u00f3 la victoria de este conjunto sobre los Paquidermos.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vladimir Guti\u00e9rrez lanz\u00f3 cinco entradas sin hit y &nbsp;Dennicher Carrasco bate\u00f3 triple y doble para que el Licey se impusiera 6 vueltas por una a las Estrellas en el partido que cerr\u00f3 la Serie Regular efectuado en el Estadio Quisqueya Juan Marichal.&nbsp; Guti\u00e9rrez se despide con lo que fue su mejor presentaci\u00f3n de la campa\u00f1a, tras lanzar cinco actos, concedi\u00f3 dos boletos y abanic\u00f3 a 8, encontr\u00f3 un gran rival en Andy Otero, quien tambi\u00e9n permaneci\u00f3 5.0 entradas en el box, permiti\u00f3 cinco hits y ponch\u00f3 a nueve.&nbsp; Carrasco fue el mejor a la ofensiva por los azules con sus dos extrabases, produjo un par de vueltas, en tanto que Erick Mej\u00eda y Anderson Tejeda tambi\u00e9n remolcaron dos carreras cada uno.&nbsp; Los Tigres, que&nbsp; el pasado lunes fueron descalificados de participar en la postemporada se despidieron con dos triunfos seguidos, ante las Aguilas el martes y contra las Estrellas anoche.&nbsp; Un rally de cinco vueltas marcadas por los Tigres en el s\u00e9ptimo episodio asegur\u00f3 la victoria de este conjunto sobre los Paquidermos.&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":80072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-80071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80071"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80071\/revisions"}],"predecessor-version":[{"id":80073,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80071\/revisions\/80073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80072"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}