{"id":80119,"date":"2020-12-27T09:27:13","date_gmt":"2020-12-27T13:27:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80119"},"modified":"2020-12-27T09:27:17","modified_gmt":"2020-12-27T13:27:17","slug":"gobierno-inicia-esta-noche-la-serie-de-conciertos-virtuales-navidad-en-casa","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/gobierno-inicia-esta-noche-la-serie-de-conciertos-virtuales-navidad-en-casa\/","title":{"rendered":"Gobierno inicia esta noche la serie de conciertos virtuales \u201cNavidad en Casa\u201d"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"294\" height=\"198\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/asaas.jpg\" alt=\"\" class=\"wp-image-80120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/asaas.jpg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/asaas-75x52.jpg 75w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de llevar alegr\u00eda y m\u00fasica en estas fiestas navide\u00f1as a todos los hogares dominicanos, la Presidencia de la Rep\u00fablica iniciar\u00e1 esta noche la serie de conciertos virtuales \u201cNavidad en Casa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de las 9:00 de la noche, la familia dominicana podr\u00e1 disfrutar gratuitamente de presentaciones art\u00edsticas con los varios exponentes de merengue, bachata, salsa, m\u00fasica urbana y balada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Silvio Mora, Luis Miguel del Amargue, Fefita la Grande, Eddy Herrera, los Hermanos Rosarios, Mar\u00eda D\u00edaz, Rubby P\u00e9rez, Pochy Familia, Pe\u00f1a Suazo, Miriam Cruz, Techy Fatule, Mozart La Para, La Materialista, Chiquito Team Band, Sexappeal, Bonny y Richie Cepeda, Amarfis, Sergio Vargas, Manny Cruz y Fernando Villalona conforman la cartelera art\u00edstica que durante cuatro dias los dominicanos podr\u00e1n disfrutar desde cualqueir parte del mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indica una nota de prensa que la iniciativa forma parte las acciones del presidente Luis Abinader en su compromiso de apoyar al sector art\u00edstico del que dependen cientos de familias, y que ha sido muy afectado durante los \u00faltimos 10 meses por los efectos de la pandemia del Covid-19 y, a su vez, regala a la ciudadan\u00eda opciones para disfrutar de sano entretenimiento en estas festividades navide\u00f1as mientras se mantiene en sus hogares respetando las disposiciones del toque de queda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los conciertos Lives \u201cNavidad en Casa\u201d, realizados bajo la coordinaci\u00f3n del Gabinete de Pol\u00edtica Social y su titular, Tony Pe\u00f1a, y el Asesor del presidente en materia art\u00edstica, Engelbert Landolfi; ser\u00e1n transmitidos cada noche a traves de las cuentas oficiales de redes sociales de la casa de gobierno @PresidenciaRD y @ComunicacionDO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de llevar alegr\u00eda y m\u00fasica en estas fiestas navide\u00f1as a todos los hogares dominicanos, la Presidencia de la Rep\u00fablica iniciar\u00e1 esta noche la serie de conciertos virtuales \u201cNavidad en Casa\u201d. A partir de las 9:00 de la noche, la familia dominicana podr\u00e1 disfrutar gratuitamente de presentaciones art\u00edsticas con los varios exponentes de merengue, bachata, salsa, m\u00fasica urbana y balada. Silvio Mora, Luis Miguel del Amargue, Fefita la Grande, Eddy Herrera, los Hermanos Rosarios, Mar\u00eda D\u00edaz, Rubby P\u00e9rez, Pochy Familia, Pe\u00f1a Suazo, Miriam Cruz, Techy Fatule, Mozart La Para, La Materialista, Chiquito Team Band, Sexappeal, Bonny y Richie Cepeda, Amarfis, Sergio Vargas, Manny Cruz y Fernando Villalona conforman la cartelera art\u00edstica que durante cuatro dias los dominicanos podr\u00e1n disfrutar desde cualqueir parte del mundo. Indica una nota de prensa que la iniciativa forma parte las acciones del presidente Luis Abinader en su compromiso de apoyar al sector art\u00edstico del que dependen cientos de familias, y que ha sido muy afectado durante los \u00faltimos 10 meses por los efectos de la pandemia del Covid-19 y, a su vez, regala a la ciudadan\u00eda opciones para disfrutar de sano entretenimiento en estas festividades navide\u00f1as mientras se mantiene en sus hogares respetando las disposiciones del toque de queda. Los conciertos Lives \u201cNavidad en Casa\u201d, realizados bajo la coordinaci\u00f3n del Gabinete de Pol\u00edtica Social y su titular, Tony Pe\u00f1a, y el Asesor del presidente en materia art\u00edstica, Engelbert Landolfi; ser\u00e1n transmitidos cada noche a traves de las cuentas oficiales de redes sociales de la casa de gobierno @PresidenciaRD y @ComunicacionDO.<\/p>\n","protected":false},"author":9,"featured_media":80120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-80119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80119"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80119\/revisions"}],"predecessor-version":[{"id":80121,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80119\/revisions\/80121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80120"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}