{"id":80139,"date":"2020-12-29T11:14:53","date_gmt":"2020-12-29T15:14:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80139"},"modified":"2020-12-29T11:14:57","modified_gmt":"2020-12-29T15:14:57","slug":"varios-muertos-en-accidente-de-transito-en-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/varios-muertos-en-accidente-de-transito-en-puerto-plata\/","title":{"rendered":"Varios muertos en accidente de tr\u00e1nsito en Puerto Plata"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/202012290959281.jpeg\" alt=\"\" class=\"wp-image-80140\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/202012290959281.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2020\/12\/202012290959281-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La madrugada de este martes&nbsp;<strong>fallecieron tres personas en un accidente de tr\u00e1nsito en la carretera de Navarrete<\/strong>&nbsp;que lleva a Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los fallecidos son Domingo Henr\u00edquez, de 50 a\u00f1os; Reynaldo Mercedes y H\u00e9ctor Mendoza. Mientras que los heridos, uno de ellos en estado delicado, son Juan Garc\u00eda, de 50 a\u00f1os de edad; y Julio C\u00e9sar Taveras Rodr\u00edguez, de 28 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El accidente se produjo en el sector de Los Tejeda de Maim\u00f3n, entre un cami\u00f3n Mack de la empresa licorera Brugal y un cami\u00f3n marca Mitsubishi de la empresa Productos Salom\u00e9, resultando muerto el chofer del cami\u00f3n de Brugal y dos ocupantes del cami\u00f3n de Salom\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El hecho ocurri\u00f3 alrededor de la 5:15 de la madrugada<\/strong>&nbsp;y de inmediato al lugar se trasladaron brigadas de la Defensa Civil, de Puerto Plata y Maim\u00f3n, de los Bomberos de ambas localidades, rescate \u00c1mbar, unidades de la Polic\u00eda Nacional, miembros de la unidad de Asistencia Vial y agentes de la Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Los heridos reciben atenciones en el Hospital Docente Ricardo Limardo de Puerto Plata.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tr\u00e1nsito se mostr\u00f3 congestionado en sentido sur-norte en el mencionado tramo de la avenida debido a que&nbsp;<strong>el accidente provoc\u00f3 el cierre del paso vehicular<\/strong>, seg\u00fan una publicaci\u00f3n realizada en Instagram por Jos\u00e9 Urtecho, quien comparte informaci\u00f3n de eventos de tr\u00e1nsito en Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las im\u00e1genes publicadas por Urtecho se muestran los restos de los veh\u00edculos destruidos rodeados por decenas de personas mientras que una ambulancia, unidades de seguridad vial del Ministerio de Obras P\u00fablicas y un cami\u00f3n de bomberos brindan asistencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Edgar Lantigua<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La madrugada de este martes&nbsp;fallecieron tres personas en un accidente de tr\u00e1nsito en la carretera de Navarrete&nbsp;que lleva a Puerto Plata. Los fallecidos son Domingo Henr\u00edquez, de 50 a\u00f1os; Reynaldo Mercedes y H\u00e9ctor Mendoza. Mientras que los heridos, uno de ellos en estado delicado, son Juan Garc\u00eda, de 50 a\u00f1os de edad; y Julio C\u00e9sar Taveras Rodr\u00edguez, de 28 a\u00f1os. El accidente se produjo en el sector de Los Tejeda de Maim\u00f3n, entre un cami\u00f3n Mack de la empresa licorera Brugal y un cami\u00f3n marca Mitsubishi de la empresa Productos Salom\u00e9, resultando muerto el chofer del cami\u00f3n de Brugal y dos ocupantes del cami\u00f3n de Salom\u00e9. El hecho ocurri\u00f3 alrededor de la 5:15 de la madrugada&nbsp;y de inmediato al lugar se trasladaron brigadas de la Defensa Civil, de Puerto Plata y Maim\u00f3n, de los Bomberos de ambas localidades, rescate \u00c1mbar, unidades de la Polic\u00eda Nacional, miembros de la unidad de Asistencia Vial y agentes de la Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre. Los heridos reciben atenciones en el Hospital Docente Ricardo Limardo de Puerto Plata. El tr\u00e1nsito se mostr\u00f3 congestionado en sentido sur-norte en el mencionado tramo de la avenida debido a que&nbsp;el accidente provoc\u00f3 el cierre del paso vehicular, seg\u00fan una publicaci\u00f3n realizada en Instagram por Jos\u00e9 Urtecho, quien comparte informaci\u00f3n de eventos de tr\u00e1nsito en Rep\u00fablica Dominicana. En las im\u00e1genes publicadas por Urtecho se muestran los restos de los veh\u00edculos destruidos rodeados por decenas de personas mientras que una ambulancia, unidades de seguridad vial del Ministerio de Obras P\u00fablicas y un cami\u00f3n de bomberos brindan asistencia. Edgar Lantigua<\/p>\n","protected":false},"author":9,"featured_media":80140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-80139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80139"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80139\/revisions"}],"predecessor-version":[{"id":80141,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80139\/revisions\/80141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80140"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}