{"id":8037,"date":"2014-09-03T18:54:47","date_gmt":"2014-09-03T22:54:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8037"},"modified":"2014-09-03T18:57:15","modified_gmt":"2014-09-03T22:57:15","slug":"aquilina-medina-asegura-gestion-de-ilana-neumann-esta-por-debajo-de-las-expectativas-de-la-poblacion-de-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/aquilina-medina-asegura-gestion-de-ilana-neumann-esta-por-debajo-de-las-expectativas-de-la-poblacion-de-sosua\/","title":{"rendered":"Aquilina Medina asegura gesti\u00f3n de Ilana Neumann est\u00e1 por debajo de las expectativas de la poblaci\u00f3n de Sos\u00faa"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/aquilina-medina.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8038 aligncenter\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/aquilina-medina.jpg\" alt=\"aquilina medina\" width=\"555\" height=\"333\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/aquilina-medina.jpg 555w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/aquilina-medina-300x180.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/aquilina-medina-500x300.jpg 500w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/a><br \/>\nSos\u00faa, Por Milton Camacho.- Una importante dirigente del Partido de la Liberaci\u00f3n Dominicana, PLD, en este municipio tur\u00edstico y actual Regidora, dijo hoy que la gesti\u00f3n de la Alcaldesa Ilana Neumann, est\u00e1 muy por debajo de las expectativas de la poblaci\u00f3n.<!--more--><\/p>\n<p>La Lic. Aquilina Medina sostuvo que la actual Alcaldesa se ha limitado a algunas \u00e1reas del quehacer municipal, pero se ha olvidado de los problemas puntuales del municipio y por ende de su gente.<\/p>\n<p>Dijo que la Alcaldesa Ilana Neumann ha comprometido el desarrollo de Sos\u00faa, al mantener una s\u00faper abultada n\u00f3mina que se traga el presupuesto municipal.<\/p>\n<p>Aquilina Medina, quien aspira a Alcaldesa de Sos\u00faa, dijo que el Concejo de Regidores ha mantenido silencio ante los desmanes de la actual Alcaldesa, por las limitaciones de la ley 176-07 y en un gesto para procurar la gobernabilidad, pero dijo que no seguir\u00e1 callando el mal manejo que se le est\u00e1 dando a los recursos existente en el ayuntamiento de Sos\u00faa.<\/p>\n<p>La Concejal revel\u00f3 que hay obras prioritarias que fueron aprobadas por el Concejo de Regidores y el ayuntamiento no las inicia porque no dispone de los recursos suficientes ya que estos no han sido invertidos de la forma correcta.<\/p>\n<p>\u201cQuiero aclarar que no acuso a la Alcaldesa de sustraer los fondos municipales, sino de mal invertirlos, cambiando las prioridades municipales\u201d, explic\u00f3 Medina.<\/p>\n<p>Agrega la aspirante a dirigir el ayuntamiento de Sos\u00faa, que la actual Alcaldesa no ha sido capaz de aplicar una correcta pol\u00edtica fiscal, por lo cual las recaudaciones se han desplomado creando un d\u00e9ficit en las proyecciones recaudadoras del ayuntamiento de Sos\u00faa.<\/p>\n<p>\u201cA partir de ahora estaremos atentos al desempe\u00f1o de la Alcald\u00eda Municipal, para defender los sagrados intereses del pueblo de Sos\u00faa\u201d, enfatiz\u00f3 la pre-candidata a Alcaldesa de Sos\u00faa Lic. Aquilina Medina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa, Por Milton Camacho.- Una importante dirigente del Partido de la Liberaci\u00f3n Dominicana, PLD, en este municipio tur\u00edstico y actual Regidora, dijo hoy que la gesti\u00f3n de la Alcaldesa Ilana Neumann, est\u00e1 muy por debajo de las expectativas de la poblaci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":8038,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-8037","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8037"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8037\/revisions"}],"predecessor-version":[{"id":8039,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8037\/revisions\/8039"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8038"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}