{"id":80379,"date":"2021-01-22T08:57:49","date_gmt":"2021-01-22T12:57:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80379"},"modified":"2021-01-22T08:57:53","modified_gmt":"2021-01-22T12:57:53","slug":"pasajeros-que-entren-a-eua-seran-sometidos-a-cuarentena-obligatoria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pasajeros-que-entren-a-eua-seran-sometidos-a-cuarentena-obligatoria\/","title":{"rendered":"Pasajeros que entren a EUA ser\u00e1n sometidos a cuarentena obligatoria"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/01\/pasajeros-que-entren-a-eua-seran-sometidos-a-cuarentena-obligatoria.jpeg\" alt=\"\" class=\"wp-image-80380\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/01\/pasajeros-que-entren-a-eua-seran-sometidos-a-cuarentena-obligatoria.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/01\/pasajeros-que-entren-a-eua-seran-sometidos-a-cuarentena-obligatoria-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de Estados Unidos, Joe Biden, prome\u00adti\u00f3 ayer jueves una movili\u00adzaci\u00f3n como \u201cen tiempos de guerra\u201d para hacer fren\u00adte al covid-19, anuncian\u00addo un endurecimiento de las normas sobre el uso de mascarilla y una cuarente\u00adna obligatoria para los via\u00adjeros que entren al pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario dem\u00f3crata dedic\u00f3 su primera jornada de gobierno a su prioridad m\u00e1s urgente, la lucha contra la pandemia, en el pa\u00eds con m\u00e1s muertos por el covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al firmar una serie de de\u00adcretos, Biden anunci\u00f3 que \u201caquellos que viajen a Esta\u00addos Unidos desde otro pa\u00eds deber\u00e1n realizarse una prueba antes de subirse al avi\u00f3n y realizar una cua\u00adrentena cuando lleguen\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La exigencia de una prue\u00adba ya hab\u00eda sido ordenada por el gobierno anterior, pero el aislamiento era s\u00f3\u00adlo una recomendaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nuevas cepas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Biden explic\u00f3 que esta medida se debe a las nue\u00advas cepas del virus detec\u00adtadas en otros pa\u00edses, en un momento en que en Estados Unidos hay m\u00e1s de 400.000 muertos por la pandemia, una cifra que su\u00adpera la cantidad de solda\u00addos estadounidenses falle\u00adcidos durante la Segunda Guerra Mundial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario afirm\u00f3 ade\u00adm\u00e1s que va a asegurarse de que los cient\u00edficos y los ex\u00adpertos puedan trabajar li\u00adbres de \u201ccualquier interfe\u00adrencia pol\u00edtica y que puedan tomar sus decisiones ba\u00adsados estrictamente en la ciencia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva administraci\u00f3n estadounidense agradeci\u00f3 ayer jueves a la Organiza\u00adci\u00f3n Mundial de la Salud (OMS) su papel de lideraz\u00adgo en la lucha contra la pan\u00addemia y le asegur\u00f3 su apoyo financiero, un giro de 180 grados respecto a la estrate\u00adgia mantenida por el expre\u00adsidente Donald Trump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos, que anun\u00adci\u00f3 su regreso a la OMS el mi\u00e9rcoles, \u201ctiene la inten\u00adci\u00f3n de cumplir con sus obligaciones financieras con la organizaci\u00f3n\u201d, ase\u00adgur\u00f3 el inmun\u00f3logo An\u00adthony Fauci en una reuni\u00f3n del consejo ejecutivo de la agencia de la ONU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<strong>PUNTOS.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Antes del viaje<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los viajeros del exterior deber\u00e1n presentar una prueba negativa de CO\u00adVID-19 antes de partir hacia Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Octubre<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El decreto de Biden con\u00advierte el uso de la mas\u00adcarilla en un mandato federal, lo que deja poco margen a los pasajeros tentados a discutir sobre sus derechos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Estados Unidos, Joe Biden, prome\u00adti\u00f3 ayer jueves una movili\u00adzaci\u00f3n como \u201cen tiempos de guerra\u201d para hacer fren\u00adte al covid-19, anuncian\u00addo un endurecimiento de las normas sobre el uso de mascarilla y una cuarente\u00adna obligatoria para los via\u00adjeros que entren al pa\u00eds. El mandatario dem\u00f3crata dedic\u00f3 su primera jornada de gobierno a su prioridad m\u00e1s urgente, la lucha contra la pandemia, en el pa\u00eds con m\u00e1s muertos por el covid-19. Al firmar una serie de de\u00adcretos, Biden anunci\u00f3 que \u201caquellos que viajen a Esta\u00addos Unidos desde otro pa\u00eds deber\u00e1n realizarse una prueba antes de subirse al avi\u00f3n y realizar una cua\u00adrentena cuando lleguen\u201d. La exigencia de una prue\u00adba ya hab\u00eda sido ordenada por el gobierno anterior, pero el aislamiento era s\u00f3\u00adlo una recomendaci\u00f3n. Nuevas cepas Biden explic\u00f3 que esta medida se debe a las nue\u00advas cepas del virus detec\u00adtadas en otros pa\u00edses, en un momento en que en Estados Unidos hay m\u00e1s de 400.000 muertos por la pandemia, una cifra que su\u00adpera la cantidad de solda\u00addos estadounidenses falle\u00adcidos durante la Segunda Guerra Mundial. El mandatario afirm\u00f3 ade\u00adm\u00e1s que va a asegurarse de que los cient\u00edficos y los ex\u00adpertos puedan trabajar li\u00adbres de \u201ccualquier interfe\u00adrencia pol\u00edtica y que puedan tomar sus decisiones ba\u00adsados estrictamente en la ciencia\u201d. La nueva administraci\u00f3n estadounidense agradeci\u00f3 ayer jueves a la Organiza\u00adci\u00f3n Mundial de la Salud (OMS) su papel de lideraz\u00adgo en la lucha contra la pan\u00addemia y le asegur\u00f3 su apoyo financiero, un giro de 180 grados respecto a la estrate\u00adgia mantenida por el expre\u00adsidente Donald Trump. Estados Unidos, que anun\u00adci\u00f3 su regreso a la OMS el mi\u00e9rcoles, \u201ctiene la inten\u00adci\u00f3n de cumplir con sus obligaciones financieras con la organizaci\u00f3n\u201d, ase\u00adgur\u00f3 el inmun\u00f3logo An\u00adthony Fauci en una reuni\u00f3n del consejo ejecutivo de la agencia de la ONU. &nbsp;PUNTOS. Antes del viaje Los viajeros del exterior deber\u00e1n presentar una prueba negativa de CO\u00adVID-19 antes de partir hacia Estados Unidos. Octubre El decreto de Biden con\u00advierte el uso de la mas\u00adcarilla en un mandato federal, lo que deja poco margen a los pasajeros tentados a discutir sobre sus derechos.<\/p>\n","protected":false},"author":9,"featured_media":80380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-80379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80379"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80379\/revisions"}],"predecessor-version":[{"id":80381,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80379\/revisions\/80381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80380"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}