{"id":80461,"date":"2021-02-03T09:03:01","date_gmt":"2021-02-03T13:03:01","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80461"},"modified":"2021-02-03T09:03:05","modified_gmt":"2021-02-03T13:03:05","slug":"argenis-a-rendir-cuentas-por-el-crimen-de-yunior-ramirez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/argenis-a-rendir-cuentas-por-el-crimen-de-yunior-ramirez\/","title":{"rendered":"Argenis: A rendir cuentas por el crimen de Yunior Ram\u00edrez"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"328\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/02\/argenis-a-rendir-cuentas-por-el-crimen-de-yunior-ramirez.jpeg\" alt=\"\" class=\"wp-image-80462\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/02\/argenis-a-rendir-cuentas-por-el-crimen-de-yunior-ramirez.jpeg 328w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/02\/argenis-a-rendir-cuentas-por-el-crimen-de-yunior-ramirez-300x155.jpeg 300w\" sizes=\"auto, (max-width: 328px) 100vw, 328px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Argenis Contreras Gonz\u00e1lez, el principal acusado del asesinato del abogado y profesor universitario Yuniol Ram\u00edrez, continuar\u00e1 siendo interrogado hoy a las 11:00 de la ma\u00f1ana por fiscales de la Procuradur\u00eda General de la Rep\u00fablica, luego de cinco horas bajo investigaci\u00f3n ayer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contreras Gonz\u00e1lez fue repatriado desde Estados Unidos y lleg\u00f3 al aeropuerto Las Am\u00e9ricas a las 11:30 de la ma\u00f1ana, donde fue esperado por el titular de la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (Pepca), Wilson Camacho, quien oficializ\u00f3 el arresto y le notific\u00f3 los cargos criminales que pesan en su contra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico tiene bajo arresto al imputado en la c\u00e1rcel preventiva del Palacio de Justicia de Ciudad Nueva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plutarco J\u00e1quez, abogado de Contreras Gonz\u00e1lez, dijo que su defendido no es el principal imputado, y que en su momento pedir\u00e1 sean agregados nuevos nombres al expediente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsas personas que ya han sido incluidas en el expediente, el Ministerio P\u00fablico las va a ponderar, tambi\u00e9n que las personas que han sido excluidas sean reintegradas en el expediente\u201d, indic\u00f3 al salir del interrogatorio a su cliente en la Procuradur\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando \u00e9l se va del pa\u00eds es porque hay muchas personas conocidas, generales, coroneles, pol\u00edticos, estamos hablando de pesos pesados que a cualquiera le pueden arrancar la cabeza\u201d, dijo J\u00e1quez, abogado de Contreras Gonz\u00e1lez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El acusado hab\u00eda huido hacia Estados Unidos para&nbsp; evadir el proceso judicial que se le sigue por el secuestro y asesinato de Ram\u00edrez Ferreras, as\u00ed como por la comisi\u00f3n de supuestos actos de corrupci\u00f3n. Est\u00e1 se\u00f1alado de ser el autor material de la muerte del abogado y catedr\u00e1tico universitario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Interpol dict\u00f3 orden de captura en su contra, desde octubre de 2017 bajo el oficio n\u00famero 2017\/254847. En el asesinato de Ram\u00edrez fueron involucrados tambi\u00e9n la esposa de Contreras, Heydi Carolina Pe\u00f1a; Jos\u00e9 Mercado Blanco (El Grande), V\u00edctor Elisander Ravelo Campos (\u201cEl Herrero\u201d) y Jorge Luis Abreu Fabi\u00e1n (\u201cDJ y El Taxista\u201d), acusados de encubrir al autor y de intentar destruir pruebas sobre el caso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n al caso al principio fue acusado el exdirector de la Oficina Metropolitana de Servicios de Autobuses (OMSA), Manuel Rivas, y el coronel Faustino D\u00edaz, quien era el gerente financiero de esa entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>EN PUNTOS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pendiente.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;El pasado lunes, Camacho hab\u00eda declarado que no se hab\u00edan olvidado del caso que imputa a Contreras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que trabajaban \u201csin prisa, pero sin pausa\u201d en ese caso y en todos los que tienen relaci\u00f3n alguna al tema de corrupci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al ser preguntado sobre cu\u00e1l es la dificultad por la cual los Estados Unidos a\u00fan no han extraditado a Contreras, el titular de la Pepca pidi\u00f3 respetar las decisiones de las otras autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El arresto en E.U.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Contreras fue apresado en Estados Unidos el 21 de abril de 2018, mediante una orden de arresto obtenida en su contra por el ministerio p\u00fablico de Rep\u00fablica Dominicana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Argenis Contreras Gonz\u00e1lez, el principal acusado del asesinato del abogado y profesor universitario Yuniol Ram\u00edrez, continuar\u00e1 siendo interrogado hoy a las 11:00 de la ma\u00f1ana por fiscales de la Procuradur\u00eda General de la Rep\u00fablica, luego de cinco horas bajo investigaci\u00f3n ayer. Contreras Gonz\u00e1lez fue repatriado desde Estados Unidos y lleg\u00f3 al aeropuerto Las Am\u00e9ricas a las 11:30 de la ma\u00f1ana, donde fue esperado por el titular de la Procuradur\u00eda Especializada de Persecuci\u00f3n de la Corrupci\u00f3n Administrativa (Pepca), Wilson Camacho, quien oficializ\u00f3 el arresto y le notific\u00f3 los cargos criminales que pesan en su contra. El Ministerio P\u00fablico tiene bajo arresto al imputado en la c\u00e1rcel preventiva del Palacio de Justicia de Ciudad Nueva. Plutarco J\u00e1quez, abogado de Contreras Gonz\u00e1lez, dijo que su defendido no es el principal imputado, y que en su momento pedir\u00e1 sean agregados nuevos nombres al expediente. \u201cEsas personas que ya han sido incluidas en el expediente, el Ministerio P\u00fablico las va a ponderar, tambi\u00e9n que las personas que han sido excluidas sean reintegradas en el expediente\u201d, indic\u00f3 al salir del interrogatorio a su cliente en la Procuradur\u00eda. \u201cCuando \u00e9l se va del pa\u00eds es porque hay muchas personas conocidas, generales, coroneles, pol\u00edticos, estamos hablando de pesos pesados que a cualquiera le pueden arrancar la cabeza\u201d, dijo J\u00e1quez, abogado de Contreras Gonz\u00e1lez. El acusado hab\u00eda huido hacia Estados Unidos para&nbsp; evadir el proceso judicial que se le sigue por el secuestro y asesinato de Ram\u00edrez Ferreras, as\u00ed como por la comisi\u00f3n de supuestos actos de corrupci\u00f3n. Est\u00e1 se\u00f1alado de ser el autor material de la muerte del abogado y catedr\u00e1tico universitario. La Interpol dict\u00f3 orden de captura en su contra, desde octubre de 2017 bajo el oficio n\u00famero 2017\/254847. En el asesinato de Ram\u00edrez fueron involucrados tambi\u00e9n la esposa de Contreras, Heydi Carolina Pe\u00f1a; Jos\u00e9 Mercado Blanco (El Grande), V\u00edctor Elisander Ravelo Campos (\u201cEl Herrero\u201d) y Jorge Luis Abreu Fabi\u00e1n (\u201cDJ y El Taxista\u201d), acusados de encubrir al autor y de intentar destruir pruebas sobre el caso. Con relaci\u00f3n al caso al principio fue acusado el exdirector de la Oficina Metropolitana de Servicios de Autobuses (OMSA), Manuel Rivas, y el coronel Faustino D\u00edaz, quien era el gerente financiero de esa entidad. EN PUNTOS Pendiente. &nbsp;El pasado lunes, Camacho hab\u00eda declarado que no se hab\u00edan olvidado del caso que imputa a Contreras. Explic\u00f3 que trabajaban \u201csin prisa, pero sin pausa\u201d en ese caso y en todos los que tienen relaci\u00f3n alguna al tema de corrupci\u00f3n. Al ser preguntado sobre cu\u00e1l es la dificultad por la cual los Estados Unidos a\u00fan no han extraditado a Contreras, el titular de la Pepca pidi\u00f3 respetar las decisiones de las otras autoridades. El arresto en E.U. &nbsp;Contreras fue apresado en Estados Unidos el 21 de abril de 2018, mediante una orden de arresto obtenida en su contra por el ministerio p\u00fablico de Rep\u00fablica Dominicana.<\/p>\n","protected":false},"author":9,"featured_media":80462,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-80461","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80461"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80461\/revisions"}],"predecessor-version":[{"id":80463,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80461\/revisions\/80463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80462"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}