{"id":80473,"date":"2021-02-03T09:23:18","date_gmt":"2021-02-03T13:23:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80473"},"modified":"2021-02-03T09:23:21","modified_gmt":"2021-02-03T13:23:21","slug":"diego-jaar-y-el-piro-primeros-en-ir-a-la-final-de-dominicanas-got-talent","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/diego-jaar-y-el-piro-primeros-en-ir-a-la-final-de-dominicanas-got-talent\/","title":{"rendered":"Diego Jaar y \u201cEl Piro\u201d, primeros en ir a la final de Dominicana\u2019s Got Talent"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/02\/diego-y-el-piro-2_15686084_20210202152159.jpg\" alt=\"\" class=\"wp-image-80474\" width=\"286\" height=\"183\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/02\/diego-y-el-piro-2_15686084_20210202152159.jpg 546w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/02\/diego-y-el-piro-2_15686084_20210202152159-300x192.jpg 300w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un rapero activista y un cantautor so\u00f1ador son los dos finalistas del primer programa de la semifinal del programa de b\u00fasqueda de talentos Dominicana\u2019s Got Talent. Ellos se impusieron a otros actos interesantes para ganarse un espacio en la final. Diario Libre convers\u00f3 con ellos, que se mostraron muy felices por este paso en la competencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diego Jaar, que hab\u00eda obtenido el Golden Buzzer de Waddys J\u00e1quez, fue el m\u00e1s votado de la noche. El cantautor hizo gala de su dominio en el escenario, con una canci\u00f3n de su autor\u00eda que le vali\u00f3 los elogios del jurado. Con el piano como su instrumento, el int\u00e9rprete demostr\u00f3 que un lugar en la final ten\u00eda su nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conversaci\u00f3n con Diario Libre, el cantautor nacido en Puerto Rico se mostr\u00f3 agradecido por este momento en su carrera, el que tom\u00f3 como una prueba para saber si puede vivir de esto. \u201cNo quiero que pase el tiempo sin intentarlo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> \u201cYo dije si puedo gustar con mis canciones puedo hacer m\u00fasica en cualquier parte, esta es la confirmaci\u00f3n de que s\u00ed puedo\u201d, expres\u00f3 emocionado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confes\u00f3 adem\u00e1s que siempre ha vivido una especie de disyuntiva entre la profesi\u00f3n que le ha dejado ingresos y la pasi\u00f3n que siente por la m\u00fasica. \u201cYo ejerzo como productor audiovisual, pero toda la vida la he pasado en la m\u00fasica, dividiendo mi vida entre hacer canciones y trabajar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A \u00e9l lo acompa\u00f1ar\u00e1 el rapero \u201cEl Piro\u201d, \u00e9l se ha dado a conocer por su activismo en \u201cSomos Pueblo\u201d, una plataforma de cr\u00edtica social que se ha hecho muy popular en las redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con su rap social, Eduardo S\u00e1nchez Tolentino, conocido como \u201cEl Piro\u201d, se gan\u00f3 un lugar en la final del programa Dominicana\u2019s Got Talent. Sin embargo, aunque sorprendi\u00f3 a muchos que lo siguen m\u00e1s por sus an\u00e1lisis en la plataforma de cr\u00edtica social, lo cierto es que \u00e9l no es un improvisado en el g\u00e9nero urbano local. As\u00ed lo expres\u00f3 a Diario Libre durante una entrevista al d\u00eda siguiente de su presentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confes\u00f3 que el rap lleg\u00f3 a su vida desde los 13 a\u00f1os. Y con \u00e9l siempre ha buscado generar conciencia, pero sin aburrir con su mensaje, a fin de que llegue al p\u00fablico joven.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cYo rapeo desde los 13 a\u00f1os&#8230; he llevado el rap al estilo de vida que tengo ahora, se relaciona un poco porque lo que pretendo es llevar rap conciencia a las personas, pero con un mensaje no muy aburrido, d\u00e1ndole un mensaje como el de la semifinal que a la gente le gust\u00f3, disfrut\u00f3 el show, pero se llev\u00f3 un mensaje con cierta relevancia\u201d, rese\u00f1\u00f3 el cantante de rap.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre su paso a la final, confes\u00f3 que no estaba seguro de si pasar\u00eda, debido a la diversidad de actos que se presentaron y a la calidad de cada uno y el estigma que existe en contra de los raperos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi te soy sincero yo no estaba seguro de si pasar\u00eda a la final porque muchas veces la gente subestima a los raperos y yo me di cuenta el d\u00eda de las audiciones, muchas personas cuestionaban cu\u00e1l ser\u00eda la evoluci\u00f3n de mi acto, y realmente a m\u00ed no me molesta porque la gente tiene raz\u00f3n en pensar as\u00ed, porque lamentablemente lo que se conoce de la m\u00fasica que yo hago es limitado, pero eso me incentiva a hacer lo que yo hice\u201d, estim\u00f3 el concursante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su acto \u00e9l con la ayuda de la tecnolog\u00eda hizo un dueto musical consigo mismo, cambiando su voz y dando la idea de que eran dos personas distintas. Adem\u00e1s la utilizaci\u00f3n de bailarines y el contexto general de su acto le sum\u00f3 puntos, aunque confes\u00f3 que le distrajo un poco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl Piro\u201d est\u00e1 en la final y busca seguir edificando con su m\u00fasica, por lo que, si gana la competencia estar\u00e1 enfocado en su carrera musical, pero tranquilos, no descuidar\u00e1 su activismo, porque al final, seg\u00fan \u00e9l considedra, el rap siempre ha estado ligado a las causas sociales y a la rebeld\u00eda juvenil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un rapero activista y un cantautor so\u00f1ador son los dos finalistas del primer programa de la semifinal del programa de b\u00fasqueda de talentos Dominicana\u2019s Got Talent. Ellos se impusieron a otros actos interesantes para ganarse un espacio en la final. Diario Libre convers\u00f3 con ellos, que se mostraron muy felices por este paso en la competencia. Diego Jaar, que hab\u00eda obtenido el Golden Buzzer de Waddys J\u00e1quez, fue el m\u00e1s votado de la noche. El cantautor hizo gala de su dominio en el escenario, con una canci\u00f3n de su autor\u00eda que le vali\u00f3 los elogios del jurado. Con el piano como su instrumento, el int\u00e9rprete demostr\u00f3 que un lugar en la final ten\u00eda su nombre. En conversaci\u00f3n con Diario Libre, el cantautor nacido en Puerto Rico se mostr\u00f3 agradecido por este momento en su carrera, el que tom\u00f3 como una prueba para saber si puede vivir de esto. \u201cNo quiero que pase el tiempo sin intentarlo\u201d. \u201cYo dije si puedo gustar con mis canciones puedo hacer m\u00fasica en cualquier parte, esta es la confirmaci\u00f3n de que s\u00ed puedo\u201d, expres\u00f3 emocionado. Confes\u00f3 adem\u00e1s que siempre ha vivido una especie de disyuntiva entre la profesi\u00f3n que le ha dejado ingresos y la pasi\u00f3n que siente por la m\u00fasica. \u201cYo ejerzo como productor audiovisual, pero toda la vida la he pasado en la m\u00fasica, dividiendo mi vida entre hacer canciones y trabajar\u201d. A \u00e9l lo acompa\u00f1ar\u00e1 el rapero \u201cEl Piro\u201d, \u00e9l se ha dado a conocer por su activismo en \u201cSomos Pueblo\u201d, una plataforma de cr\u00edtica social que se ha hecho muy popular en las redes sociales. Con su rap social, Eduardo S\u00e1nchez Tolentino, conocido como \u201cEl Piro\u201d, se gan\u00f3 un lugar en la final del programa Dominicana\u2019s Got Talent. Sin embargo, aunque sorprendi\u00f3 a muchos que lo siguen m\u00e1s por sus an\u00e1lisis en la plataforma de cr\u00edtica social, lo cierto es que \u00e9l no es un improvisado en el g\u00e9nero urbano local. As\u00ed lo expres\u00f3 a Diario Libre durante una entrevista al d\u00eda siguiente de su presentaci\u00f3n. Confes\u00f3 que el rap lleg\u00f3 a su vida desde los 13 a\u00f1os. Y con \u00e9l siempre ha buscado generar conciencia, pero sin aburrir con su mensaje, a fin de que llegue al p\u00fablico joven. \u201cYo rapeo desde los 13 a\u00f1os&#8230; he llevado el rap al estilo de vida que tengo ahora, se relaciona un poco porque lo que pretendo es llevar rap conciencia a las personas, pero con un mensaje no muy aburrido, d\u00e1ndole un mensaje como el de la semifinal que a la gente le gust\u00f3, disfrut\u00f3 el show, pero se llev\u00f3 un mensaje con cierta relevancia\u201d, rese\u00f1\u00f3 el cantante de rap. Sobre su paso a la final, confes\u00f3 que no estaba seguro de si pasar\u00eda, debido a la diversidad de actos que se presentaron y a la calidad de cada uno y el estigma que existe en contra de los raperos. \u201cSi te soy sincero yo no estaba seguro de si pasar\u00eda a la final porque muchas veces la gente subestima a los raperos y yo me di cuenta el d\u00eda de las audiciones, muchas personas cuestionaban cu\u00e1l ser\u00eda la evoluci\u00f3n de mi acto, y realmente a m\u00ed no me molesta porque la gente tiene raz\u00f3n en pensar as\u00ed, porque lamentablemente lo que se conoce de la m\u00fasica que yo hago es limitado, pero eso me incentiva a hacer lo que yo hice\u201d, estim\u00f3 el concursante. En su acto \u00e9l con la ayuda de la tecnolog\u00eda hizo un dueto musical consigo mismo, cambiando su voz y dando la idea de que eran dos personas distintas. Adem\u00e1s la utilizaci\u00f3n de bailarines y el contexto general de su acto le sum\u00f3 puntos, aunque confes\u00f3 que le distrajo un poco. \u201cEl Piro\u201d est\u00e1 en la final y busca seguir edificando con su m\u00fasica, por lo que, si gana la competencia estar\u00e1 enfocado en su carrera musical, pero tranquilos, no descuidar\u00e1 su activismo, porque al final, seg\u00fan \u00e9l considedra, el rap siempre ha estado ligado a las causas sociales y a la rebeld\u00eda juvenil.<\/p>\n","protected":false},"author":9,"featured_media":80474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-80473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80473"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80473\/revisions"}],"predecessor-version":[{"id":80475,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80473\/revisions\/80475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80474"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}