{"id":8076,"date":"2014-09-04T09:00:04","date_gmt":"2014-09-04T13:00:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8076"},"modified":"2014-09-04T08:34:56","modified_gmt":"2014-09-04T12:34:56","slug":"que-es-la-memoria-muscular","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/que-es-la-memoria-muscular\/","title":{"rendered":"\u00bfQu\u00e9 es la memoria muscular?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/articulo_20130205172447.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8077 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/articulo_20130205172447-300x200.jpg\" alt=\"articulo_20130205172447\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/articulo_20130205172447-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/articulo_20130205172447.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Una vez que aprendemos a caminar no olvidamos c\u00f3mo hacerlo y ello es gracias a nuestra\u00a0<label style=\"color: #0000ff;\">memoria<\/label>\u00a0muscular. Nuestro cerebro no tiene que descubrir c\u00f3mo hacerlo cada vez que desea ordenarle a nuestras\u00a0<label style=\"color: #0000ff;\">piernas<\/label>\u00a0dar un paso, gracias a la repetici\u00f3n cotidiana de dar un paso tras otro, simplemente lo sabe.<!--more--><\/p>\n<p>Todos los d\u00edas,\u00a0<label style=\"color: #0000ff;\">todo<\/label>\u00a0el\u00a0<label style=\"color: #0000ff;\">d\u00eda<\/label>, realizamos movimientos y acciones que requieren una orden muy espec\u00edfica del cerebro.\u00a0<label style=\"color: #0000ff;\">Claro<\/label>\u00a0que no somos conscientes de ello a cada momento, nuestra memoria autom\u00e1ticamente lo hace sin que tengamos que tomar la decisi\u00f3n.<\/p>\n<p>Actividades primarias, como caminar, hacer gestos o mantenernos de pie, de hecho no son tan b\u00e1sicas. Una vez que aprendemos a caminar no olvidamos c\u00f3mo hacerlo y ello es gracias a nuestra memoria muscular. Nuestro cerebro no tiene que descubrir c\u00f3mo hacerlo cada vez que desea ordenarle a nuestras piernas dar un paso, gracias a la repetici\u00f3n cotidiana de dar un paso tras otro, simplemente lo sabe. Vamos a averiguar de qu\u00e9 manera.<\/p>\n<p><strong>Ensayo y error<\/strong><\/p>\n<p>Con el paso de los meses un beb\u00e9 aprende a caminar, agarrar cosas con sus manos, correr, saltar y adquirir precisi\u00f3n y fuerza en sus movimientos de forma gradual. Ello es gracias a que, mediante est\u00edmulos, va descubriendo y experientando movimientos nuevos, repiti\u00e9ndolos todo el tiempo. As\u00ed es como funciona la memoria muscular: experimentaci\u00f3n y repetici\u00f3n.<\/p>\n<p>Como ya mencionamos, las actividades primarias que realizamos todos los d\u00edas quedan guardadas en nuestro cerebro y no es necesario que todo el tiempo seamos conscientes sobre c\u00f3mo realizarlas. Ahora bien, algunas actividades m\u00e1s complejas requieren cientos o miles de horas de pr\u00e1ctica. Digitar r\u00e1pidamente en un teclado de computadora, tocar el piano o realizar deportes, son buenos ejemplos.<\/p>\n<p><strong>La memoria muscular en el deporte<\/strong><\/p>\n<p>Los deportistas pasan varias horas a la semana entrenando y practicando para perfeccionar sus movimientos. Algunos deportes como el tenis o el golf requieren un nivel de precisi\u00f3n tal, que s\u00f3lo es posible alcanzar mediante horas y horas de pr\u00e1ctica.<\/p>\n<p>Por ejemplo, un tenista debe ser capaz de medir exactamente d\u00f3nde va a rebotar la pelota si le pega de tal o cual manera, con cu\u00e1nta fuerza debe pegarle y en qu\u00e9 direcci\u00f3n. El jugador no es totalmente consciente del mecanismo detr\u00e1s de cada golpe, simplemente aprendi\u00f3 a hacerlo, lo ha practicado y lo puede repetir.<\/p>\n<p>Si el jugador realiza mal un golpe y se queda pensando en ello, sin volver a concentrarse en ejecutar buenos disparos, es probable que siga jugando mal. Esto sucede porque se trata de una orden tan compleja y sofisticada, que requiere total concentraci\u00f3n.<\/p>\n<p>Todos podemos caminar pensando en otras cosas, pero es pr\u00e1cticamente imposible ejecutar disparos perfectos si no estamos completamente concentrados en ello. Ni siquiera si somos Novak Djokovic o Roger Federer.<\/p>\n<p><strong>Un arma de doble filo<\/strong><\/p>\n<p>No todo es tan prometedor. Ser excelentes m\u00fasicos o deportistas no s\u00f3lo depende de cu\u00e1nto practiquemos o cu\u00e1n concentrados logremos estar. Depende tambi\u00e9n de qui\u00e9n y c\u00f3mo nos ense\u00f1en.<\/p>\n<p>As\u00ed como podemos aprender a mejorar nuestros movimientos gracias a la pr\u00e1ctica y la repetici\u00f3n, tambi\u00e9n podemos aprender a realizarlos mal. Nuestro cerebro procesa toda la informaci\u00f3n, no decide si es buena o mala. Es decir, si nos ense\u00f1an mal un movimiento o un h\u00e1bito, es muy dif\u00edcil eliminarlo o corregirlo.<\/p>\n<p>Volviendo al deporte, si a un ni\u00f1o le ense\u00f1an que a la pelota de f\u00fatbol le debe pegar con la punta de los pies, lo aprende y lo practica as\u00ed, ser\u00e1 excelente pateando p\u00e9simos tiros. Podemos aprender y perfeccionar cualquier movimiento que practiquemos, pero ello no significa que sea el movimiento correcto.<\/p>\n<p>Malas indicaciones, falta de concentraci\u00f3n y nervios, pueden arruinar el complejo y valioso proceso de aprender y perfeccionar un movimiento. Nuestra memoria es maravillosa y puede realizar muchas cosas por s\u00ed sola, sin que seamos conscientes. Pero no es infalible y necesita que tomemos las decisiones correctas.<\/p>\n<p>Fuente:\u00a0<a style=\"color: #006e94;\" href=\"http:\/\/curiosidades.batanga.com\/6797\/que-es-la-memoria-muscular\" target=\"_blank\">Ojo cient\u00edfico<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una vez que aprendemos a caminar no olvidamos c\u00f3mo hacerlo y ello es gracias a nuestra\u00a0memoria\u00a0muscular. Nuestro cerebro no tiene que descubrir c\u00f3mo hacerlo cada vez que desea ordenarle a nuestras\u00a0piernas\u00a0dar un paso, gracias a la repetici\u00f3n cotidiana de dar un paso tras otro, simplemente lo sabe.<\/p>\n","protected":false},"author":3,"featured_media":8077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8076"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8076\/revisions"}],"predecessor-version":[{"id":8078,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8076\/revisions\/8078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8077"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}