{"id":8082,"date":"2014-09-04T13:00:46","date_gmt":"2014-09-04T17:00:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8082"},"modified":"2014-09-04T08:40:12","modified_gmt":"2014-09-04T12:40:12","slug":"sofia-vergara-tercer-ano-como-la-actriz-de-television-mejor-pagada","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sofia-vergara-tercer-ano-como-la-actriz-de-television-mejor-pagada\/","title":{"rendered":"Sof\u00eda Vergara, tercer a\u00f1o como la actriz de televisi\u00f3n mejor pagada"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/6613317w.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8083 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/6613317w-300x200.jpg\" alt=\"6613317w\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/6613317w-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/6613317w.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Sof\u00eda Vergara por tercer a\u00f1o consecutivo como la actriz de televisi\u00f3n mejor pagada del a\u00f1o en EEUU, de acuerdo a Forbes.<!--more--><\/p>\n<p>La actriz colombiana Sof\u00eda Vergara repite en 2014 por tercer a\u00f1o consecutivo como la actriz de televisi\u00f3n mejor pagada del a\u00f1o en Estados Unidos, seg\u00fan una nueva lista que public\u00f3 hoy la revista Forbes.<\/p>\n<p>La actriz recibi\u00f3 37 millones de d\u00f3lares por su caracterizaci\u00f3n de la apasionada Gloria Delgado-Pritchett en la popular\u00a0<label style=\"color: #0000ff;\">serie<\/label>\u00a0televisiva \u00abModern Family\u00bb, que la convirti\u00f3 en la n\u00famero\u00a0<label style=\"color: #0000ff;\">uno<\/label>\u00a0de la lista de las diez actrices de televisi\u00f3n mejor pagadas entre junio de 2013 y junio de 2014.<\/p>\n<p>Adem\u00e1s de actuar en esta popular serie, Vergara, de 42 a\u00f1os, tambi\u00e9n es una empresaria de \u00e9xito y cofundadora de la agencia de talento y\u00a0<label style=\"color: #0000ff;\">entretenimiento<\/label>\u00a0hispano Latin World Entertainment, adem\u00e1s de ser la\u00a0<label style=\"color: #0000ff;\">imagen<\/label>\u00a0de marcas internacionales.<\/p>\n<p>Lejos de la pol\u00e9mica que caus\u00f3 durante la reciente entrega de los premios Emmy al ejercer de\u00a0<label style=\"color: #0000ff;\">mujer<\/label>\u00a0objeto en una broma, la colombiana ha dejado claro que pisa fuerte y considera que es sano \u00abre\u00edrse\u00bb de uno mismo.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sof\u00eda Vergara por tercer a\u00f1o consecutivo como la actriz de televisi\u00f3n mejor pagada del a\u00f1o en EEUU, de acuerdo a Forbes.<\/p>\n","protected":false},"author":3,"featured_media":8083,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-8082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8082"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8082\/revisions"}],"predecessor-version":[{"id":8084,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8082\/revisions\/8084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8083"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}