{"id":80937,"date":"2021-04-04T18:54:15","date_gmt":"2021-04-04T22:54:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=80937"},"modified":"2021-04-04T18:54:17","modified_gmt":"2021-04-04T22:54:17","slug":"boletin3-coe-reporta-5-muertes-para-un-total-de-24-defunciones-durante-el-asueto-de-semana-santa","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/boletin3-coe-reporta-5-muertes-para-un-total-de-24-defunciones-durante-el-asueto-de-semana-santa\/","title":{"rendered":"Bolet\u00edn#3: COE reporta 5 muertes para un total de 24 defunciones durante el asueto de Semana Santa"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/04\/boletin3-coe-reporta-5-muertes-para-un-total-de-24-defunciones-durante-el-asueto-de-semana-santa.jpeg\" alt=\"\" class=\"wp-image-80938\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/04\/boletin3-coe-reporta-5-muertes-para-un-total-de-24-defunciones-durante-el-asueto-de-semana-santa.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/04\/boletin3-coe-reporta-5-muertes-para-un-total-de-24-defunciones-durante-el-asueto-de-semana-santa-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro de Operaciones de Emergencias (COE) report\u00f3 que en las \u00faltimas 24 horas se han producido un total de cinco muertes por accidentes de tr\u00e1nsito, intoxicaci\u00f3n alcoh\u00f3lica y ahogamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo declarado por el director del COE, Juan Manuel M\u00e9ndez, dos de esas muertes se produjeron fuera del operativo de la entidad denominado \u00abSemana Santa: Un Compromiso por la Vida 2021\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro del operativo fallecieron Yancarlos Salla Ram\u00edrez y un desconocido por accidentes de tr\u00e1nsito separados ocurridos en la Carretera S\u00e1nchez, mientras que un menor de 6 a\u00f1os se ahog\u00f3 en el R\u00edo Yab\u00f3n en la comunidad Loma Larga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director del COE afirm\u00f3 que desde que se inici\u00f3 el operativo, el Jueves Santo en la tarde, hasta la ma\u00f1ana de este Domingo de Resurrecci\u00f3n han fallecido 24 personas por accidentes de tr\u00e1nsito, asfixia por inmersi\u00f3n e intoxicaci\u00f3n alcoh\u00f3lica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fuera del Operativo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuera del operativo fueron reportados los fallecimientos del hombre de nacionalidad haitiana, Raynold Jumeau y de una persona, que hasta el momento no ha sido identificada, que fue atropellada en el cruce de Catalina, en Bani durante el horario que impera el toque de queda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Accidentes de Tr\u00e1nsito<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las \u00faltimas 24 horas se reportaron al centro de operaciones de emergencia un total de 143 accidentes de tr\u00e1nsito, resultando 211 personas afectadas. En esos accidentes se vieron involucrados 117 motocicletas, 15 veh\u00edculos livianos, 4 veh\u00edculos pesados y 7 atropellamientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Intoxicados<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El COE report\u00f3 que se atendieron 330 personas intoxicadas por alcohol, de los 31 fueron en menores de edad con edades comprendidas entre 10 y 17 a\u00f1os de edad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Operaciones de Emergencias (COE) report\u00f3 que en las \u00faltimas 24 horas se han producido un total de cinco muertes por accidentes de tr\u00e1nsito, intoxicaci\u00f3n alcoh\u00f3lica y ahogamiento. De acuerdo a lo declarado por el director del COE, Juan Manuel M\u00e9ndez, dos de esas muertes se produjeron fuera del operativo de la entidad denominado \u00abSemana Santa: Un Compromiso por la Vida 2021\u00bb. Dentro del operativo fallecieron Yancarlos Salla Ram\u00edrez y un desconocido por accidentes de tr\u00e1nsito separados ocurridos en la Carretera S\u00e1nchez, mientras que un menor de 6 a\u00f1os se ahog\u00f3 en el R\u00edo Yab\u00f3n en la comunidad Loma Larga. El director del COE afirm\u00f3 que desde que se inici\u00f3 el operativo, el Jueves Santo en la tarde, hasta la ma\u00f1ana de este Domingo de Resurrecci\u00f3n han fallecido 24 personas por accidentes de tr\u00e1nsito, asfixia por inmersi\u00f3n e intoxicaci\u00f3n alcoh\u00f3lica. Fuera del Operativo Fuera del operativo fueron reportados los fallecimientos del hombre de nacionalidad haitiana, Raynold Jumeau y de una persona, que hasta el momento no ha sido identificada, que fue atropellada en el cruce de Catalina, en Bani durante el horario que impera el toque de queda. Accidentes de Tr\u00e1nsito En las \u00faltimas 24 horas se reportaron al centro de operaciones de emergencia un total de 143 accidentes de tr\u00e1nsito, resultando 211 personas afectadas. En esos accidentes se vieron involucrados 117 motocicletas, 15 veh\u00edculos livianos, 4 veh\u00edculos pesados y 7 atropellamientos. Intoxicados El COE report\u00f3 que se atendieron 330 personas intoxicadas por alcohol, de los 31 fueron en menores de edad con edades comprendidas entre 10 y 17 a\u00f1os de edad<\/p>\n","protected":false},"author":9,"featured_media":80938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-80937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=80937"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80937\/revisions"}],"predecessor-version":[{"id":80939,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/80937\/revisions\/80939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/80938"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=80937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=80937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=80937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}