{"id":81019,"date":"2021-04-21T18:30:50","date_gmt":"2021-04-21T22:30:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81019"},"modified":"2021-04-21T18:30:52","modified_gmt":"2021-04-21T22:30:52","slug":"hasta-que-me-olvides-la-cancion-de-luis-miguel-escrita-por-juan-luis-guerra-que-resucito-en-las-plataformas-digitales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/hasta-que-me-olvides-la-cancion-de-luis-miguel-escrita-por-juan-luis-guerra-que-resucito-en-las-plataformas-digitales\/","title":{"rendered":"\u201cHasta que me olvides\u201d, la canci\u00f3n de Luis Miguel escrita por Juan Luis Guerra que &#8216;resucit\u00f3&#8217; en las plataformas digitales"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/04\/esp.jpg\" alt=\"\" class=\"wp-image-81020\" width=\"335\" height=\"186\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/04\/esp.jpg 451w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/04\/esp-300x167.jpg 300w\" sizes=\"auto, (max-width: 335px) 100vw, 335px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Los primeros cap\u00edtulos de la segunda temporada de \u201cLuis Miguel: la serie\u201d siguen siendo tema de conversaci\u00f3n en las redes sociales, especialmente el segundo episodio donde se descubri\u00f3 el origen de \u201cHasta que me olvides\u201d, tema que fue escrito por Juan Luis Guerra y los fans resucitaron en las plataformas digitales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal ha sido la euforia el disco \u201cAries\u201d, lanzado en junio de 1993 y el que incluye el mencionado tema, se ha colocado en la lista de Top \u00c1lbumes de Apple Music por encima del \u201c\u00daltimo tour del mundo\u201d, de Bad Bunny.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a los datos recolectados por el peri\u00f3dico, Excelsior, en M\u00e9xico \u201cHasta que me olvides\u201d ocupa el quinto sitio en Apple Music, octavo en Spotify, plataforma en la que logr\u00f3 un crecimiento de escuchas de 262%. Acumul\u00f3 m\u00e1s de 368 mil reproducciones en apenas un par de d\u00edas. Argentina y Chile tambi\u00e9n lo hacen parte de su lista de canciones m\u00e1s reproducidas esta semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es decir, los fans resucitaron el mencionado tema luego de conocer la historia en la serie de Luis Miguel, hasta antes del domingo, el tema no figuraba en ninguna de las listas que ahora se mencionan, un fen\u00f3meno que tom\u00f3 apenas 72 horas para que se colara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Origen de la canci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan se revel\u00f3 en la bioserie sobre Luis Miguel, la canci\u00f3n fue descubierta por Patricio Robles, un empleado de Hugo L\u00f3pez, m\u00e1nager de Luis Miguel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al leer sus letras, Patricio se le acerca a mostr\u00e1rsela a Luis Miguel, pero el joven artista no le prest\u00f3 atenci\u00f3n porque en ese momento no ten\u00eda conciencia de qui\u00e9n se trataba el compositor. En ese momento el muchacho ten\u00eda 22 a\u00f1os de vida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, Hugo termin\u00f3 convenci\u00e9ndolo y los resultados fueron extraordinarios: \u201cHasta que me olvides\u201d logr\u00f3 el n\u00famero uno en la lista Billboard Hot Latin Songs de Estados Unidos, convirti\u00e9ndose en la d\u00e9cima canci\u00f3n de Luismi en alcanzar este puesto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El conductor mexicano Jorge \u201cEl Burro\u201d Van Rankin revel\u00f3 a principios de 2021 que \u00abHasta que me olvides\u00bb fue escrito en una servilleta por Juan Luis Guerra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los primeros cap\u00edtulos de la segunda temporada de \u201cLuis Miguel: la serie\u201d siguen siendo tema de conversaci\u00f3n en las redes sociales, especialmente el segundo episodio donde se descubri\u00f3 el origen de \u201cHasta que me olvides\u201d, tema que fue escrito por Juan Luis Guerra y los fans resucitaron en las plataformas digitales. Tal ha sido la euforia el disco \u201cAries\u201d, lanzado en junio de 1993 y el que incluye el mencionado tema, se ha colocado en la lista de Top \u00c1lbumes de Apple Music por encima del \u201c\u00daltimo tour del mundo\u201d, de Bad Bunny. De acuerdo a los datos recolectados por el peri\u00f3dico, Excelsior, en M\u00e9xico \u201cHasta que me olvides\u201d ocupa el quinto sitio en Apple Music, octavo en Spotify, plataforma en la que logr\u00f3 un crecimiento de escuchas de 262%. Acumul\u00f3 m\u00e1s de 368 mil reproducciones en apenas un par de d\u00edas. Argentina y Chile tambi\u00e9n lo hacen parte de su lista de canciones m\u00e1s reproducidas esta semana. Es decir, los fans resucitaron el mencionado tema luego de conocer la historia en la serie de Luis Miguel, hasta antes del domingo, el tema no figuraba en ninguna de las listas que ahora se mencionan, un fen\u00f3meno que tom\u00f3 apenas 72 horas para que se colara. Origen de la canci\u00f3n Seg\u00fan se revel\u00f3 en la bioserie sobre Luis Miguel, la canci\u00f3n fue descubierta por Patricio Robles, un empleado de Hugo L\u00f3pez, m\u00e1nager de Luis Miguel. Al leer sus letras, Patricio se le acerca a mostr\u00e1rsela a Luis Miguel, pero el joven artista no le prest\u00f3 atenci\u00f3n porque en ese momento no ten\u00eda conciencia de qui\u00e9n se trataba el compositor. En ese momento el muchacho ten\u00eda 22 a\u00f1os de vida. Sin embargo, Hugo termin\u00f3 convenci\u00e9ndolo y los resultados fueron extraordinarios: \u201cHasta que me olvides\u201d logr\u00f3 el n\u00famero uno en la lista Billboard Hot Latin Songs de Estados Unidos, convirti\u00e9ndose en la d\u00e9cima canci\u00f3n de Luismi en alcanzar este puesto. El conductor mexicano Jorge \u201cEl Burro\u201d Van Rankin revel\u00f3 a principios de 2021 que \u00abHasta que me olvides\u00bb fue escrito en una servilleta por Juan Luis Guerra.<\/p>\n","protected":false},"author":9,"featured_media":81020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-81019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81019"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81019\/revisions"}],"predecessor-version":[{"id":81021,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81019\/revisions\/81021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81020"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}