{"id":81137,"date":"2021-05-01T09:14:53","date_gmt":"2021-05-01T13:14:53","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81137"},"modified":"2021-05-01T09:14:56","modified_gmt":"2021-05-01T13:14:56","slug":"posponen-para-la-proxima-semana-llenado-de-formulario-digital-de-viajes-aereos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/posponen-para-la-proxima-semana-llenado-de-formulario-digital-de-viajes-aereos\/","title":{"rendered":"Posponen para la pr\u00f3xima semana llenado de formulario digital de viajes a\u00e9reos"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/aa.jpg\" alt=\"\" class=\"wp-image-81138\" width=\"260\" height=\"156\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/aa.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/aa-300x180.jpg 300w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La Direcci\u00f3n General de Migraci\u00f3n pospuso para la pr\u00f3xima semana la obligatoriedad del llenado y uso del formulario digital (e-ticket) para la entrada y salida de pasajeros desde y hacia el pa\u00eds, por ajustes en el sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enrique Garc\u00eda, director general de la instituci\u00f3n explic\u00f3 que los pasajeros que salgan o ingresen a partir de este s\u00e1bado primero de mayo, cuando entraba en vigencia la medida, podr\u00e1n hacer el llenado del formulario a trav\u00e9s de la v\u00eda digital o escrita, hasta la pr\u00f3xima semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garc\u00eda se\u00f1al\u00f3 que todav\u00eda la instituci\u00f3n seguir\u00e1 trabajando en una fase de prueba hasta la pr\u00f3xima semana cuando se hagan algunos ajustes en el sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAunque hab\u00edamos anunciado su entrada para este primero de mayo hemos decido prologarla para la pr\u00f3xima semana a fin de hacer algunos ajustes necesarios en el sistema, que lo hagan m\u00e1s viable y accesible para los diferentes p\u00fablicos\u201d, expreso el director general de Migraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que, en la regi\u00f3n del norte del pa\u00eds, principalmente en Santiago es donde se han detectado mayores inconvenientes con el nuevo sistema de llenado electr\u00f3nico del ticket de salida y entrada de migraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma\u00f1ana s\u00e1bado estaba prevista la entrada en vigor del uso obligatorio en el llenado y uso del formulario digital (e-ticket) para la entrada y salida de pasajeros desde y hacia la Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n a su aplicaci\u00f3n, destac\u00f3 que esa decisi\u00f3n de llevar el ticket de migratorio del m\u00e9todo escrito a digital es un mecanismo que representa un reto, para la instituci\u00f3n debido a que mucha gente se resiste a los cambios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que algunos viajeros cuestionan el hecho de que en el formulario nuevo digital se hagan varias preguntas contrario al ticket tradicional escrito que se aplica en las terminales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enrique Garc\u00eda, neg\u00f3 que en el m\u00e9todo digital de llenado del formulario se hagan muchas preguntas que el pasajero tiene que contestar, como alegan algunos de ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aclar\u00f3 que ahora son menos porque anteriormente el viajero ten\u00eda que llenar tres formularios uno de migraci\u00f3n, otro de aduana y el de salud p\u00fablica y en cada uno ten\u00eda que escribir su nombre y apellidos y otras informaciones y ahora con el nuevo m\u00e9todo digital los pasajeros solo tienen que colocar una sola vez su nombre y apellidos, &nbsp;algunos detalles y luego enviar el documento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n General de Migraci\u00f3n pospuso para la pr\u00f3xima semana la obligatoriedad del llenado y uso del formulario digital (e-ticket) para la entrada y salida de pasajeros desde y hacia el pa\u00eds, por ajustes en el sistema. Enrique Garc\u00eda, director general de la instituci\u00f3n explic\u00f3 que los pasajeros que salgan o ingresen a partir de este s\u00e1bado primero de mayo, cuando entraba en vigencia la medida, podr\u00e1n hacer el llenado del formulario a trav\u00e9s de la v\u00eda digital o escrita, hasta la pr\u00f3xima semana. Garc\u00eda se\u00f1al\u00f3 que todav\u00eda la instituci\u00f3n seguir\u00e1 trabajando en una fase de prueba hasta la pr\u00f3xima semana cuando se hagan algunos ajustes en el sistema. \u201cAunque hab\u00edamos anunciado su entrada para este primero de mayo hemos decido prologarla para la pr\u00f3xima semana a fin de hacer algunos ajustes necesarios en el sistema, que lo hagan m\u00e1s viable y accesible para los diferentes p\u00fablicos\u201d, expreso el director general de Migraci\u00f3n. Explic\u00f3 que, en la regi\u00f3n del norte del pa\u00eds, principalmente en Santiago es donde se han detectado mayores inconvenientes con el nuevo sistema de llenado electr\u00f3nico del ticket de salida y entrada de migraci\u00f3n. Ma\u00f1ana s\u00e1bado estaba prevista la entrada en vigor del uso obligatorio en el llenado y uso del formulario digital (e-ticket) para la entrada y salida de pasajeros desde y hacia la Rep\u00fablica Dominicana. Con relaci\u00f3n a su aplicaci\u00f3n, destac\u00f3 que esa decisi\u00f3n de llevar el ticket de migratorio del m\u00e9todo escrito a digital es un mecanismo que representa un reto, para la instituci\u00f3n debido a que mucha gente se resiste a los cambios. Explic\u00f3 que algunos viajeros cuestionan el hecho de que en el formulario nuevo digital se hagan varias preguntas contrario al ticket tradicional escrito que se aplica en las terminales Enrique Garc\u00eda, neg\u00f3 que en el m\u00e9todo digital de llenado del formulario se hagan muchas preguntas que el pasajero tiene que contestar, como alegan algunos de ellos. Aclar\u00f3 que ahora son menos porque anteriormente el viajero ten\u00eda que llenar tres formularios uno de migraci\u00f3n, otro de aduana y el de salud p\u00fablica y en cada uno ten\u00eda que escribir su nombre y apellidos y otras informaciones y ahora con el nuevo m\u00e9todo digital los pasajeros solo tienen que colocar una sola vez su nombre y apellidos, &nbsp;algunos detalles y luego enviar el documento.<\/p>\n","protected":false},"author":9,"featured_media":81138,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-81137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81137"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81137\/revisions"}],"predecessor-version":[{"id":81139,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81137\/revisions\/81139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81138"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}