{"id":81159,"date":"2021-05-03T19:01:37","date_gmt":"2021-05-03T23:01:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81159"},"modified":"2021-05-03T19:01:40","modified_gmt":"2021-05-03T23:01:40","slug":"la-digesett-retira-de-calles-y-aceras-chatarras-obstaculizaban-libre-transito","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-digesett-retira-de-calles-y-aceras-chatarras-obstaculizaban-libre-transito\/","title":{"rendered":"La DIGESETT retira de calles y aceras chatarras obstaculizaban libre tr\u00e1nsito"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"154\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/6879883F-0A9D-4531-BD64-2A6BB4E2D04A-300x154-1.jpeg\" alt=\"\" class=\"wp-image-81160\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO.- La Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre (DIGESETT) retir\u00f3 de calles y aceras chatarras, tarantines y quioscos que obst\u00e1culizaban el libre tr\u00e1nsito de veh\u00edculos y peatones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El general de brigada Ram\u00f3n Antonio Guzm\u00e1n Peralta, director del organismo, explic\u00f3 que el prop\u00f3sito del operativo es recuperar los espacios p\u00fablicos para el libre tr\u00e1nsito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El general Guzm\u00e1n Peralta dijo que asumi\u00f3 la iniciativa tras decenas de denuncias de ciudadanos, organizaciones comunitarias y empresarios, quienes se quejaron de que los peatones ten\u00edan dificultades para caminar por las v\u00edas p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn los lugares donde estaban las chatarras abandonadas se observ\u00f3 que cuando estas eran retiradas hab\u00eda un gran c\u00famulo de basura, todo tipo de desperdicios que se convert\u00edan en criaderos de ratas, cucarachas, mosquitos, entre otros tipos de insectos\u00bb, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que esos lugares \u00abson un foco de contaminaci\u00f3n que amenaza la salud de los ciudadanos, adem\u00e1s de obstaculizar el libre tr\u00e1nsito de veh\u00edculos, peatones\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El operativo fue realizado en los sectores capitalinos Villa Juana, Villa Consuelo, Villas Agr\u00edcolas, Villa Mar\u00eda, Ensanche La Fe, Cristo Rey, La Feria, Mata Hambre, La Paz, Herrera, Mar\u00eda Auxiliadora, Villa Francisca, avenida Independencia y Carretera S\u00e1nchez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- La Direcci\u00f3n General de Seguridad de Tr\u00e1nsito y Transporte Terrestre (DIGESETT) retir\u00f3 de calles y aceras chatarras, tarantines y quioscos que obst\u00e1culizaban el libre tr\u00e1nsito de veh\u00edculos y peatones. El general de brigada Ram\u00f3n Antonio Guzm\u00e1n Peralta, director del organismo, explic\u00f3 que el prop\u00f3sito del operativo es recuperar los espacios p\u00fablicos para el libre tr\u00e1nsito. El general Guzm\u00e1n Peralta dijo que asumi\u00f3 la iniciativa tras decenas de denuncias de ciudadanos, organizaciones comunitarias y empresarios, quienes se quejaron de que los peatones ten\u00edan dificultades para caminar por las v\u00edas p\u00fablicas. \u00abEn los lugares donde estaban las chatarras abandonadas se observ\u00f3 que cuando estas eran retiradas hab\u00eda un gran c\u00famulo de basura, todo tipo de desperdicios que se convert\u00edan en criaderos de ratas, cucarachas, mosquitos, entre otros tipos de insectos\u00bb, explic\u00f3. Dijo que esos lugares \u00abson un foco de contaminaci\u00f3n que amenaza la salud de los ciudadanos, adem\u00e1s de obstaculizar el libre tr\u00e1nsito de veh\u00edculos, peatones\u00bb. El operativo fue realizado en los sectores capitalinos Villa Juana, Villa Consuelo, Villas Agr\u00edcolas, Villa Mar\u00eda, Ensanche La Fe, Cristo Rey, La Feria, Mata Hambre, La Paz, Herrera, Mar\u00eda Auxiliadora, Villa Francisca, avenida Independencia y Carretera S\u00e1nchez<\/p>\n","protected":false},"author":9,"featured_media":81160,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-81159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81159"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81159\/revisions"}],"predecessor-version":[{"id":81161,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81159\/revisions\/81161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81160"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}