{"id":81438,"date":"2021-05-22T08:27:43","date_gmt":"2021-05-22T12:27:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81438"},"modified":"2021-05-22T08:27:46","modified_gmt":"2021-05-22T12:27:46","slug":"enrique-de-sussex-dice-que-uso-las-fiestas-y-el-alcohol-para-huir-del-dolor","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/enrique-de-sussex-dice-que-uso-las-fiestas-y-el-alcohol-para-huir-del-dolor\/","title":{"rendered":"Enrique de Sussex dice que us\u00f3 las fiestas y el alcohol para huir del dolor"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/enrique-de-sussex-dice-que-uso-las-fiestas-y-el-alcohol-para-huir-del-dolor.jpeg\" alt=\"\" class=\"wp-image-81439\" width=\"228\" height=\"151\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/enrique-de-sussex-dice-que-uso-las-fiestas-y-el-alcohol-para-huir-del-dolor.jpeg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/05\/enrique-de-sussex-dice-que-uso-las-fiestas-y-el-alcohol-para-huir-del-dolor-300x199.jpeg 300w\" sizes=\"auto, (max-width: 228px) 100vw, 228px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El pr\u00edncipe Enrique de Inglaterra confes\u00f3 que, durante una \u00e9poca de su vida, recurri\u00f3 a las fiestas y al alcohol \u00abcomo una forma de escape\u00bb del dolor que sent\u00eda tras las muerte de su madre Diana y su encaje en la familia real brit\u00e1nica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En una nueva serie documental titulada \u00abThe Me You Can&#8217;t See\u00bb (\u00abLo que no puedes ver de mi\u00bb), que ha creado junto a la famosa presentadora estadounidense Oprah Winfrey, Enrique comparte detalles de c\u00f3mo fue su vida con los Windsor tras la muerte de su madre, especialmente los primeros a\u00f1os de su juventud, y su lucha por mantener su estabilidad metal, seg\u00fan la revista People.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEstaba dispuesto a beber, estaba dispuesto a tomar drogas, estaba dispuesto a intentar hacer las cosas que me hac\u00edan sentir menos como me sent\u00eda\u00bb, le confiesa en el documental a Winfrey, que ha emitido su primer cap\u00edtulo en la plataforma Apple TV.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abPero poco a poco me di cuenta de que, est\u00e1 bien, no estaba bebiendo de lunes a viernes, pero probablemente beber\u00eda el equivalente a una semana en un solo d\u00eda, un viernes o un s\u00e1bado, por la noche. Y estaba bebiendo, no porque lo disfrutara, sino porque estaba tratando de enmascarar algo\u00bb, precisa en la entrevista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esa charla confiesa que la \u00e9poca m\u00e1s feliz de su vida fueron los 10 a\u00f1os que estuvo en el Ej\u00e9rcito \u00abporque no hab\u00eda un trato especial por ser miembro de la realeza\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Cuatro a\u00f1os de terapia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus problemas de salud mental se intensificaron despu\u00e9s de la muerte de su madre, la princesa Diana, en agosto de 1997. En ese momento, Harry ten\u00eda solo 12 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSoy una de las primeras personas en reconocer que, en primer lugar, ten\u00eda miedo, cuando fui a terapia por primera vez, miedo a perder\u00bb, asegura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCuatro a\u00f1os de terapia para una persona que nunca pens\u00f3 que alguna vez la necesitar\u00eda o har\u00eda terapia es&#8230; eso es mucho tiempo. Yo tampoco estaba en un ambiente en el que se animara a hablar de eso\u00bb, se queja, al referirse a la falta de comunicaci\u00f3n con su familia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enrique de Sussex tambi\u00e9n explica que pens\u00f3 que \u00abnecesitaba\u00bb terapia debido al \u00abpasado, para curarse del pasado\u00bb, principalmente de la muerte de su madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo quiero pensar en ella, porque si pienso en ella, va a salir a relucir el hecho de que no puedo traerla de vuelta y me va a entristecer. \u00bfDe qu\u00e9 sirve pensar en algo triste?. Y simplemente decid\u00ed no hablar de eso. Nadie hablaba de eso\u00bb, recuerda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la muerte de Diana de Gales, Enrique cree que ten\u00eda \u00abla cabeza metida en la arena y simplemente se resquebrajaba\u00bb, y agrega: \u00abSi la gente hubiera dicho: &#8216;\u00bfC\u00f3mo est\u00e1s?&#8217; dir\u00eda que &#8216;bien&#8217;. Nunca feliz. Nunca triste, muy bien. Bien fue la respuesta f\u00e1cil\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ataques de p\u00e1nico y ansiedad severa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Soportaba \u00abataques de p\u00e1nico [y] ansiedad severa\u00bb durante sus deberes reales en sus veintitantos, un per\u00edodo que \u00e9l llama un \u00abtiempo de pesadilla en mi vida\u00bb debido a estar en \u00abmodo de lucha o huida\u00bb y \u00abenloqueciendo\u00bb a menudo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abCada vez que me sub\u00eda al autom\u00f3vil y cada vez que ve\u00eda una c\u00e1mara, empezaba a sudar. Sent\u00eda como si la temperatura de mi cuerpo fuera dos o tres grados m\u00e1s alta que la de todos los dem\u00e1s en la habitaci\u00f3n. Me convenc\u00eda a m\u00ed mismo de que mi rostro estaba rojo brillante y todos pod\u00edan ver c\u00f3mo me sent\u00eda, pero nadie sabr\u00eda por qu\u00e9\u00bb, comparte el nieto de la reina Isabel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAhora, en retrospectiva, mirando hacia atr\u00e1s, todo es cuesti\u00f3n de tiempo. Hacia el final de mis 20, todo se volvi\u00f3 realmente agitado para m\u00ed. Hasta el punto del agotamiento, estaba viajando por todos lados\u00bb porque desde la perspectiva de su familia se planteaba as\u00ed: \u00abNecesitamos que alguien vaya all\u00ed: Nepal, Harry. Ve t\u00fa\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconoce que siempre fue asertivo con sus obligaciones pero eso le llev\u00f3 al agotamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Appel TV estren\u00f3 el 21 de mayo esta producci\u00f3n en la que tambi\u00e9n han participado Lady Gaga, Glenn Close, Zack Williams y la boxeadora Virginia Fuchs, entre otros invitados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Apple, los productores del formato han contado con la supervisi\u00f3n de 14 especialistas y organizaciones de diferentes partes del mundo para hablar de tratamientos y terapias sobre salud metal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La serie contar\u00e1 tambi\u00e9n con los testimonios de personas de diferentes edades, g\u00e9nero y condici\u00f3n sociocultural, a\u00f1adi\u00f3 la plataforma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta es la segunda colaboraci\u00f3n entre Winfrey y el nieto de la reina Isabel II despu\u00e9s de la medi\u00e1tica entrevista que \u00e9l y su mujer, Meghan Markle, concedieron a la presentadora a principios de marzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los duques de Sussex fueron los protagonistas de una gran pol\u00e9mica cuando, en esa conversaci\u00f3n, Markle acus\u00f3 a la Casa Real brit\u00e1nica de racismo, se\u00f1al\u00f3 al Palacio de Buckingham por perpetuar mentiras sobre Enrique y ella, y admiti\u00f3 que tuvo pensamientos suicidas por la presi\u00f3n que sufri\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00edncipe Enrique de Inglaterra confes\u00f3 que, durante una \u00e9poca de su vida, recurri\u00f3 a las fiestas y al alcohol \u00abcomo una forma de escape\u00bb del dolor que sent\u00eda tras las muerte de su madre Diana y su encaje en la familia real brit\u00e1nica. En una nueva serie documental titulada \u00abThe Me You Can&#8217;t See\u00bb (\u00abLo que no puedes ver de mi\u00bb), que ha creado junto a la famosa presentadora estadounidense Oprah Winfrey, Enrique comparte detalles de c\u00f3mo fue su vida con los Windsor tras la muerte de su madre, especialmente los primeros a\u00f1os de su juventud, y su lucha por mantener su estabilidad metal, seg\u00fan la revista People. \u00abEstaba dispuesto a beber, estaba dispuesto a tomar drogas, estaba dispuesto a intentar hacer las cosas que me hac\u00edan sentir menos como me sent\u00eda\u00bb, le confiesa en el documental a Winfrey, que ha emitido su primer cap\u00edtulo en la plataforma Apple TV. \u00abPero poco a poco me di cuenta de que, est\u00e1 bien, no estaba bebiendo de lunes a viernes, pero probablemente beber\u00eda el equivalente a una semana en un solo d\u00eda, un viernes o un s\u00e1bado, por la noche. Y estaba bebiendo, no porque lo disfrutara, sino porque estaba tratando de enmascarar algo\u00bb, precisa en la entrevista. En esa charla confiesa que la \u00e9poca m\u00e1s feliz de su vida fueron los 10 a\u00f1os que estuvo en el Ej\u00e9rcito \u00abporque no hab\u00eda un trato especial por ser miembro de la realeza\u00bb. Cuatro a\u00f1os de terapia Sus problemas de salud mental se intensificaron despu\u00e9s de la muerte de su madre, la princesa Diana, en agosto de 1997. En ese momento, Harry ten\u00eda solo 12 a\u00f1os. \u00abSoy una de las primeras personas en reconocer que, en primer lugar, ten\u00eda miedo, cuando fui a terapia por primera vez, miedo a perder\u00bb, asegura. \u00abCuatro a\u00f1os de terapia para una persona que nunca pens\u00f3 que alguna vez la necesitar\u00eda o har\u00eda terapia es&#8230; eso es mucho tiempo. Yo tampoco estaba en un ambiente en el que se animara a hablar de eso\u00bb, se queja, al referirse a la falta de comunicaci\u00f3n con su familia. Enrique de Sussex tambi\u00e9n explica que pens\u00f3 que \u00abnecesitaba\u00bb terapia debido al \u00abpasado, para curarse del pasado\u00bb, principalmente de la muerte de su madre. \u00abNo quiero pensar en ella, porque si pienso en ella, va a salir a relucir el hecho de que no puedo traerla de vuelta y me va a entristecer. \u00bfDe qu\u00e9 sirve pensar en algo triste?. Y simplemente decid\u00ed no hablar de eso. Nadie hablaba de eso\u00bb, recuerda. Despu\u00e9s de la muerte de Diana de Gales, Enrique cree que ten\u00eda \u00abla cabeza metida en la arena y simplemente se resquebrajaba\u00bb, y agrega: \u00abSi la gente hubiera dicho: &#8216;\u00bfC\u00f3mo est\u00e1s?&#8217; dir\u00eda que &#8216;bien&#8217;. Nunca feliz. Nunca triste, muy bien. Bien fue la respuesta f\u00e1cil\u00bb. Ataques de p\u00e1nico y ansiedad severa Soportaba \u00abataques de p\u00e1nico [y] ansiedad severa\u00bb durante sus deberes reales en sus veintitantos, un per\u00edodo que \u00e9l llama un \u00abtiempo de pesadilla en mi vida\u00bb debido a estar en \u00abmodo de lucha o huida\u00bb y \u00abenloqueciendo\u00bb a menudo. \u00abCada vez que me sub\u00eda al autom\u00f3vil y cada vez que ve\u00eda una c\u00e1mara, empezaba a sudar. Sent\u00eda como si la temperatura de mi cuerpo fuera dos o tres grados m\u00e1s alta que la de todos los dem\u00e1s en la habitaci\u00f3n. Me convenc\u00eda a m\u00ed mismo de que mi rostro estaba rojo brillante y todos pod\u00edan ver c\u00f3mo me sent\u00eda, pero nadie sabr\u00eda por qu\u00e9\u00bb, comparte el nieto de la reina Isabel. \u00abAhora, en retrospectiva, mirando hacia atr\u00e1s, todo es cuesti\u00f3n de tiempo. Hacia el final de mis 20, todo se volvi\u00f3 realmente agitado para m\u00ed. Hasta el punto del agotamiento, estaba viajando por todos lados\u00bb porque desde la perspectiva de su familia se planteaba as\u00ed: \u00abNecesitamos que alguien vaya all\u00ed: Nepal, Harry. Ve t\u00fa\u00bb. Reconoce que siempre fue asertivo con sus obligaciones pero eso le llev\u00f3 al agotamiento. Appel TV estren\u00f3 el 21 de mayo esta producci\u00f3n en la que tambi\u00e9n han participado Lady Gaga, Glenn Close, Zack Williams y la boxeadora Virginia Fuchs, entre otros invitados. Seg\u00fan Apple, los productores del formato han contado con la supervisi\u00f3n de 14 especialistas y organizaciones de diferentes partes del mundo para hablar de tratamientos y terapias sobre salud metal. La serie contar\u00e1 tambi\u00e9n con los testimonios de personas de diferentes edades, g\u00e9nero y condici\u00f3n sociocultural, a\u00f1adi\u00f3 la plataforma. Esta es la segunda colaboraci\u00f3n entre Winfrey y el nieto de la reina Isabel II despu\u00e9s de la medi\u00e1tica entrevista que \u00e9l y su mujer, Meghan Markle, concedieron a la presentadora a principios de marzo. Los duques de Sussex fueron los protagonistas de una gran pol\u00e9mica cuando, en esa conversaci\u00f3n, Markle acus\u00f3 a la Casa Real brit\u00e1nica de racismo, se\u00f1al\u00f3 al Palacio de Buckingham por perpetuar mentiras sobre Enrique y ella, y admiti\u00f3 que tuvo pensamientos suicidas por la presi\u00f3n que sufri\u00f3.<\/p>\n","protected":false},"author":9,"featured_media":81439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-81438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81438"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81438\/revisions"}],"predecessor-version":[{"id":81440,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81438\/revisions\/81440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81439"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}