{"id":8158,"date":"2014-09-05T14:35:09","date_gmt":"2014-09-05T18:35:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8158"},"modified":"2014-09-05T14:35:09","modified_gmt":"2014-09-05T18:35:09","slug":"facebook-invita-a-sus-usuarios-a-revisar-confidencialidad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/facebook-invita-a-sus-usuarios-a-revisar-confidencialidad\/","title":{"rendered":"Facebook invita a sus usuarios a revisar confidencialidad"},"content":{"rendered":"<p><label style=\"color: #0000ff;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/2c886f33f252a397e4fb6a6d1ef58d25d3d7afb2_1_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8159 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/2c886f33f252a397e4fb6a6d1ef58d25d3d7afb2_1_1-300x200.jpg\" alt=\"2c886f33f252a397e4fb6a6d1ef58d25d3d7afb2_1_1\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/2c886f33f252a397e4fb6a6d1ef58d25d3d7afb2_1_1-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/2c886f33f252a397e4fb6a6d1ef58d25d3d7afb2_1_1.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Facebook<\/label>\u00a0comenz\u00f3 este jueves a proponer a sus\u00a0<label style=\"color: #0000ff;\">usuarios<\/label>\u00a0revisar sus par\u00e1metros de confidencialidad para ayudarlos a controlar mejor lo que comparten o publican sobre la red social.<!--more--><\/p>\n<p>Un dinosaurio azul los gu\u00eda a trav\u00e9s de los par\u00e1metros de privacidad sobre informaci\u00f3n<label style=\"color: #0000ff;\">personal<\/label>\u00a0y para compartir sus publicaciones de forma p\u00fablica o de manera m\u00e1s restringida.<\/p>\n<p>\u00abSabemos que vienes a Facebook para estar en\u00a0<label style=\"color: #0000ff;\">contacto<\/label>\u00a0con amigos, no con nosotros\u00bb, explica Paddy Underwood, del\u00a0<label style=\"color: #0000ff;\">equipo<\/label>\u00a0de Facebook, en una entrada del blog de la compa\u00f1\u00eda. \u00abPero sabemos cu\u00e1n importante es controlar lo que compartes y con qui\u00e9n lo compartes\u00bb.<\/p>\n<p>Facebook hab\u00eda anunciado en junio este plan tras haber sido criticado por pr\u00e1cticas de recolecci\u00f3n de datos para prop\u00f3sitos publicitarios.<\/p>\n<p>Pero, seg\u00fan Facebook, los usuarios pueden regular sus par\u00e1metros de confidencialidad para desactivar esta nueva funci\u00f3n.<\/p>\n<p>Facebook, que cuenta con m\u00e1s de 1.000 millones de usuarios, est\u00e1 regularmente en los tribunales por no proteger suficientemente los datos de sus miembros ante aplicaciones terceras o anuncios publicitarios.<\/p>\n<p>La red social lleg\u00f3 a un acuerdo con el gobierno estadounidense para realizar una auditor\u00eda sobre el modo de conservaci\u00f3n de los datos personales de sus usuarios.<\/p>\n<p>AFP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Facebook\u00a0comenz\u00f3 este jueves a proponer a sus\u00a0usuarios\u00a0revisar sus par\u00e1metros de confidencialidad para ayudarlos a controlar mejor lo que comparten o publican sobre la red social.<\/p>\n","protected":false},"author":3,"featured_media":8159,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-8158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8158"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8158\/revisions"}],"predecessor-version":[{"id":8160,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8158\/revisions\/8160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8159"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}