{"id":81652,"date":"2021-06-09T07:32:05","date_gmt":"2021-06-09T11:32:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81652"},"modified":"2021-06-09T07:32:09","modified_gmt":"2021-06-09T11:32:09","slug":"la-tarjeta-de-la-vacuna-genera-controversia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-tarjeta-de-la-vacuna-genera-controversia\/","title":{"rendered":"La tarjeta de la vacuna genera controversia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"330\" height=\"170\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/06\/la-tarjeta-de-la-vacuna-genera-controversia.jpeg\" alt=\"\" class=\"wp-image-81653\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/06\/la-tarjeta-de-la-vacuna-genera-controversia.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/06\/la-tarjeta-de-la-vacuna-genera-controversia-300x155.jpeg 300w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La pandemia ha desatado una discusi\u00f3n entre los empleadores, trabajadores y autoridades administrativas del trabajo en la cual se pre\u00adguntan si es posible que el empleador exija al trabajador someterse al examen y la vacuna del Covid-19 y cu\u00e1les ser\u00edan las consecuencias ante la nega\u00adtiva del trabajador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Constituci\u00f3n de la Republica Dominicana, el C\u00f3digo de Trabajo, la Jurisprudencia constante de la Suprema Cor\u00adte de Justicia y el Tribunal Constitucional no dejan dudas que no puedan ser interpretadas por un jurista conocedor del derecho del trabajo y r\u00e1pidamente los art\u00edculos 44, 46 y 88 dan respuestas a las interrogantes, en este sentido es una obligaci\u00f3n del trabajador someterse al examen m\u00e9dico a peticion del empleador para comprobar que no padece de una enfermedad infecto contagiosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es obligaci\u00f3n del empleador mantener la fabrica, la ofi\u00adcina y dem\u00e1s lugares en que deben ejecutarse los trabajos en las condiciones exigidas por las disposiciones sanitarias y proporcionar gratuitamente los medicamentos preventi\u00advos que indiquen las autoridades sanitarias en caso de en\u00adfermedades epid\u00e9micas cubriendo los costos del examen o la vacuna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El art\u00edculo 7 del Reglamento para la aplicaci\u00f3n del C\u00f3\u00addigo de Trabajo considera esta negativa como falta grave a las obligaciones del contrato de trabajo tipificada tambi\u00e9n como una causa de despido por el numeral 19 del art\u00edcu\u00adlo 88 del C\u00f3digo de Trabajo, que puede ser utilizada por el empleador para terminar el contrato de trabajo por des\u00adpido o el trabajador en caso de que el empleador no tome esas medidas, para terminar el contrato por dimisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCu\u00e1les ser\u00edan las consecuencias si el trabajador se niega al examen m\u00e9dico contra el COVI-19?<\/strong><br \/>El empleador podr\u00eda terminar el contrato de trabajo des\u00adpidiendo al trabajador con justa causa, al comprometer el trabajador por imprudencia o descuido inexcusable la se\u00adguridad del centro de trabajo de la empresa o las personas que all\u00ed se encuentren y por negarse el trabajador a adoptar las medidas preventivas y no seguir los procedimientos in\u00addicados por las autoridades competentes o el empleador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si el tribunal declara el despido justificado el trabajador no recibe las indemnizaciones que en la calle se les denomi\u00adna liquidaci\u00f3n o prestaciones laborales (preaviso y auxilio de cesant\u00eda); sin embargo la gran pregunta ser\u00eda:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfEstar\u00e1 en la obligaci\u00f3n el trabajador de vacunarse a so\u00adlicitud del empleador?<\/strong><br \/>Sin duda alguna, no vacunarse a petici\u00f3n del empleador y bajo las sugerencias de las autoridades sanitarias corre\u00adr\u00eda las mismas consecuencias del despido justificado, bajo la premisa de que este trabajador pone en riesgo la salud y su vida, la de los compa\u00f1eros de trabajo y toda la empresa, el art\u00edculo 88 en el numeral 15 del C\u00f3digo de Trabajo clara\u00admente establece que es causa de despido cuando el traba\u00adjador se niega a tomar las medidas preventivas o seguir los procedimientos indicados por las autoridades competentes o los empleadores que eviten enfermedades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es un compromiso y una obligaci\u00f3n legal para el trabaja\u00addor y el empleador bajo la existencia de una pandemia que puede afectar los derechos fundamentales colectivos (el orden p\u00fablico general se impone al orden p\u00fablico particu\u00adlar) tomar todas las medidas preventivas que puedan evi\u00adtar la enfermedad o la muerte de los trabajadores por Co\u00advid-19 , la vacuna m\u00e1s alla de un deber es una obligacion (ver art\u00edculos 42 y 74 de la Constituci\u00f3n y los art\u00edculos 44, 46 y 88 del C\u00f3digo Trabajo y 7 del Reglamento 258-93).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La pandemia ha desatado una discusi\u00f3n entre los empleadores, trabajadores y autoridades administrativas del trabajo en la cual se pre\u00adguntan si es posible que el empleador exija al trabajador someterse al examen y la vacuna del Covid-19 y cu\u00e1les ser\u00edan las consecuencias ante la nega\u00adtiva del trabajador. La Constituci\u00f3n de la Republica Dominicana, el C\u00f3digo de Trabajo, la Jurisprudencia constante de la Suprema Cor\u00adte de Justicia y el Tribunal Constitucional no dejan dudas que no puedan ser interpretadas por un jurista conocedor del derecho del trabajo y r\u00e1pidamente los art\u00edculos 44, 46 y 88 dan respuestas a las interrogantes, en este sentido es una obligaci\u00f3n del trabajador someterse al examen m\u00e9dico a peticion del empleador para comprobar que no padece de una enfermedad infecto contagiosa. Es obligaci\u00f3n del empleador mantener la fabrica, la ofi\u00adcina y dem\u00e1s lugares en que deben ejecutarse los trabajos en las condiciones exigidas por las disposiciones sanitarias y proporcionar gratuitamente los medicamentos preventi\u00advos que indiquen las autoridades sanitarias en caso de en\u00adfermedades epid\u00e9micas cubriendo los costos del examen o la vacuna. El art\u00edculo 7 del Reglamento para la aplicaci\u00f3n del C\u00f3\u00addigo de Trabajo considera esta negativa como falta grave a las obligaciones del contrato de trabajo tipificada tambi\u00e9n como una causa de despido por el numeral 19 del art\u00edcu\u00adlo 88 del C\u00f3digo de Trabajo, que puede ser utilizada por el empleador para terminar el contrato de trabajo por des\u00adpido o el trabajador en caso de que el empleador no tome esas medidas, para terminar el contrato por dimisi\u00f3n. \u00bfCu\u00e1les ser\u00edan las consecuencias si el trabajador se niega al examen m\u00e9dico contra el COVI-19?El empleador podr\u00eda terminar el contrato de trabajo des\u00adpidiendo al trabajador con justa causa, al comprometer el trabajador por imprudencia o descuido inexcusable la se\u00adguridad del centro de trabajo de la empresa o las personas que all\u00ed se encuentren y por negarse el trabajador a adoptar las medidas preventivas y no seguir los procedimientos in\u00addicados por las autoridades competentes o el empleador. Si el tribunal declara el despido justificado el trabajador no recibe las indemnizaciones que en la calle se les denomi\u00adna liquidaci\u00f3n o prestaciones laborales (preaviso y auxilio de cesant\u00eda); sin embargo la gran pregunta ser\u00eda: \u00bfEstar\u00e1 en la obligaci\u00f3n el trabajador de vacunarse a so\u00adlicitud del empleador?Sin duda alguna, no vacunarse a petici\u00f3n del empleador y bajo las sugerencias de las autoridades sanitarias corre\u00adr\u00eda las mismas consecuencias del despido justificado, bajo la premisa de que este trabajador pone en riesgo la salud y su vida, la de los compa\u00f1eros de trabajo y toda la empresa, el art\u00edculo 88 en el numeral 15 del C\u00f3digo de Trabajo clara\u00admente establece que es causa de despido cuando el traba\u00adjador se niega a tomar las medidas preventivas o seguir los procedimientos indicados por las autoridades competentes o los empleadores que eviten enfermedades. Es un compromiso y una obligaci\u00f3n legal para el trabaja\u00addor y el empleador bajo la existencia de una pandemia que puede afectar los derechos fundamentales colectivos (el orden p\u00fablico general se impone al orden p\u00fablico particu\u00adlar) tomar todas las medidas preventivas que puedan evi\u00adtar la enfermedad o la muerte de los trabajadores por Co\u00advid-19 , la vacuna m\u00e1s alla de un deber es una obligacion (ver art\u00edculos 42 y 74 de la Constituci\u00f3n y los art\u00edculos 44, 46 y 88 del C\u00f3digo Trabajo y 7 del Reglamento 258-93).<\/p>\n","protected":false},"author":9,"featured_media":81653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-81652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81652"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81652\/revisions"}],"predecessor-version":[{"id":81654,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81652\/revisions\/81654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81653"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}