{"id":8170,"date":"2014-09-06T13:57:57","date_gmt":"2014-09-06T17:57:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=8170"},"modified":"2014-09-06T13:57:57","modified_gmt":"2014-09-06T17:57:57","slug":"cientificos-revelan-como-predecir-el-futuro","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cientificos-revelan-como-predecir-el-futuro\/","title":{"rendered":"Cient\u00edficos revelan c\u00f3mo predecir el futuro"},"content":{"rendered":"<div>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/ver-el-futuro.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-8172\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/ver-el-futuro.jpg\" alt=\"ver el futuro\" width=\"630\" height=\"354\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/ver-el-futuro.jpg 630w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/09\/ver-el-futuro-300x168.jpg 300w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a>En tiempos de las turbulencias pol\u00edticas y econ\u00f3micas pronosticar el futuro se convierte en algo cada vez m\u00e1s vital. Un estudio pionero revela el secreto: es posible predecir el futuro y explica c\u00f3mo hacerlo.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div id=\"article_text\">Tim Harford, un economista y columnista brit\u00e1nico, en su art\u00edculo en &#8216;The Financial Times&#8217;\u00a0 publica un an\u00e1lisis detallado de este estudio.<\/p>\n<p>\u00abLa previsi\u00f3n es posible, y algunas personas\u00a0<span lang=\"ES\">\u2014&#8217;<\/span>superpronosticadores&#8217;<span lang=\"ES\">\u2014<\/span>\u00a0pueden predecir acontecimientos geopol\u00edticos con\u00a0una precisi\u00f3n mucho m\u00e1s all\u00e1 de la casualidad. Los &#8216;superpronosticadores&#8217; han sido capaces de mantener e incluso mejorar su rendimiento\u00bb, escribe Harford.<\/p>\n<p>Un psic\u00f3logo de origen canadiense, Philip Tetlock, quien sent\u00f3 las bases para la industria de la previsi\u00f3n econ\u00f3mica y geopol\u00edtica, en 1987 junto con sus colegas Don Moore y Barbara Mellers lanz\u00f3 \u00abun importante programa de nueva investigaci\u00f3n\u00bb financiado por la comunidad de inteligencia de\u00a0Estados Unidos.<\/p>\n<blockquote><p>La previsi\u00f3n es posible, y algunas personas \u2014&#8217;superpronosticadores&#8217;\u2014 pueden predecir acontecimientos geopol\u00edticos<\/p><\/blockquote>\n<p>La esencia del programa, que ha estado funcionando desde 2011, era una colecci\u00f3n de\u00a0previsiones\u00a0cuantificables como acontecimientos econ\u00f3micos y geopol\u00edticos: asuntos reales y acuciantes como el impago de Grecia, un ataque militar contra Ir\u00e1n, etc. Estas previsiones tomaron la forma de un torneo con miles de participantes.<\/p>\n<p>Cuando los psic\u00f3logos establecieron el proyecto Good Judgment Project (Proyecto del Buen Juicio), el principio b\u00e1sico era recoger predicciones espec\u00edficas sobre el futuro y despu\u00e9s comprobar si se hab\u00edan hecho realidad. Todo esto sugiere que, entre las diversas estrategias empleadas por los &#8216;superpronosticadores&#8217; del Proyecto del Buen Juicio, la explicaci\u00f3n m\u00e1s b\u00e1sica de su \u00e9xito es que tienen el objetivo\u00a0intransigente de\u00a0predecir el futuro, y esto es \u00fanico.<br \/>\nReciben retroalimentaci\u00f3n continua sobre el \u00e9xito y el fracaso de todos los pron\u00f3sticos, y no hay espacio para el radicalismo, la originalidad, la audacia, las devociones convencionales, el nihilismo o el ingenio.<\/p>\n<p>El director del proyecto, Terry Murray, dice simplemente: \u00abLo \u00fanico que importa es la respuesta correcta\u00bb.<\/p>\n<p>En general, se destaca que los mejores pronosticadores son, seg\u00fan Tetlock, los llamados &#8216;zorros&#8217; con respecto a los &#8216;erizos&#8217;. Tetlock utiliza este t\u00e9rmino para referirse a un estilo particular de pensar: amplio en lugar de profundo, m\u00e1s intuitivo que l\u00f3gico, sea autocr\u00edtico en vez de querer tener la raz\u00f3n, y ad hoc en vez de sistem\u00e1tico.<\/p>\n<p>Barbara Mellers, por su parte, destaca que el estilo de pensamiento que m\u00e1s se asocia con la realizaci\u00f3n de\u00a0mejores previsiones es algo que los psic\u00f3logos califican de \u00abpensamiento de mentalidad abierta y activa\u00bb.\u00a0 Un cuestionario para diagnosticar este rasgo invita a las personas a calificar hasta qu\u00e9 punto est\u00e1n de acuerdo o en desacuerdo con afirmaciones como: \u00abCambiar de opini\u00f3n es un signo de debilidad\u00bb. El proyecto encontr\u00f3 que los pronosticadores de \u00e9xito no tienen miedo a cambiar de opini\u00f3n, les gusta\u00a0buscar\u00a0opiniones en conflicto\u00a0y se sienten c\u00f3modos pensando que una nueva\u00a0prueba puede obligarlos a abandonar una vieja visi\u00f3n del mundo y abrazar algo nuevo.<\/p>\n<h2>Cu\u00e1l es el secreto de mirar hacia el futuro<\/h2>\n<p>Los resultados iniciales del Proyecto del Buen Juicio sugieren los siguientes enfoques. En primer lugar, una formaci\u00f3n b\u00e1sica en razonamiento probabil\u00edstico ayuda a producir mejores pron\u00f3sticos. En segundo lugar, los equipos de buenos pronosticadores producen mejores resultados que los buenos pronosticadores que trabajan solos.\u00a0 En tercer lugar, las personas con una mente activa y abierta prosperan como pronosticadores.<\/p>\n<h2>C\u00f3mo convertirse en un superpronosticador<\/h2>\n<p>A algunos participantes del Proyecto del Buen Juicio se les dieron consejos sobre c\u00f3mo transformar su conocimiento sobre el mundo en un pron\u00f3stico probabil\u00edstico:<\/p>\n<p>\u25cf Las comparaciones son importantes: usar comparaciones relevantes como punto de partida;<\/p>\n<p>\u25cf Las tendencias hist\u00f3ricas pueden ayudar: estudiar la historia a menos que tenga una raz\u00f3n de peso para esperar un cambio;<\/p>\n<p>\u25cf Promedio de opiniones: los expertos no siempre est\u00e1n de acuerdo unos con otros; por lo tanto, investigue lo que piensan y escoja un t\u00e9rmino medio;<\/p>\n<p>\u25cf Modelos matem\u00e1ticos: cuando las predicciones basadas en modelos est\u00e1n disponibles, se deben tomar en cuenta;<\/p>\n<p>\u25cf Existen prejuicios predecibles y se debe tener en cuenta. No deje que sus esperanzas influyan en sus previsiones, por ejemplo; no se aferre obstinadamente a las previsiones antiguas cuando analice noticias nuevas.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>En tiempos de las turbulencias pol\u00edticas y econ\u00f3micas pronosticar el futuro se convierte en algo cada vez m\u00e1s vital. Un estudio pionero revela el secreto: es posible predecir el futuro y explica c\u00f3mo hacerlo.<\/p>\n","protected":false},"author":3,"featured_media":8172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-8170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=8170"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8170\/revisions"}],"predecessor-version":[{"id":8173,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/8170\/revisions\/8173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/8172"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=8170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=8170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=8170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}