{"id":81766,"date":"2021-06-20T20:43:18","date_gmt":"2021-06-21T00:43:18","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81766"},"modified":"2021-06-20T20:43:22","modified_gmt":"2021-06-21T00:43:22","slug":"ocho-cosas-que-debes-saber-sobre-nuevas-regulaciones-a-las-prestadoras-que-ofrecen-acceso-a-internet","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ocho-cosas-que-debes-saber-sobre-nuevas-regulaciones-a-las-prestadoras-que-ofrecen-acceso-a-internet\/","title":{"rendered":"Ocho cosas que debes saber sobre nuevas regulaciones a las prestadoras que ofrecen acceso a internet"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/06\/as.jpg\" alt=\"\" class=\"wp-image-81767\" width=\"492\" height=\"252\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/06\/as.jpg 332w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/06\/as-300x154.jpg 300w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nA partir del&nbsp;<strong>1 de julio de 2021<\/strong>, entrar\u00e1 en vigencia un nuevo reglamento del Instituto Dominicano de las Telecomunicaciones (Indotel) que regula las relaciones entre las prestadoras que ofrecen acceso a internet y sus usuarios en cualquiera de sus modalidades: postpago o prepago, fijo o m\u00f3vil, independientemente de la tecnolog\u00eda que se utilice.&nbsp;&nbsp;La entidad aclara que este reglamentar\u00e1 la prestaci\u00f3n del servicio, sea contratado en conjunto o de forma separada.&nbsp;&nbsp;Te presentamos&nbsp;<strong>ocho nuevas medidas que deber\u00e1s conocer para defender tus derechos<\/strong>&nbsp;ante cualquier prestadora de internet:&nbsp;&nbsp;<strong>1<\/strong>. Las prestadoras deben&nbsp;<strong>transparentar cualquier l\u00edmite que pudiera haber en sus planes<\/strong>, que en ciertos casos estaban ambiguos u omitidos del contrato o pol\u00edtica de uso del servicio.&nbsp;&nbsp;El Indotel evaluar\u00e1 si los topes anunciados por las prestadoras resultan razonables, debido al incremento de la demanda de servicios digitales por parte de los usuarios y las caracter\u00edsticas de los servicios contratados.&nbsp;&nbsp;<strong>2.&nbsp;<\/strong>Las prestadoras deber\u00e1n presentar al Indotel, con la entrada en vigencia del Reglamento, un&nbsp;<strong>plan de transici\u00f3n a IPv6&nbsp;<\/strong>a partir de la fecha citada arriba.&nbsp;&nbsp;<strong>3.<\/strong>&nbsp;En cuanto a los casos de aver\u00edas, el reglamento establece que<strong>&nbsp;los usuarios tendr\u00e1n derecho a la aplicaci\u00f3n de un cr\u00e9dito por la aver\u00eda, total o parcial del servicio,<\/strong>&nbsp;por causas que no sean imputables al usuario, salvo casos de fuerza mayor.&nbsp;<strong>4.<\/strong><strong>Las prestadoras deber\u00e1n generar un cr\u00e9dito a favor del usuario en caso de degradaciones en el servicio de internet fijo<\/strong>&nbsp;si la velocidad recibida es 10% menor a la contratada, de conformidad con las condiciones establecidas en el referido reglamento.&nbsp;&nbsp;<strong>5.&nbsp;<\/strong>Las prestadoras deber\u00e1n&nbsp;<strong>informar a los usuarios sobre los principales factores que podr\u00edan limitar o degradar la velocidad efectiva del servicio<\/strong>&nbsp;experimentada por el usuario, diferenciando aquellos sobre los que s\u00ed tiene control la prestadora y los que son ajenos a la misma.&nbsp;&nbsp;<strong>6.<\/strong>&nbsp;Estas compa\u00f1\u00edas tendr\u00e1n que&nbsp;<strong>garantizar la accesibilidad de las personas con discapacidad<\/strong>&nbsp;mediante la asistencia adecuada que asegure su acceso a las Tecnolog\u00edas de la Comunicaci\u00f3n (TIC).&nbsp;&nbsp;<strong>7.&nbsp;<\/strong>El usuario tiene derecho a acceder a internet bajo el principio de neutralidad de la red, en el cual&nbsp;<strong>las concesionarias del servicio no podr\u00e1n bloquear, interferir, ralentizar o discriminar contenidos,<\/strong>&nbsp;aplicaciones o servicios disponibles en internet&nbsp;<strong>8.<\/strong>&nbsp;Los usuarios&nbsp;<strong>podr\u00e1n acceder, descargar, cargar, subir o distribuir libremente informaci\u00f3n, contenidos, aplicaciones y servicios legales<\/strong>, sin discriminaci\u00f3n o restricci\u00f3n por parte de las prestadoras del servicio de acceso a internet, siempre y cuando no contravenga las leyes y reglamentaciones nacionales.&nbsp;&nbsp;<strong>Caso reciente&nbsp;<\/strong>Este fin de semana se desataron cr\u00edticas en las redes sociales porque la compa\u00f1\u00eda de telecomunicaciones Claro explic\u00f3 que establec\u00eda el l\u00edmite de consumo de internet en 2,000 gigabytes (GB).&nbsp;En un comunicado, la empresa explic\u00f3 que el l\u00edmite est\u00e1 fijado en dos terabytes (TB), diez veces m\u00e1s que la cantidad anteriormente se\u00f1alada para el servicio de internet fijo para residencias, tal como regula la resoluci\u00f3n del Indotel.&nbsp;\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del&nbsp;1 de julio de 2021, entrar\u00e1 en vigencia un nuevo reglamento del Instituto Dominicano de las Telecomunicaciones (Indotel) que regula las relaciones entre las prestadoras que ofrecen acceso a internet y sus usuarios en cualquiera de sus modalidades: postpago o prepago, fijo o m\u00f3vil, independientemente de la tecnolog\u00eda que se utilice.&nbsp;&nbsp;La entidad aclara que este reglamentar\u00e1 la prestaci\u00f3n del servicio, sea contratado en conjunto o de forma separada.&nbsp;&nbsp;Te presentamos&nbsp;ocho nuevas medidas que deber\u00e1s conocer para defender tus derechos&nbsp;ante cualquier prestadora de internet:&nbsp;&nbsp;1. Las prestadoras deben&nbsp;transparentar cualquier l\u00edmite que pudiera haber en sus planes, que en ciertos casos estaban ambiguos u omitidos del contrato o pol\u00edtica de uso del servicio.&nbsp;&nbsp;El Indotel evaluar\u00e1 si los topes anunciados por las prestadoras resultan razonables, debido al incremento de la demanda de servicios digitales por parte de los usuarios y las caracter\u00edsticas de los servicios contratados.&nbsp;&nbsp;2.&nbsp;Las prestadoras deber\u00e1n presentar al Indotel, con la entrada en vigencia del Reglamento, un&nbsp;plan de transici\u00f3n a IPv6&nbsp;a partir de la fecha citada arriba.&nbsp;&nbsp;3.&nbsp;En cuanto a los casos de aver\u00edas, el reglamento establece que&nbsp;los usuarios tendr\u00e1n derecho a la aplicaci\u00f3n de un cr\u00e9dito por la aver\u00eda, total o parcial del servicio,&nbsp;por causas que no sean imputables al usuario, salvo casos de fuerza mayor.&nbsp;4.Las prestadoras deber\u00e1n generar un cr\u00e9dito a favor del usuario en caso de degradaciones en el servicio de internet fijo&nbsp;si la velocidad recibida es 10% menor a la contratada, de conformidad con las condiciones establecidas en el referido reglamento.&nbsp;&nbsp;5.&nbsp;Las prestadoras deber\u00e1n&nbsp;informar a los usuarios sobre los principales factores que podr\u00edan limitar o degradar la velocidad efectiva del servicio&nbsp;experimentada por el usuario, diferenciando aquellos sobre los que s\u00ed tiene control la prestadora y los que son ajenos a la misma.&nbsp;&nbsp;6.&nbsp;Estas compa\u00f1\u00edas tendr\u00e1n que&nbsp;garantizar la accesibilidad de las personas con discapacidad&nbsp;mediante la asistencia adecuada que asegure su acceso a las Tecnolog\u00edas de la Comunicaci\u00f3n (TIC).&nbsp;&nbsp;7.&nbsp;El usuario tiene derecho a acceder a internet bajo el principio de neutralidad de la red, en el cual&nbsp;las concesionarias del servicio no podr\u00e1n bloquear, interferir, ralentizar o discriminar contenidos,&nbsp;aplicaciones o servicios disponibles en internet&nbsp;8.&nbsp;Los usuarios&nbsp;podr\u00e1n acceder, descargar, cargar, subir o distribuir libremente informaci\u00f3n, contenidos, aplicaciones y servicios legales, sin discriminaci\u00f3n o restricci\u00f3n por parte de las prestadoras del servicio de acceso a internet, siempre y cuando no contravenga las leyes y reglamentaciones nacionales.&nbsp;&nbsp;Caso reciente&nbsp;Este fin de semana se desataron cr\u00edticas en las redes sociales porque la compa\u00f1\u00eda de telecomunicaciones Claro explic\u00f3 que establec\u00eda el l\u00edmite de consumo de internet en 2,000 gigabytes (GB).&nbsp;En un comunicado, la empresa explic\u00f3 que el l\u00edmite est\u00e1 fijado en dos terabytes (TB), diez veces m\u00e1s que la cantidad anteriormente se\u00f1alada para el servicio de internet fijo para residencias, tal como regula la resoluci\u00f3n del Indotel.&nbsp;<\/p>\n","protected":false},"author":9,"featured_media":81767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-81766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81766"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81766\/revisions"}],"predecessor-version":[{"id":81768,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81766\/revisions\/81768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81767"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}