{"id":81990,"date":"2021-07-12T17:31:13","date_gmt":"2021-07-12T21:31:13","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=81990"},"modified":"2021-07-12T17:31:17","modified_gmt":"2021-07-12T21:31:17","slug":"el-millonario-branson-cumple-su-sueno-y-llega-al-espacio-en-su-propio-avion","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-millonario-branson-cumple-su-sueno-y-llega-al-espacio-en-su-propio-avion\/","title":{"rendered":"El millonario Branson cumple su sue\u00f1o y llega al espacio en su propio avi\u00f3n"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"194\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/07\/descarga.jpg\" alt=\"\" class=\"wp-image-81991\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nEl multimillonario brit\u00e1nico Richard Branson alcanz\u00f3 este domingo una meta largamente anhelada y finalmente lleg\u00f3 al espacio a bordo de un avi\u00f3n de su propia compa\u00f1\u00eda, Virgin Galactic, tras despegar desde el desierto de Nuevo M\u00e9xico y superar m\u00e1s de 50 millas (80 km.) de altura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTodo fue m\u00e1gico\u00bb, dijo un jubiloso Branson luego de que el plateado avi\u00f3n espacial VSS Unity retornar\u00e1 una hora despu\u00e9s a la pista de aterrizaje de la base Spaceport America, con Branson y los otros cinco ocupantes a bordo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHe so\u00f1ado con este momento desde que era un ni\u00f1o, pero nada me hab\u00eda preparado para tener una vista de la Tierra desde el espacio\u00bb, reconoci\u00f3 el empresario ante periodistas y miembros de Virgin Galactic, la firma que fund\u00f3 en 2004 para realizar vuelos comerciales al espacio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco despu\u00e9s, el brit\u00e1nico y los miembros de la misi\u00f3n Unity 22 recib\u00edan una insignia que los acreditaba como astronautas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conclu\u00eda as\u00ed una jornada que empez\u00f3 con un retraso de 90 minutos a causa del mal tiempo, y en el que el avi\u00f3n se separ\u00f3 de la nave propulsora VMS Eve, llamada as\u00ed en honor a la madre de Branson, luego de alcanzar una altitud de 10.000 pies (poco m\u00e1s de 3 kil\u00f3metros).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ha sido el primero de los que forman parte de \u00abla carrera espacial de los millonarios\u00bb, como los medios estadounidenses han llamado a las iniciativas espaciales que encabezan Jeff Bezos, hasta hace unos d\u00edas director ejecutivo del gigante Amazon, y Elon Musk, fundador de la firma de autos el\u00e9ctricos Tesla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Branson, de 70 a\u00f1os, ha quitado le\u00f1a al asunto, al asegurar que no existe tal carrera, e incluso Musk, fundador de la firma privada SpaceX, fue uno de los asistentes al despegue hoy en Nuevo M\u00e9xico y hasta le dese\u00f3 buena suerte en un mensaje de Twitter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bezos, quien en unos d\u00edas viajar\u00e1 tambi\u00e9n al espacio en la nave New Shepard, dise\u00f1ada y construida por su compa\u00f1\u00eda Blue Origin, se\u00f1al\u00f3 este fin de semana que los de Virgin Galatic no son exactamente aviones espaciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El creador de la mayor empresa de venta al detalle del mundo asever\u00f3 que es aceptado mundialmente que por arriba de la l\u00ednea imaginaria de Karman, situada a 62 millas (99,7 km) de la Tierra, est\u00e1 el espacio exterior y por debajo la atm\u00f3sfera terrestre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este domingo, no obstante, rebaj\u00f3 tambi\u00e9n las diferencias y felicit\u00f3 al tambi\u00e9n fil\u00e1ntropo por su aventura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abFelicitaciones por el vuelo. \u00a1No puedo esperar para unirme al club!\u00bb, escribi\u00f3 Bezos en su cuenta de Instagram.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>UNA \u00abREVOLUCI\u00d3N\u00bb AL SECTOR TURISMO<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Spaceport America, una estructura futurista levantada en medio del desierto y base de operaciones de Virgin Galactic, se ha vivido este domingo un ambiente de j\u00fabilo tras a\u00f1os de trabajar en la meta de realizar vuelos espaciales comerciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este aeropuerto, de propiedad estatal ubicado en la localidad de Truth or Consequences (Nuevo M\u00e9xico), se hab\u00edan completado recientemente tres vuelos de prueba al espacio, algunos con personas a bordo, si bien el de hoy era el primero \u00abcompletamente tripulado\u00bb y con su fundador y principal inversionista a bordo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Branson tuvo como tarea evaluar la experiencia de los futuros clientes de los vuelos espaciales que haga Virgin Galatic, compa\u00f1\u00eda que tiene previsto a\u00fan por lo menos otros tres vuelos de prueba como el de este domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viajaron con \u00e9l Beth Moses, instructora jefa de astronautas; Colin Bennet, ingeniero de operaciones, y Sirisha Bandla, vicepresidenta de asuntos gubernamentales e investigaci\u00f3n. Los pilotos del VSS Unity son Dave Mackay y Michael Masucci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rick Homans, que fue director de las instalaciones de Spaceport America, dijo a Efe antes del despegue que \u00abesto es solo el principio\u00bb en lo que respecta a una industria que pretende \u00abrevolucionar\u00bb el sector del turismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTodo el mundo est\u00e1 pendiente de lo que pasa hoy aqu\u00ed. Pero estamos en el inicio de algo que ser\u00e1 much\u00edsimo m\u00e1s grande, as\u00ed que toda la inversi\u00f3n que se ha hecho va a valer mucho la pena de cara a las pr\u00f3ximas d\u00e9cadas\u00bb, declar\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su turno, el alcalde de Las Cruces, Kenneth Miyagishima, asegur\u00f3 que el proyecto de Branson \u00abva a servir de modelo para otros pa\u00edses para poner en evidencia lo importante que es el turismo espacial\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn un futuro cercano, los que puedan viajar a bordo de estas naves van a poder estar en cualquier parte del mundo en pocas horas y eso era impensable hasta ahora\u00bb, dijo Miyagishima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Virgin Galactic espera poder empezar sus viajes a partir del pr\u00f3ximo a\u00f1o a clientes que han pagado hasta 250.000 d\u00f3lares por sus billetes. Seg\u00fan la compa\u00f1\u00eda, lleva recaudados 80 millones de d\u00f3lares en ventas y dep\u00f3sitos.\n\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El multimillonario brit\u00e1nico Richard Branson alcanz\u00f3 este domingo una meta largamente anhelada y finalmente lleg\u00f3 al espacio a bordo de un avi\u00f3n de su propia compa\u00f1\u00eda, Virgin Galactic, tras despegar desde el desierto de Nuevo M\u00e9xico y superar m\u00e1s de 50 millas (80 km.) de altura. \u00abTodo fue m\u00e1gico\u00bb, dijo un jubiloso Branson luego de que el plateado avi\u00f3n espacial VSS Unity retornar\u00e1 una hora despu\u00e9s a la pista de aterrizaje de la base Spaceport America, con Branson y los otros cinco ocupantes a bordo. \u00abHe so\u00f1ado con este momento desde que era un ni\u00f1o, pero nada me hab\u00eda preparado para tener una vista de la Tierra desde el espacio\u00bb, reconoci\u00f3 el empresario ante periodistas y miembros de Virgin Galactic, la firma que fund\u00f3 en 2004 para realizar vuelos comerciales al espacio. Poco despu\u00e9s, el brit\u00e1nico y los miembros de la misi\u00f3n Unity 22 recib\u00edan una insignia que los acreditaba como astronautas. Conclu\u00eda as\u00ed una jornada que empez\u00f3 con un retraso de 90 minutos a causa del mal tiempo, y en el que el avi\u00f3n se separ\u00f3 de la nave propulsora VMS Eve, llamada as\u00ed en honor a la madre de Branson, luego de alcanzar una altitud de 10.000 pies (poco m\u00e1s de 3 kil\u00f3metros). Ha sido el primero de los que forman parte de \u00abla carrera espacial de los millonarios\u00bb, como los medios estadounidenses han llamado a las iniciativas espaciales que encabezan Jeff Bezos, hasta hace unos d\u00edas director ejecutivo del gigante Amazon, y Elon Musk, fundador de la firma de autos el\u00e9ctricos Tesla. Branson, de 70 a\u00f1os, ha quitado le\u00f1a al asunto, al asegurar que no existe tal carrera, e incluso Musk, fundador de la firma privada SpaceX, fue uno de los asistentes al despegue hoy en Nuevo M\u00e9xico y hasta le dese\u00f3 buena suerte en un mensaje de Twitter. Bezos, quien en unos d\u00edas viajar\u00e1 tambi\u00e9n al espacio en la nave New Shepard, dise\u00f1ada y construida por su compa\u00f1\u00eda Blue Origin, se\u00f1al\u00f3 este fin de semana que los de Virgin Galatic no son exactamente aviones espaciales. El creador de la mayor empresa de venta al detalle del mundo asever\u00f3 que es aceptado mundialmente que por arriba de la l\u00ednea imaginaria de Karman, situada a 62 millas (99,7 km) de la Tierra, est\u00e1 el espacio exterior y por debajo la atm\u00f3sfera terrestre. Este domingo, no obstante, rebaj\u00f3 tambi\u00e9n las diferencias y felicit\u00f3 al tambi\u00e9n fil\u00e1ntropo por su aventura. \u00abFelicitaciones por el vuelo. \u00a1No puedo esperar para unirme al club!\u00bb, escribi\u00f3 Bezos en su cuenta de Instagram. UNA \u00abREVOLUCI\u00d3N\u00bb AL SECTOR TURISMO En Spaceport America, una estructura futurista levantada en medio del desierto y base de operaciones de Virgin Galactic, se ha vivido este domingo un ambiente de j\u00fabilo tras a\u00f1os de trabajar en la meta de realizar vuelos espaciales comerciales. En este aeropuerto, de propiedad estatal ubicado en la localidad de Truth or Consequences (Nuevo M\u00e9xico), se hab\u00edan completado recientemente tres vuelos de prueba al espacio, algunos con personas a bordo, si bien el de hoy era el primero \u00abcompletamente tripulado\u00bb y con su fundador y principal inversionista a bordo. Branson tuvo como tarea evaluar la experiencia de los futuros clientes de los vuelos espaciales que haga Virgin Galatic, compa\u00f1\u00eda que tiene previsto a\u00fan por lo menos otros tres vuelos de prueba como el de este domingo. Viajaron con \u00e9l Beth Moses, instructora jefa de astronautas; Colin Bennet, ingeniero de operaciones, y Sirisha Bandla, vicepresidenta de asuntos gubernamentales e investigaci\u00f3n. Los pilotos del VSS Unity son Dave Mackay y Michael Masucci. Rick Homans, que fue director de las instalaciones de Spaceport America, dijo a Efe antes del despegue que \u00abesto es solo el principio\u00bb en lo que respecta a una industria que pretende \u00abrevolucionar\u00bb el sector del turismo. \u00abTodo el mundo est\u00e1 pendiente de lo que pasa hoy aqu\u00ed. Pero estamos en el inicio de algo que ser\u00e1 much\u00edsimo m\u00e1s grande, as\u00ed que toda la inversi\u00f3n que se ha hecho va a valer mucho la pena de cara a las pr\u00f3ximas d\u00e9cadas\u00bb, declar\u00f3. A su turno, el alcalde de Las Cruces, Kenneth Miyagishima, asegur\u00f3 que el proyecto de Branson \u00abva a servir de modelo para otros pa\u00edses para poner en evidencia lo importante que es el turismo espacial\u00bb. \u00abEn un futuro cercano, los que puedan viajar a bordo de estas naves van a poder estar en cualquier parte del mundo en pocas horas y eso era impensable hasta ahora\u00bb, dijo Miyagishima. Virgin Galactic espera poder empezar sus viajes a partir del pr\u00f3ximo a\u00f1o a clientes que han pagado hasta 250.000 d\u00f3lares por sus billetes. Seg\u00fan la compa\u00f1\u00eda, lleva recaudados 80 millones de d\u00f3lares en ventas y dep\u00f3sitos.<\/p>\n","protected":false},"author":9,"featured_media":81991,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-81990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=81990"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81990\/revisions"}],"predecessor-version":[{"id":81992,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/81990\/revisions\/81992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/81991"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=81990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=81990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=81990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}