{"id":82974,"date":"2021-10-04T09:48:10","date_gmt":"2021-10-04T13:48:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=82974"},"modified":"2021-10-04T09:48:15","modified_gmt":"2021-10-04T13:48:15","slug":"cecilia-garcia-protagoniza-un-concierto-de-lujo-y-recibe-la-mas-linda-de-las-sorpresas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cecilia-garcia-protagoniza-un-concierto-de-lujo-y-recibe-la-mas-linda-de-las-sorpresas\/","title":{"rendered":"Cecilia Garc\u00eda protagoniza un concierto de lujo y recibe la m\u00e1s linda de las sorpresas"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/cecilia-garcia-protagoniza-un-concierto-de-lujo-y-recibe-la-mas-linda-de-las-sorpresas.jpeg\" alt=\"\" class=\"wp-image-82975\" width=\"188\" height=\"125\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/cecilia-garcia-protagoniza-un-concierto-de-lujo-y-recibe-la-mas-linda-de-las-sorpresas.jpeg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/cecilia-garcia-protagoniza-un-concierto-de-lujo-y-recibe-la-mas-linda-de-las-sorpresas-300x200.jpeg 300w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Con la ovaci\u00f3n del p\u00fablico y la interpretaci\u00f3n de la emblem\u00e1tica canci\u00f3n \u201cMediterr\u00e1neo\u201d, popularizada por Joan Manuel Serrat, la polifac\u00e9tica artista dominicana Cecilia Garc\u00eda celebr\u00f3 con \u00e9xito su primer concierto en el Teatro Nacional Eduardo Brito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCecilia en todos los tiempos\u201d es el t\u00edtulo de este concierto que era un sue\u00f1o acariciado en su coraz\u00f3n y que fue motivado por su hijo Hat\u00fcey, incluyendo el concepto de cantar los temas que ella atesora y que sus admiradores tambi\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras cantar un popurr\u00ed de los boleros los temas \u201cNo me platiques\u201d, \u201cInolvidable\u201d, y \u201cTe extra\u00f1o\u201d, de Armando Manzanero, la arista dijo \u201c\u00a1qu\u00e9 linda noche!, es muy especial porque est\u00e1n ustedes aqu\u00ed escuchando las canciones que les gustan\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 adem\u00e1s que, en sus 54 a\u00f1os de trayectoria, por sus actuaciones ha estado en la piel de otras personas, \u201cpero como Cecilia, ahora; y no est\u00e1 mal para ser la primera vez\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esa amena conversaci\u00f3n que estableci\u00f3 con su p\u00fablico la noche del pasado viernes, agradeci\u00f3 la presencia del presidente de la Rep\u00fablica, Luis Abinader y su esposa Raquel Arbaje. Tambi\u00e9n, valor\u00f3 la presencia de la comunicadora Milagros Germ\u00e1n, a quien le unen muchos afectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como esa era una noche de estreno, la artista confes\u00f3 que era la primera vez que interpretaba \u201cL\u00eda\u201d, una inspiradora canci\u00f3n que Ana Bel\u00e9n hizo famosa. De Espa\u00f1a volvi\u00f3 al pa\u00eds para cantar \u201cDerroche\u201d, ic\u00f3nico tema autor\u00eda de Manuel Jim\u00e9nez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1Sorpresas, sorpresas!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cecilia Garc\u00eda dijo que, en la producci\u00f3n de un concierto de esa naturaleza, siempre se contempla llevar a un o varios artistas sorpresas, sin embargo, en este sobrepas\u00f3 la imaginaci\u00f3n del p\u00fablico, y es que tras interpretar la canci\u00f3n \u201cCuando te beso\u201d, del maestro Juan Luis Guerra, subi\u00f3 al escenario su hijo Luis Miguel De Camps, ministro de Trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro de Trabajo fue la gran sorpresa de la noche, porque muchos desconoc\u00edan su talento art\u00edstico, el cual demostr\u00f3 cantando el tema \u201cHasta que me olvides\u201d, escrito por Juan Luis Guerra y hecho famoso en la voz del \u201cSol de M\u00e9xico\u201d, Luis Miguel. Con esta interpretaci\u00f3n, \u00e9l se conquist\u00f3 al p\u00fablico que le ped\u00eda otra.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros invitados sorpresas fue el tenor l\u00edrico Pedro Pablo Reyes, quien fascin\u00f3 con su inigualable interpretaci\u00f3n de \u201cUna primavera para el mundo\u201d, de nuestro poeta Ren\u00e9 del Risco Berm\u00fadez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En varios momentos del concierto, cont\u00f3 con el acompa\u00f1amiento de los artistas Carolina Rivas, Ana Rivas y Carlos Luis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la ovaci\u00f3n del p\u00fablico y la interpretaci\u00f3n de la emblem\u00e1tica canci\u00f3n \u201cMediterr\u00e1neo\u201d, popularizada por Joan Manuel Serrat, la polifac\u00e9tica artista dominicana Cecilia Garc\u00eda celebr\u00f3 con \u00e9xito su primer concierto en el Teatro Nacional Eduardo Brito. \u201cCecilia en todos los tiempos\u201d es el t\u00edtulo de este concierto que era un sue\u00f1o acariciado en su coraz\u00f3n y que fue motivado por su hijo Hat\u00fcey, incluyendo el concepto de cantar los temas que ella atesora y que sus admiradores tambi\u00e9n. Tras cantar un popurr\u00ed de los boleros los temas \u201cNo me platiques\u201d, \u201cInolvidable\u201d, y \u201cTe extra\u00f1o\u201d, de Armando Manzanero, la arista dijo \u201c\u00a1qu\u00e9 linda noche!, es muy especial porque est\u00e1n ustedes aqu\u00ed escuchando las canciones que les gustan\u201d. Destac\u00f3 adem\u00e1s que, en sus 54 a\u00f1os de trayectoria, por sus actuaciones ha estado en la piel de otras personas, \u201cpero como Cecilia, ahora; y no est\u00e1 mal para ser la primera vez\u201d. En esa amena conversaci\u00f3n que estableci\u00f3 con su p\u00fablico la noche del pasado viernes, agradeci\u00f3 la presencia del presidente de la Rep\u00fablica, Luis Abinader y su esposa Raquel Arbaje. Tambi\u00e9n, valor\u00f3 la presencia de la comunicadora Milagros Germ\u00e1n, a quien le unen muchos afectos. Como esa era una noche de estreno, la artista confes\u00f3 que era la primera vez que interpretaba \u201cL\u00eda\u201d, una inspiradora canci\u00f3n que Ana Bel\u00e9n hizo famosa. De Espa\u00f1a volvi\u00f3 al pa\u00eds para cantar \u201cDerroche\u201d, ic\u00f3nico tema autor\u00eda de Manuel Jim\u00e9nez. \u00a1Sorpresas, sorpresas! Cecilia Garc\u00eda dijo que, en la producci\u00f3n de un concierto de esa naturaleza, siempre se contempla llevar a un o varios artistas sorpresas, sin embargo, en este sobrepas\u00f3 la imaginaci\u00f3n del p\u00fablico, y es que tras interpretar la canci\u00f3n \u201cCuando te beso\u201d, del maestro Juan Luis Guerra, subi\u00f3 al escenario su hijo Luis Miguel De Camps, ministro de Trabajo. El ministro de Trabajo fue la gran sorpresa de la noche, porque muchos desconoc\u00edan su talento art\u00edstico, el cual demostr\u00f3 cantando el tema \u201cHasta que me olvides\u201d, escrito por Juan Luis Guerra y hecho famoso en la voz del \u201cSol de M\u00e9xico\u201d, Luis Miguel. Con esta interpretaci\u00f3n, \u00e9l se conquist\u00f3 al p\u00fablico que le ped\u00eda otra.&nbsp; Otros invitados sorpresas fue el tenor l\u00edrico Pedro Pablo Reyes, quien fascin\u00f3 con su inigualable interpretaci\u00f3n de \u201cUna primavera para el mundo\u201d, de nuestro poeta Ren\u00e9 del Risco Berm\u00fadez. En varios momentos del concierto, cont\u00f3 con el acompa\u00f1amiento de los artistas Carolina Rivas, Ana Rivas y Carlos Luis.<\/p>\n","protected":false},"author":9,"featured_media":82975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-82974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/82974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=82974"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/82974\/revisions"}],"predecessor-version":[{"id":82976,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/82974\/revisions\/82976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/82975"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=82974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=82974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=82974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}