{"id":83115,"date":"2021-10-12T14:46:10","date_gmt":"2021-10-12T18:46:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83115"},"modified":"2021-10-12T14:46:15","modified_gmt":"2021-10-12T18:46:15","slug":"con-un-jonron-de-longoria-gigantes-se-imponen-1-0-a-dodgers","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/con-un-jonron-de-longoria-gigantes-se-imponen-1-0-a-dodgers\/","title":{"rendered":"Con un jonr\u00f3n de Longoria, Gigantes se imponen 1-0 a Dodgers"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/pelo.jpg\" alt=\"\" class=\"wp-image-83116\" width=\"192\" height=\"102\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/pelo.jpg 335w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/pelo-300x159.jpg 300w\" sizes=\"auto, (max-width: 192px) 100vw, 192px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Evan Longoria jonrone\u00f3 ante Max Scherzer en el quinto inning y los Gigantes de San Francisco derrotaron 1-0 el lunes a los Dodgers de Los \u00c1ngeles en una noche ventosa, para ponerse 2-1 arriba en su serie divisional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los \u00c1ngeles estuvo cerca de igualar la pizarra con dos outs en el noveno, cuando el bateador emergente Gavin Lux peg\u00f3 un buen batazo que envi\u00f3 la pelota entre el jard\u00edn izquierdo y el central. Pero el viento la desvi\u00f3 y la pelota acab\u00f3 atrapada, para desconcierto de Lux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chris Taylor envi\u00f3 un elevado al centro, pero esa pelota tambi\u00e9n acab\u00f3 en manos de los Gigantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCreo que cualquier otra noche, la pelota de CT, la pelota de Gavin Lux, habr\u00edan sido jonrones, s\u00ed\u201d, dijo el m\u00e1nager de los Dodgers, Dave Roberts.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue la segunda blanqueada de los Gigantes en la serie al mejor de cinco, tras ganar el primer juego 4-0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El martes se celebra el cuarto duelo en el Dodger Stadium, mientras que el quinto se disputar\u00eda el jueves en San Francisco de ser necesario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Dodgers derrotaron 9-2 a los Gigantes en el segundo juego de la serie, pero en casa apenas lograron asestar cinco hits. El campe\u00f3n de bateo de la Liga Nacional, Trea Turner, y Mookie Betts se fueron de 4-0, mientras que Corey Seager se fue de 4-0 con un boleto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Longoria se recuper\u00f3 a lo grande de una racha de 23-0, tras apenas dos hits en sus \u00faltimos 40 turnos de bateo. Fue su primer cuadrangular en postemporada desde la serie divisional de la Liga Americana en 2013 con Tampa Bay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEste ambiente&#8230; es una locura\u201d, dijo Longoria. \u201cQu\u00e9 noche m\u00e1s loca, con el viento. Creo que en cierto modo el viento tapaba el sonido aqu\u00ed\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s del jonr\u00f3n, Scherzer retir\u00f3 a sus \u00faltimos seis bateadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuando llegas a la postemporada, siempre puedes perder por un lanzamiento. Eso ocurre. Esta noche perd\u00ed en un lanzamiento\u201d, dijo Scherzer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los otros dos hits de los Gigantes fueron sencillos de Buster Posey y Kris Bryant. Sus \u00faltimos 15 bateadores fueron retirados, incluido en el noveno, cuando el cerrador curazole\u00f1o de los Dodgers Kenley Jansen retir\u00f3 a todos sus rivales en orden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El abridor de San Francisco Alex Wood admiti\u00f3 dos hits en 4 innings y dos tercios contra su antiguo equipo. El izquierdo ponch\u00f3 a cuatro y dio dos boletos. Tyler Rogers se llev\u00f3 la victoria por un inning y dos tercios en labor de relevo. El dominicano Camilo Doval firm\u00f3 el rescate por dos innings perfectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los Gigantes, el colombiano Donovan Solano de 1-0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por los Dodgers, el dominicano Albert Pujols de 2-2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evan Longoria jonrone\u00f3 ante Max Scherzer en el quinto inning y los Gigantes de San Francisco derrotaron 1-0 el lunes a los Dodgers de Los \u00c1ngeles en una noche ventosa, para ponerse 2-1 arriba en su serie divisional. Los \u00c1ngeles estuvo cerca de igualar la pizarra con dos outs en el noveno, cuando el bateador emergente Gavin Lux peg\u00f3 un buen batazo que envi\u00f3 la pelota entre el jard\u00edn izquierdo y el central. Pero el viento la desvi\u00f3 y la pelota acab\u00f3 atrapada, para desconcierto de Lux. Chris Taylor envi\u00f3 un elevado al centro, pero esa pelota tambi\u00e9n acab\u00f3 en manos de los Gigantes. \u201cCreo que cualquier otra noche, la pelota de CT, la pelota de Gavin Lux, habr\u00edan sido jonrones, s\u00ed\u201d, dijo el m\u00e1nager de los Dodgers, Dave Roberts. Fue la segunda blanqueada de los Gigantes en la serie al mejor de cinco, tras ganar el primer juego 4-0. El martes se celebra el cuarto duelo en el Dodger Stadium, mientras que el quinto se disputar\u00eda el jueves en San Francisco de ser necesario. Los Dodgers derrotaron 9-2 a los Gigantes en el segundo juego de la serie, pero en casa apenas lograron asestar cinco hits. El campe\u00f3n de bateo de la Liga Nacional, Trea Turner, y Mookie Betts se fueron de 4-0, mientras que Corey Seager se fue de 4-0 con un boleto. Longoria se recuper\u00f3 a lo grande de una racha de 23-0, tras apenas dos hits en sus \u00faltimos 40 turnos de bateo. Fue su primer cuadrangular en postemporada desde la serie divisional de la Liga Americana en 2013 con Tampa Bay. \u201cEste ambiente&#8230; es una locura\u201d, dijo Longoria. \u201cQu\u00e9 noche m\u00e1s loca, con el viento. Creo que en cierto modo el viento tapaba el sonido aqu\u00ed\u201d. Despu\u00e9s del jonr\u00f3n, Scherzer retir\u00f3 a sus \u00faltimos seis bateadores. \u201cCuando llegas a la postemporada, siempre puedes perder por un lanzamiento. Eso ocurre. Esta noche perd\u00ed en un lanzamiento\u201d, dijo Scherzer. Los otros dos hits de los Gigantes fueron sencillos de Buster Posey y Kris Bryant. Sus \u00faltimos 15 bateadores fueron retirados, incluido en el noveno, cuando el cerrador curazole\u00f1o de los Dodgers Kenley Jansen retir\u00f3 a todos sus rivales en orden. El abridor de San Francisco Alex Wood admiti\u00f3 dos hits en 4 innings y dos tercios contra su antiguo equipo. El izquierdo ponch\u00f3 a cuatro y dio dos boletos. Tyler Rogers se llev\u00f3 la victoria por un inning y dos tercios en labor de relevo. El dominicano Camilo Doval firm\u00f3 el rescate por dos innings perfectos. Por los Gigantes, el colombiano Donovan Solano de 1-0. Por los Dodgers, el dominicano Albert Pujols de 2-2.<\/p>\n","protected":false},"author":9,"featured_media":83116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-83115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83115"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83115\/revisions"}],"predecessor-version":[{"id":83117,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83115\/revisions\/83117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83116"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}