{"id":83309,"date":"2021-10-25T10:55:22","date_gmt":"2021-10-25T14:55:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83309"},"modified":"2021-10-25T10:55:30","modified_gmt":"2021-10-25T14:55:30","slug":"framber-valdez-abrira-primer-partido-por-astros","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/framber-valdez-abrira-primer-partido-por-astros\/","title":{"rendered":"Framber Valdez abrir\u00e1 primer partido por Astros"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/dep-3.jpg\" alt=\"\" class=\"wp-image-83310\" width=\"187\" height=\"117\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/dep-3.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/10\/dep-3-300x190.jpg 300w\" sizes=\"auto, (max-width: 187px) 100vw, 187px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El dominicano Framber Valdez ser\u00e1 el abridor de los Astros de Houston para el primer partido de la Serie Mundial frente a los Bravos de Atlanta del martes por la noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El manager Dusty Baker anunci\u00f3 el domingo que Valdez tendr\u00e1 el honor, pero indic\u00f3 que el equipo a\u00fan no ha decidido sobre el abridor para el segundo duelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El zurdo de 27 a\u00f1os sostendr\u00e1 un duelo monticular con Charlie Morton, quien lanz\u00f3 para Houston en 2017-18, obteniendo el triunfo en el s\u00e9ptimo partido de la Serie Mundial de 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valdez lanz\u00f3 ocho innings espectaculares en una victoria de 9-1 en el quinto juego de la serie de campeonato de la Liga Americana. En el primer encuentro, permiti\u00f3 tres carreras en dos entradas y dos tercios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Astros no ofrecieron mucha informaci\u00f3n actualizada sobre la salud del as Lance McCullers Jr., quien fue retirado del roster para la serie de campeonato de la Americana debido a una lesi\u00f3n de brazo derecho. McCullers no ha empezado a realizar lanzamientos, pero el gerente general James Click no descarta su regreso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abNo estamos quitando nada de la mesa\u00bb, afirm\u00f3 Click. \u00abVamos a ver c\u00f3mo est\u00e1. Esta es la Serie Mundial, por lo que obviamente es algo en lo que s\u00e9 que Lance desea participar, de ser posible. As\u00ed que hablaremos con los m\u00e9dicos, con \u00e9l y con los entrenadores y partiremos de ah\u00ed\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Houston tambi\u00e9n esperar\u00e1n antes de tomar una decisi\u00f3n sobre el jardinero central Jake Meyers, quien estuvo en el roster de la serie ante Boston pero no jug\u00f3 mientras se recupera de una lesi\u00f3n de hombros. El novato se lesion\u00f3 en el \u00faltimo juego de la serie divisional, y Chas McCormick y el dominicano Jos\u00e9 Siri se hicieron cargo del prado en contra de los Medias Rojas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Astros tambi\u00e9n est\u00e1n considerando sus opciones respecto a la manera de incorporar en la alineaci\u00f3n al toletero cubano Yordan \u00c1lvarez cuando la serie se traslade a Atlanta para el tercer partido y pierdan la posici\u00f3n de bateador designado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dominicano Framber Valdez ser\u00e1 el abridor de los Astros de Houston para el primer partido de la Serie Mundial frente a los Bravos de Atlanta del martes por la noche. El manager Dusty Baker anunci\u00f3 el domingo que Valdez tendr\u00e1 el honor, pero indic\u00f3 que el equipo a\u00fan no ha decidido sobre el abridor para el segundo duelo. El zurdo de 27 a\u00f1os sostendr\u00e1 un duelo monticular con Charlie Morton, quien lanz\u00f3 para Houston en 2017-18, obteniendo el triunfo en el s\u00e9ptimo partido de la Serie Mundial de 2017. Valdez lanz\u00f3 ocho innings espectaculares en una victoria de 9-1 en el quinto juego de la serie de campeonato de la Liga Americana. En el primer encuentro, permiti\u00f3 tres carreras en dos entradas y dos tercios. Los Astros no ofrecieron mucha informaci\u00f3n actualizada sobre la salud del as Lance McCullers Jr., quien fue retirado del roster para la serie de campeonato de la Americana debido a una lesi\u00f3n de brazo derecho. McCullers no ha empezado a realizar lanzamientos, pero el gerente general James Click no descarta su regreso. \u00abNo estamos quitando nada de la mesa\u00bb, afirm\u00f3 Click. \u00abVamos a ver c\u00f3mo est\u00e1. Esta es la Serie Mundial, por lo que obviamente es algo en lo que s\u00e9 que Lance desea participar, de ser posible. As\u00ed que hablaremos con los m\u00e9dicos, con \u00e9l y con los entrenadores y partiremos de ah\u00ed\u00bb. Houston tambi\u00e9n esperar\u00e1n antes de tomar una decisi\u00f3n sobre el jardinero central Jake Meyers, quien estuvo en el roster de la serie ante Boston pero no jug\u00f3 mientras se recupera de una lesi\u00f3n de hombros. El novato se lesion\u00f3 en el \u00faltimo juego de la serie divisional, y Chas McCormick y el dominicano Jos\u00e9 Siri se hicieron cargo del prado en contra de los Medias Rojas. Los Astros tambi\u00e9n est\u00e1n considerando sus opciones respecto a la manera de incorporar en la alineaci\u00f3n al toletero cubano Yordan \u00c1lvarez cuando la serie se traslade a Atlanta para el tercer partido y pierdan la posici\u00f3n de bateador designado.<\/p>\n","protected":false},"author":9,"featured_media":83310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-83309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83309"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83309\/revisions"}],"predecessor-version":[{"id":83311,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83309\/revisions\/83311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83310"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}