{"id":83598,"date":"2021-11-26T07:25:47","date_gmt":"2021-11-26T11:25:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83598"},"modified":"2021-11-26T07:25:50","modified_gmt":"2021-11-26T11:25:50","slug":"madonna-reina-del-pop-y-del-escandalo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/madonna-reina-del-pop-y-del-escandalo\/","title":{"rendered":"Madonna: reina del pop&#8230; \u00a1y del esc\u00e1ndalo!"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/11\/ma.jpg\" alt=\"\" class=\"wp-image-83600\" width=\"230\" height=\"125\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/11\/ma.jpg 333w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/11\/ma-300x163.jpg 300w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Es la mujer m\u00e1s importante de la historia de la m\u00fasica moderna, una superestrella a la que solo The Beatles superan en la clasificaci\u00f3n de los artistas m\u00e1s exitosos para la revista Billboard, y a sus 63 a\u00f1os nadie parece indiferente tras m\u00e1s de cuatro d\u00e9cadas de carrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La pol\u00e9mica ha acompa\u00f1ado a Madonna<\/strong>&nbsp;durante toda su carrera, y ha sido una de las claves para convertirla en la solista femenina m\u00e1s famosa de la historia de la m\u00fasica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una mujer que, pese a quien pese, siempre ha hecho lo que ha querido, aunque a veces haya pagado un precio demasiado alto por ello, como cuando la publicaci\u00f3n del libro \u2018Sex\u2019, que acompa\u00f1aba al lanzamiento discogr\u00e1fico de \u2018Erotica\u2019 (1992), su quinto trabajo, que provoc\u00f3 una campa\u00f1a en su contra que la llev\u00f3 a los momentos m\u00e1s bajos de su carrera y tambi\u00e9n a comprender que las reglas para hombres y mujeres no son las mismas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tampoco en el mundo de la m\u00fasica, como explic\u00f3 al reconocer el premio Billboard a la mujer del a\u00f1o, en el que se autoproclam\u00f3 \u201cmala feminista\u201d y confes\u00f3 haber salido de aquel mal momento escuchando la m\u00fasica de Nina Simone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRecuerdo verme en las portadas de todas las revistas y peri\u00f3dicos. Todo lo que le\u00eda era da\u00f1ino. Me convert\u00ed en una puta y una bruja. Un titular me compar\u00f3 con Sat\u00e1n. En aquel momento Prince ense\u00f1aba el culo y llevaba medias de rejilla. Pero \u00e9l era un hombre. Fue el primer momento en que me di cuenta que las mujeres no tenemos la misma libertad que ellos. Me qued\u00e9 paralizada y me llev\u00f3 mucho tiempo recuperarme y seguir adelante, no solo con mi carrera, sino tambi\u00e9n con mi vida\u201d, comento en la prensa de la \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Madonna Louise Veronica Ciccone (Bay City, Michigan, 16 de agosto de 1958) ya hab\u00eda escandalizado en la d\u00e9cada de los 80 con \u2018Like a Virgin\u2019 (1984) o \u2018Like a Prayer\u2019 (1989) con el uso irreverente de la simbolog\u00eda cat\u00f3lica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>l videoclip de \u2018Like a Prayer\u2019&nbsp;<\/strong>es reconocido como el m\u00e1s escandaloso, aunque no ha sido el \u00fanico v\u00eddeo que ha supuesto problemas para la artista, que antes de ver c\u00f3mo censuraban \u2018Erotica\u2019, sufri\u00f3 lo mismo con \u2018Justify My Love\u2019 dos a\u00f1os antes, y que m\u00e1s adelante pasar\u00eda con otros como \u2018What If Feels Like For a Girl\u2019 (2001), \u2018American Life\u2019 (2003) o, ya en la era YouTube, \u2018Girl Gone Wild\u2019 (2012).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a todo, y gracias a temas como \u2018Like a Virgin\u2019, \u2018Like a Prayer\u2019, \u2018Papa Don\u2019t Preach\u2019, \u2018Vogue\u2019, \u2018Frozen\u2019, \u2018Music\u2019, \u2018Hung Up\u2019 o \u2018Express Yourself\u2019, la estrella estadounidense es uno de los grandes nombres de la historia de la m\u00fasica de todos los tiempos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+ Actualidad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana Madonna ha vuelto a su rol de provocadora, al posar de manera extra sensual en una serie de 10 fotograf\u00edas que se amontonaron en las redes sociales provocando un fuego medi\u00e1tico entre atizadores y aplacadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201c\u00c1ngel cuid\u00e1ndome\u201d,<\/strong>&nbsp;escribi\u00f3 la cantante en el post de su publicaci\u00f3n en Instagram, en referencia a la imagen que est\u00e1 sobre la cama en la que pos\u00f3 usando medias de malla y ropa interior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las capturas la int\u00e9rprete de \u201cLike a Virgin\u201d quiso exponer la figura que mantiene y no se cort\u00f3 en mostrar su cuerpo de sus s\u00edmbolos como el crucifijo en el pecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como en sus viejos tiempos, a la estrella estadounidense de la m\u00fasica se le ve en poses provocadoras sobre y alrededor de una cama, luciendo lencer\u00eda negra, medias de red y unos stilettos Louboutin, con su caracter\u00edstica suela roja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las fotograf\u00edas generan controversias entre liberales y conservadores, sobre todo por las \u201cposes endiabladas\u201d que hacen frente a la figura de un \u00e1ngel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La serie de fotograf\u00edas tienen un concepto en colores tenues con predominio del blanco y negro que dan pie a que algunos comentaron que \u201cparece reptiliana\u201d y otros m\u00e1s que \u201ces una muestra m\u00e1s de su ideolog\u00eda illuminatti\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>+ Su reacci\u00f3n&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa Reina del Pop\u201d escribi\u00f3 luego en sus historias una cita de la poeta Mary Oliver: \u201cLa belleza sin prop\u00f3sito es belleza sin virtud, pero todas las cosas hermosas tienen esta funci\u00f3n: excitar a los espectadores hacia el pensamiento sublime. Gloria al mundo, ese buen maestro\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En m\u00fasica.<\/strong>&nbsp;Ha sido desde sus comienzos una referencia indiscutible en la m\u00fasica y en la moda. \u201cNo quiero que nadie imite mi forma de vestir, sino de pensar\u201d, asegura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un disco.<\/strong>&nbsp;A finales de los a\u00f1os 90, la publicaci\u00f3n de \u2018Ray of Light\u2019 (1998) marc\u00f3 un punto de inflexi\u00f3n en su carrera y en su vida, una nueva Madonna que, por una temporada, se alej\u00f3 de su estilo habitual y con el que su trayectoria volvi\u00f3 a repuntar. Por \u2018Ray of Light\u2019 obtuvo cuatro premios Grammy de los seis a los que fue nominada, y con m\u00e1s de 20 millones de copias vendidas es uno de los trabajos m\u00e1s exitosos de la gran artista americana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es la mujer m\u00e1s importante de la historia de la m\u00fasica moderna, una superestrella a la que solo The Beatles superan en la clasificaci\u00f3n de los artistas m\u00e1s exitosos para la revista Billboard, y a sus 63 a\u00f1os nadie parece indiferente tras m\u00e1s de cuatro d\u00e9cadas de carrera. La pol\u00e9mica ha acompa\u00f1ado a Madonna&nbsp;durante toda su carrera, y ha sido una de las claves para convertirla en la solista femenina m\u00e1s famosa de la historia de la m\u00fasica.&nbsp; Una mujer que, pese a quien pese, siempre ha hecho lo que ha querido, aunque a veces haya pagado un precio demasiado alto por ello, como cuando la publicaci\u00f3n del libro \u2018Sex\u2019, que acompa\u00f1aba al lanzamiento discogr\u00e1fico de \u2018Erotica\u2019 (1992), su quinto trabajo, que provoc\u00f3 una campa\u00f1a en su contra que la llev\u00f3 a los momentos m\u00e1s bajos de su carrera y tambi\u00e9n a comprender que las reglas para hombres y mujeres no son las mismas. Tampoco en el mundo de la m\u00fasica, como explic\u00f3 al reconocer el premio Billboard a la mujer del a\u00f1o, en el que se autoproclam\u00f3 \u201cmala feminista\u201d y confes\u00f3 haber salido de aquel mal momento escuchando la m\u00fasica de Nina Simone. \u201cRecuerdo verme en las portadas de todas las revistas y peri\u00f3dicos. Todo lo que le\u00eda era da\u00f1ino. Me convert\u00ed en una puta y una bruja. Un titular me compar\u00f3 con Sat\u00e1n. En aquel momento Prince ense\u00f1aba el culo y llevaba medias de rejilla. Pero \u00e9l era un hombre. Fue el primer momento en que me di cuenta que las mujeres no tenemos la misma libertad que ellos. Me qued\u00e9 paralizada y me llev\u00f3 mucho tiempo recuperarme y seguir adelante, no solo con mi carrera, sino tambi\u00e9n con mi vida\u201d, comento en la prensa de la \u00e9poca. Madonna Louise Veronica Ciccone (Bay City, Michigan, 16 de agosto de 1958) ya hab\u00eda escandalizado en la d\u00e9cada de los 80 con \u2018Like a Virgin\u2019 (1984) o \u2018Like a Prayer\u2019 (1989) con el uso irreverente de la simbolog\u00eda cat\u00f3lica. l videoclip de \u2018Like a Prayer\u2019&nbsp;es reconocido como el m\u00e1s escandaloso, aunque no ha sido el \u00fanico v\u00eddeo que ha supuesto problemas para la artista, que antes de ver c\u00f3mo censuraban \u2018Erotica\u2019, sufri\u00f3 lo mismo con \u2018Justify My Love\u2019 dos a\u00f1os antes, y que m\u00e1s adelante pasar\u00eda con otros como \u2018What If Feels Like For a Girl\u2019 (2001), \u2018American Life\u2019 (2003) o, ya en la era YouTube, \u2018Girl Gone Wild\u2019 (2012). Pese a todo, y gracias a temas como \u2018Like a Virgin\u2019, \u2018Like a Prayer\u2019, \u2018Papa Don\u2019t Preach\u2019, \u2018Vogue\u2019, \u2018Frozen\u2019, \u2018Music\u2019, \u2018Hung Up\u2019 o \u2018Express Yourself\u2019, la estrella estadounidense es uno de los grandes nombres de la historia de la m\u00fasica de todos los tiempos. + Actualidad Esta semana Madonna ha vuelto a su rol de provocadora, al posar de manera extra sensual en una serie de 10 fotograf\u00edas que se amontonaron en las redes sociales provocando un fuego medi\u00e1tico entre atizadores y aplacadores. \u201c\u00c1ngel cuid\u00e1ndome\u201d,&nbsp;escribi\u00f3 la cantante en el post de su publicaci\u00f3n en Instagram, en referencia a la imagen que est\u00e1 sobre la cama en la que pos\u00f3 usando medias de malla y ropa interior. En las capturas la int\u00e9rprete de \u201cLike a Virgin\u201d quiso exponer la figura que mantiene y no se cort\u00f3 en mostrar su cuerpo de sus s\u00edmbolos como el crucifijo en el pecho. Como en sus viejos tiempos, a la estrella estadounidense de la m\u00fasica se le ve en poses provocadoras sobre y alrededor de una cama, luciendo lencer\u00eda negra, medias de red y unos stilettos Louboutin, con su caracter\u00edstica suela roja. Las fotograf\u00edas generan controversias entre liberales y conservadores, sobre todo por las \u201cposes endiabladas\u201d que hacen frente a la figura de un \u00e1ngel. La serie de fotograf\u00edas tienen un concepto en colores tenues con predominio del blanco y negro que dan pie a que algunos comentaron que \u201cparece reptiliana\u201d y otros m\u00e1s que \u201ces una muestra m\u00e1s de su ideolog\u00eda illuminatti\u201d. + Su reacci\u00f3n&nbsp; \u201cLa Reina del Pop\u201d escribi\u00f3 luego en sus historias una cita de la poeta Mary Oliver: \u201cLa belleza sin prop\u00f3sito es belleza sin virtud, pero todas las cosas hermosas tienen esta funci\u00f3n: excitar a los espectadores hacia el pensamiento sublime. Gloria al mundo, ese buen maestro\u201d. En m\u00fasica.&nbsp;Ha sido desde sus comienzos una referencia indiscutible en la m\u00fasica y en la moda. \u201cNo quiero que nadie imite mi forma de vestir, sino de pensar\u201d, asegura. Un disco.&nbsp;A finales de los a\u00f1os 90, la publicaci\u00f3n de \u2018Ray of Light\u2019 (1998) marc\u00f3 un punto de inflexi\u00f3n en su carrera y en su vida, una nueva Madonna que, por una temporada, se alej\u00f3 de su estilo habitual y con el que su trayectoria volvi\u00f3 a repuntar. Por \u2018Ray of Light\u2019 obtuvo cuatro premios Grammy de los seis a los que fue nominada, y con m\u00e1s de 20 millones de copias vendidas es uno de los trabajos m\u00e1s exitosos de la gran artista americana.<\/p>\n","protected":false},"author":9,"featured_media":83600,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-83598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83598"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83598\/revisions"}],"predecessor-version":[{"id":83601,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83598\/revisions\/83601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83600"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}