{"id":83638,"date":"2021-12-08T15:58:22","date_gmt":"2021-12-08T19:58:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83638"},"modified":"2021-12-08T15:58:25","modified_gmt":"2021-12-08T19:58:25","slug":"francisco-pena-decide-triunfo-de-las-aguilas-ante-los-toros","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/francisco-pena-decide-triunfo-de-las-aguilas-ante-los-toros\/","title":{"rendered":"Francisco Pe\u00f1a decide triunfo de las \u00c1guilas ante los Toros"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/dep.jpg\" alt=\"\" class=\"wp-image-83639\" width=\"172\" height=\"114\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/dep.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/dep-300x200.jpg 300w\" sizes=\"auto, (max-width: 172px) 100vw, 172px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Un sencillo de Francisco Pe\u00f1a con corredores en las esquinas, rompi\u00f3 un empate en la apertura del noveno episodio y las \u00c1guilas Cibae\u00f1as derrotaron a los Toros del Este con pizarra de 2-1, en partido celebrado este martes en el Estadio Francisco A. Micheli.&nbsp;<br \/>Los Toros amenazaron en el cierre del noveno episodio, cuando colocaron las carreras del empate y la victoria en circulaci\u00f3n, pero no pudieron conectar el batazo para producir carreras.&nbsp;<br \/>Bryan Abreu lanz\u00f3 pelota de calidad durante 5 episodios, mientras que Esteury Ruiz peg\u00f3 uno de los 6 imparables de los Toros, anot\u00f3 una carrera y se estaf\u00f3 dos almohadillas y Alejandro Mej\u00eda dispar\u00f3 dos indiscutibles, para ser los m\u00e1s destacados de los locales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la derrota, los Toros (12-19) pierden su segundo partido consecutivo, y dejan su r\u00e9cord en el Corral en (6-10). Mientras que las \u00c1guilas (17-14), ganan su segundo partido seguido, ganan la serie particular (5-2) y mejoran su r\u00e9cord en la ruta (7-9).&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El derecho de los Toros, Bryan Abreu (1-2, 3.00), sali\u00f3 sin decisi\u00f3n luego de lanzar 5 s\u00f3lidas entradas de 4 hits, una carrera inmerecida, cero boletos y 3 ponches. Fue la segunda ocasi\u00f3n en la temporada en la que Abreu completa al menos 5 entradas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\n\nLe siguieron los relevistas Tim Peterson, James Hoyt, Anthony Gose y Fernando Abad. En general, el relevo taurino lanz\u00f3 4 entradas de 3 hits, una carrera limpia y 5 ponches.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tambi\u00e9n derecho, Yunesky Maya (2-3, 2.16) tambi\u00e9n se fue sin decisi\u00f3n luego de una labor de 6 episodios en los que permiti\u00f3 3 imparables y una carrera limpia, otorg\u00f3 dos boletos y ponch\u00f3 a 3.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La victoria fue para el derecho Juli\u00e1n Fern\u00e1ndez (1-0, 1.35) quien lanz\u00f3 una entrada en blanco con un boleto y 2 ponches. El derrotado fue Fernando Abad (1-2, 9.45) quien permiti\u00f3 3 hits y una carrera limpia con un ponche, en una entrada de labor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LAS CARRERAS:&nbsp;<br \/>Los Toros tomaron el comando del partido en la misma primera entrada, cuando Peter O\\\u00bbBrien consigui\u00f3 elevado de sacrificio con un corredor en tercera.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las \u00c1guilas empataron las acciones en la apertura del segundo episodio, cuando Ram\u00f3n Torres conecto batazo por el box con corredores en las esquinas pero el abridor taurino, Bryan Aberu, cometi\u00f3 error en tiro a la inicial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por las \u00c1guilas, Luis Valenzuela de 4-3 con una anotada, Francisco Pe\u00f1a de 4-2 con una impulsada y Ram\u00f3n Torres de 3-1 con una producida. Por los Toros, Esteury Ruiz de 3-1 con una anotada y dos bases robadas, Alejandro Mej\u00eda de 5-2 y Raudy Reed de 1-1.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Toros se mantienen en el Corral este mi\u00e9rcoles, para recibir la visita de las Estrellas Orientales en partido pautado para las 7:30 PM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sencillo de Francisco Pe\u00f1a con corredores en las esquinas, rompi\u00f3 un empate en la apertura del noveno episodio y las \u00c1guilas Cibae\u00f1as derrotaron a los Toros del Este con pizarra de 2-1, en partido celebrado este martes en el Estadio Francisco A. Micheli.&nbsp;Los Toros amenazaron en el cierre del noveno episodio, cuando colocaron las carreras del empate y la victoria en circulaci\u00f3n, pero no pudieron conectar el batazo para producir carreras.&nbsp;Bryan Abreu lanz\u00f3 pelota de calidad durante 5 episodios, mientras que Esteury Ruiz peg\u00f3 uno de los 6 imparables de los Toros, anot\u00f3 una carrera y se estaf\u00f3 dos almohadillas y Alejandro Mej\u00eda dispar\u00f3 dos indiscutibles, para ser los m\u00e1s destacados de los locales.&nbsp; Tras la derrota, los Toros (12-19) pierden su segundo partido consecutivo, y dejan su r\u00e9cord en el Corral en (6-10). Mientras que las \u00c1guilas (17-14), ganan su segundo partido seguido, ganan la serie particular (5-2) y mejoran su r\u00e9cord en la ruta (7-9).&nbsp;&nbsp; El derecho de los Toros, Bryan Abreu (1-2, 3.00), sali\u00f3 sin decisi\u00f3n luego de lanzar 5 s\u00f3lidas entradas de 4 hits, una carrera inmerecida, cero boletos y 3 ponches. Fue la segunda ocasi\u00f3n en la temporada en la que Abreu completa al menos 5 entradas.\u00a0 Le siguieron los relevistas Tim Peterson, James Hoyt, Anthony Gose y Fernando Abad. En general, el relevo taurino lanz\u00f3 4 entradas de 3 hits, una carrera limpia y 5 ponches.&nbsp; El tambi\u00e9n derecho, Yunesky Maya (2-3, 2.16) tambi\u00e9n se fue sin decisi\u00f3n luego de una labor de 6 episodios en los que permiti\u00f3 3 imparables y una carrera limpia, otorg\u00f3 dos boletos y ponch\u00f3 a 3.&nbsp; La victoria fue para el derecho Juli\u00e1n Fern\u00e1ndez (1-0, 1.35) quien lanz\u00f3 una entrada en blanco con un boleto y 2 ponches. El derrotado fue Fernando Abad (1-2, 9.45) quien permiti\u00f3 3 hits y una carrera limpia con un ponche, en una entrada de labor. LAS CARRERAS:&nbsp;Los Toros tomaron el comando del partido en la misma primera entrada, cuando Peter O\\\u00bbBrien consigui\u00f3 elevado de sacrificio con un corredor en tercera.&nbsp; Las \u00c1guilas empataron las acciones en la apertura del segundo episodio, cuando Ram\u00f3n Torres conecto batazo por el box con corredores en las esquinas pero el abridor taurino, Bryan Aberu, cometi\u00f3 error en tiro a la inicial.&nbsp; Por las \u00c1guilas, Luis Valenzuela de 4-3 con una anotada, Francisco Pe\u00f1a de 4-2 con una impulsada y Ram\u00f3n Torres de 3-1 con una producida. Por los Toros, Esteury Ruiz de 3-1 con una anotada y dos bases robadas, Alejandro Mej\u00eda de 5-2 y Raudy Reed de 1-1.&nbsp; Los Toros se mantienen en el Corral este mi\u00e9rcoles, para recibir la visita de las Estrellas Orientales en partido pautado para las 7:30 PM.<\/p>\n","protected":false},"author":9,"featured_media":83639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-83638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83638"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83638\/revisions"}],"predecessor-version":[{"id":83640,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83638\/revisions\/83640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83639"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}