{"id":83647,"date":"2021-12-08T16:06:49","date_gmt":"2021-12-08T20:06:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83647"},"modified":"2021-12-08T16:06:52","modified_gmt":"2021-12-08T20:06:52","slug":"camilo-suma-el-alfa-a-su-tribu-ante-la-algarabia-de-su-fanaticada-dominicana-en-el-teatro-nacional","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/camilo-suma-el-alfa-a-su-tribu-ante-la-algarabia-de-su-fanaticada-dominicana-en-el-teatro-nacional\/","title":{"rendered":"Camilo suma El Alfa a su \u00abtribu\u00bb ante la algarab\u00eda de su fanaticada dominicana en el Teatro Nacional"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/al.jpg\" alt=\"\" class=\"wp-image-83648\" width=\"206\" height=\"137\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/al.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/al-300x200.jpg 300w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSanto Domingo no te vayas\u00bb, con esas palabras se dio inicio al concierto de Camilo en el Teatro Nacional, donde hubo complicidad entre artista y p\u00fablico entre aplausos, j\u00fabilo y mucha energ\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un evento donde hasta ni\u00f1os\/as se mostraban extasiados ante la presencia del cantante colombiano cuya interacci\u00f3n con su \u00abtribu\u00bb alter\u00f3 los esquemas en la principal sala de teatro del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las luces, el sonido y la felicidad que reinaban en el&nbsp; ambiente demostraron porque Camilo es parte del top de los artistas favoritos de la nueva camada musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los espectadores, un grupo compuesto por personas de todas las edades, desde antes de iniciar el gran evento transcurrido en el Teatro Nacional Eduardo Brito ya estaban aclamando a Camilo y su repertorio musical.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Era tanta la algarab\u00eda y emoci\u00f3n&nbsp;<\/strong>por parte de la fanaticada que no hubo canci\u00f3n que no se cantara y bailara en la sala. No acababa bien un tema y ya ellos ped\u00edan m\u00e1s y m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Con la presencia de su amada Evaluna,<\/strong>&nbsp;con quien interpret\u00f3 temas como &#8216;Machu picchu&#8217;, &#8216;Por primera vez&#8217; e &#8216;\u00cdndigo&#8217;, la pareja brill\u00f3 y mostr\u00f3 su amor por todo lo alto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Evaluna, a pesar de encontrarse en estado de gestaci\u00f3n, bail\u00f3 y cant\u00f3 con la fuerza y alegr\u00eda que la caracteriza junto a su esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El artista colombiano expres\u00f3 en varias ocasiones lo feliz que se sent\u00eda en su primera vez present\u00e1ndose en el pa\u00eds, y lo transmiti\u00f3 con cada interpretaci\u00f3n desde el inicio con &#8216;Favorito&#8217; hasta que concluy\u00f3 con el tema &#8216;Vida de rico&#8217;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Habl\u00f3 sobre su experiencia en Rep\u00fablica Dominicana y c\u00f3mo el pa\u00eds lo inspir\u00f3 a componer sus canciones m\u00e1s bonitas, seg\u00fan \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un momento, dentro de la euforia y las ovaciones del p\u00fablico, Camilo sacaba momentos para charlar amenamente con sus espectadores, incluso subiendo al escenario a una ni\u00f1a llamada Silvana, de 5 a\u00f1os de edad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n recibi\u00f3 con mucho aprecio diversos obsequios de parte de sus fan\u00e1ticos en el transcurso de la actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El concierto cont\u00f3 con invitados como El Alfa,&nbsp;<\/strong>con quien interpret\u00f3 la bachata &#8216;Beb\u00e9&#8217; y se mostr\u00f3 agradecido con este por abrirle las puertas y por la humildad con que lo acogi\u00f3; y su suegro Ricardo Montaner, quien le brind\u00f3 unas palabras sobre c\u00f3mo el artista le hab\u00eda recordado a su primer concierto en el pa\u00eds, que fue justamente en el Teatro Nacional y le regal\u00f3 al p\u00fablico junto a su hijo, como lo considera \u00e9l, uno de sus emblem\u00e1ticos temas &#8216;B\u00e9same&#8217;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el cierre con broche de oro de Camilo con sus invitados, a la salida del Teatro Nacional, una pareja de t\u00f3rtolos decidi\u00f3 darse un rotundo s\u00ed, gan\u00e1ndose los suspiros del p\u00fablico presente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin duda, fue un concierto inolvidable y la tribu espera con ansias su regreso a los escenarios del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSanto Domingo no te vayas\u00bb, con esas palabras se dio inicio al concierto de Camilo en el Teatro Nacional, donde hubo complicidad entre artista y p\u00fablico entre aplausos, j\u00fabilo y mucha energ\u00eda. Un evento donde hasta ni\u00f1os\/as se mostraban extasiados ante la presencia del cantante colombiano cuya interacci\u00f3n con su \u00abtribu\u00bb alter\u00f3 los esquemas en la principal sala de teatro del pa\u00eds. Las luces, el sonido y la felicidad que reinaban en el&nbsp; ambiente demostraron porque Camilo es parte del top de los artistas favoritos de la nueva camada musical. Los espectadores, un grupo compuesto por personas de todas las edades, desde antes de iniciar el gran evento transcurrido en el Teatro Nacional Eduardo Brito ya estaban aclamando a Camilo y su repertorio musical. Era tanta la algarab\u00eda y emoci\u00f3n&nbsp;por parte de la fanaticada que no hubo canci\u00f3n que no se cantara y bailara en la sala. No acababa bien un tema y ya ellos ped\u00edan m\u00e1s y m\u00e1s. Con la presencia de su amada Evaluna,&nbsp;con quien interpret\u00f3 temas como &#8216;Machu picchu&#8217;, &#8216;Por primera vez&#8217; e &#8216;\u00cdndigo&#8217;, la pareja brill\u00f3 y mostr\u00f3 su amor por todo lo alto. Evaluna, a pesar de encontrarse en estado de gestaci\u00f3n, bail\u00f3 y cant\u00f3 con la fuerza y alegr\u00eda que la caracteriza junto a su esposo. El artista colombiano expres\u00f3 en varias ocasiones lo feliz que se sent\u00eda en su primera vez present\u00e1ndose en el pa\u00eds, y lo transmiti\u00f3 con cada interpretaci\u00f3n desde el inicio con &#8216;Favorito&#8217; hasta que concluy\u00f3 con el tema &#8216;Vida de rico&#8217;. Habl\u00f3 sobre su experiencia en Rep\u00fablica Dominicana y c\u00f3mo el pa\u00eds lo inspir\u00f3 a componer sus canciones m\u00e1s bonitas, seg\u00fan \u00e9l. En un momento, dentro de la euforia y las ovaciones del p\u00fablico, Camilo sacaba momentos para charlar amenamente con sus espectadores, incluso subiendo al escenario a una ni\u00f1a llamada Silvana, de 5 a\u00f1os de edad.&nbsp; Tambi\u00e9n recibi\u00f3 con mucho aprecio diversos obsequios de parte de sus fan\u00e1ticos en el transcurso de la actividad. El concierto cont\u00f3 con invitados como El Alfa,&nbsp;con quien interpret\u00f3 la bachata &#8216;Beb\u00e9&#8217; y se mostr\u00f3 agradecido con este por abrirle las puertas y por la humildad con que lo acogi\u00f3; y su suegro Ricardo Montaner, quien le brind\u00f3 unas palabras sobre c\u00f3mo el artista le hab\u00eda recordado a su primer concierto en el pa\u00eds, que fue justamente en el Teatro Nacional y le regal\u00f3 al p\u00fablico junto a su hijo, como lo considera \u00e9l, uno de sus emblem\u00e1ticos temas &#8216;B\u00e9same&#8217;. Tras el cierre con broche de oro de Camilo con sus invitados, a la salida del Teatro Nacional, una pareja de t\u00f3rtolos decidi\u00f3 darse un rotundo s\u00ed, gan\u00e1ndose los suspiros del p\u00fablico presente. Sin duda, fue un concierto inolvidable y la tribu espera con ansias su regreso a los escenarios del pa\u00eds.<\/p>\n","protected":false},"author":9,"featured_media":83648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-83647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83647"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83647\/revisions"}],"predecessor-version":[{"id":83649,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83647\/revisions\/83649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83648"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}