{"id":83659,"date":"2021-12-09T09:25:11","date_gmt":"2021-12-09T13:25:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83659"},"modified":"2021-12-09T09:25:20","modified_gmt":"2021-12-09T13:25:20","slug":"el-turismo-esquivo-la-pandemia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-turismo-esquivo-la-pandemia\/","title":{"rendered":"El turismo esquiv\u00f3 la pandemia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/el-turismo-esquivo-la-pandemia.jpeg\" alt=\"\" class=\"wp-image-83660\" width=\"204\" height=\"105\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/el-turismo-esquivo-la-pandemia.jpeg 330w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/el-turismo-esquivo-la-pandemia-300x155.jpeg 300w\" sizes=\"auto, (max-width: 204px) 100vw, 204px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">La industria tur\u00edstica se vio forzada&nbsp; a&nbsp; reinventarse para impulsar una de las recuperaciones m\u00e1s asombrosas que ha experimentado la econom\u00eda dominicana, con una llegada rec\u00f3rd de turistas de 519,349 en noviembre de este a\u00f1o, sobrepasando las cifras logradas en noviembre del 2019, previo a la pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es innegable que para alcanzar estos resultados es mucho el trabajo realizado para que hoteles, bares y restaurantes lograr\u00e1n adaptarse a un mundo totalmente transformado con un turista m\u00e1s exigente, m\u00e1s adiestrado tecnol\u00f3gicamente, con un abanico de ofertas disponibles que supera el todo incluido, dispuesto a vivir experiencias menos convencionales y a mejores costos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La industria tur\u00edstica dominicana se dio cuenta a tiempo de la importancia de unirse a los esfuerzos que desde el Gobierno se hac\u00edan para lograr un alto grado de personas vacunadas que permitiera una apertura econ\u00f3mica sostenible y se enfoc\u00f3 en exigir a sus trabajadores las dos dosis de vacuna, como forma certera de atraer a un turista ansioso de libertad pero con temor a enfermarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta industria, que en los meses de abril, mayo, junio y julio del 2020, vio desaparecer practicamente toda su actividad&nbsp; econ\u00f3mica y se sinti\u00f3 tambalear, se dio cuenta a tiempo de que el turismo interno ser\u00eda su \u00fanico soporte, a pesar de las restricciones, y desde ese momento empez\u00f3 a reinventarse, adapt\u00e1ndose a los protocolos, a las restricciones horarias y a un turista criollo con menos recursos, pero en definitiva su tabla de salvaci\u00f3n en medio de la crisis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igual sucedi\u00f3 en el turismo de ciudad, donde hoteles, bares y restaurantes asumieron nuevas maneras de mantener sus clientes, ofreciendo servicios m\u00e1s personalizados, experiencias m\u00e1s familiares e integrando la tecnolog\u00eda como la mejor opci\u00f3n de un servicio acorde con los protocolos mpuestos por el Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reinventarse&nbsp; o&nbsp; acumular p\u00e9rdidas. Reinventarse o perder su posicionamiento en la regi\u00f3n, ese fue el dilema. Se crearon mecanismos de burbujas sanitarias con pruebas PCR y seguimiento de los trabajadores en riesgo, reduciendo as\u00ed los contagios durante la reactivaci\u00f3n del sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sector ha recuperado su ritmo y las proyecciones son realmente halag\u00fce\u00f1as para las pr\u00f3ximas temporadas,&nbsp; aunque muchos de sus trabajadores, que esperaron m\u00e1s de un a\u00f1o suspendidos, desesperados por la crisis buscaron otra forma de ganar dinero y no se han reintegrado, lo que consta en un reporte reciente del corresponsal del List\u00edn Diario en la zona Este, Florentino Dur\u00e1n, en el que el presidente de la Asociaci\u00f3n de Hoteles y Proyectos Tur\u00edsticos del Este (Asodeste), Ernesto Veloz, se\u00f1ala que empleados que salieron de los hoteles, no han regresado y que en la actualidad existen cerca de 5,000 plazas vacantes en la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Opinan periodistas turisticos<\/strong><br \/>Definitivamente, la industria ha cambiado, sostiene el periodista&nbsp; especializado en turismo, Salvador Batista. Expone que en la actualidad&nbsp; se tiene mucho m\u00e1s cuidado de c\u00f3mo tratar al turista, pues la pandemia dej\u00f3 un visitante m\u00e1s exigente y cuidadoso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este visitante procura que los establecimientos tengan las medidas protocolares para su protecci\u00f3n,&nbsp; tienen mecanismos digitales para denunciar si les pareci\u00f3 bien o no un destino, hotel o restaurantes, esto ha puesto en jaque a los complejos tur\u00edsticos, explica Batista, puntualizando que&nbsp; los&nbsp; empresarios del sector tur\u00edstico han tenido que hacer millonarias inversiones para no verse opacados ante sus competidores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El turismo ha dado un giro de 180 grados, insiste el comunicador, debido principalmente a la forma de las personas viajar..<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Refiere que en el caso de los viajes internacionales muchos se han limitado y realizan sus reservas de manera directa a trav\u00e9s de las plataformas digitales. Sostiene que la intermediaci\u00f3n de las agencias de viaje ha bajado bastante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indica el eriodista y productor del programa \u201cRecorriendo con Salvador\u201d, que los destinos que buscan los visitantes ya no son los mismos&nbsp; debido a que&nbsp; muchos turistas se han enfocado en destinos abiertos, sobre todo que muestren mucha naturaleza y playas, contrario a tiempos atr\u00e1s que se buscaba muchos destinos culturales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El confinamiento cambi\u00f3 la forma del turista definir sus viajes. La periodista Naivi Fr\u00edas, especializada en turismo, refiere que lo que cambi\u00f3 en la industria es que la gente est\u00e1 valorando m\u00e1s el turismo de experiencia como alternativa al turismo masivo del todo incluido o de los grandes tour y hacer turismo en su propio territorio. \u201cNo es una tendencia en Rep\u00fablica Dominicana, que la gente coja para los pueblos, sino que es una tendencia mundial, conocer sus propios territorios\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explica que, luego de la pandemia, el turista tiende m\u00e1s a viajes experienciales, en grupos peque\u00f1os y busca alternativas m\u00e1s a la aventura y a la comunidad. \u201cEst\u00e1 pensando m\u00e1s en quedarse en villas, casas de campa\u00f1as, Air BnB y alquiler de plataformas digitales que ofrecen una variedad de opciones que van m\u00e1s all\u00e1 del todo incluido\u201d apunta Fr\u00edas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destaca que entre los cambios que llegaron para quedarse se encuentran m\u00e1s herramientas que garanticen los protocolos sanitarios, brindar experiencias que no sean masivas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostiene que muchos hoteles promueven de manera gratuita el servicio al cuarto para evitar las aglomeraciones en los restaurantes, como opci\u00f3n para clientes que no quieren permanecer en lugares cerrados, por lo que tambi\u00e9n se notan mayores inversiones en hacer m\u00e1s agradable los espacios abiertos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fr\u00edas, quien produce y conduce el programa radial \u201cP\u00e1rate Ah\u00ed Tours\u201d, se\u00f1al\u00f3 que las nuevas ofertas de hospedajes que se ofrecen a trav\u00e9s de distintas plataformas digitales en principio han creado preocupaci\u00f3n por su impacto en los complejos hoteleros y aunque estos han tenido que \u201csacar sus garras\u201d para mantener su supremac\u00eda, lo que en realidad se ve es que la oferta tur\u00edstica se ha diversificado y eso termina atrayendo un flujo mayor de visitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1ala que el reto actual de los hoteles es responder de manera adecuada y eficiente a las nuevas exigencias del viajero de hoy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CIFRAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>4.2MM<br \/>Visitantes.<\/strong><br \/>&nbsp;Al cierre de noviembre, el Ministerio de Turismo contabilizaba la llegada de 4,263,259 visitantes al pa\u00eds. A la fecha se habia recuperado el 73% de los visitantes no residentes, en comparaci\u00f3n al 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>27%<br \/>Turismo familiar.<\/strong><br \/>&nbsp;El turismo familiar aport\u00f3 el 27% del turismo en noviembre 2021 con estad\u00eda promedio de 8 noches, alojados principalmente en La Altagracia y El Gran Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>27%<br \/>Turismo aventura.<\/strong><br \/>&nbsp;Los aventureros representaron el 27% del total, con estad\u00eda promedio de 9 noches, alojados principalmente en hoteles, seg\u00fan Mitur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CIFRAS<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Opini\u00f3n del experto<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los cambios que ha generado el sector hotelero han sido muchos, explica el empresario hotelero, Joel Santos, expresidente de la Asociaci\u00f3n de Hoteles y Turismo de Rep\u00fablica Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En los protocolos de manejo de los turistas, en el uso de los espacios, en las reglamentaciones para mantener las distancias, en los procesos de checking y en las reservas, siempre tratando de evitar aglometaciones y de ofrecer servicios m\u00e1s individualizados en todas las \u00e1reas. Destac\u00f3&nbsp; que todos los procesos han sido revisados y se han integrado los beneficios que ofrece la tecnolog\u00eda&nbsp; para garantizar la higiene y salud de los visitantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 el incremento del uso de plataformas en l\u00ednea para los procesos de reservas. Santos expone que la industria se enfrenta a un turista m\u00e1s adaptado al uso de las plataformas digitales, lo que obliga a la diversificaci\u00f3n de la industria. \u201cLas personas han descubierto una nueva modalidad de hacer turismo, que no es solo el todo incluido sino tambi\u00e9n el uso y alquiler de villas y apartamentos a trav\u00e9s de las plataformas en l\u00ednea\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santos estima que los cambios generados en la industria son una gran oportunidad para que el sector diversifique su oferta&nbsp; y logre mayores flujos y el c\u00edrculo virtuoso tenga mayores alcances.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se disparan las inversiones de doble uso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los proyectos inmobiliarios en el sector tur\u00edstico se han vuelto cada vez m\u00e1s diversos y la pandemia ha hecho que un nuevo inversionista, m\u00e1s local, con limitada liquidez, encuentre oportunidades en proyectos habitacionales con vocaci\u00f3n tur\u00edstica, una tendencia que crece y que desafia la oferta hotelera tradicional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los expertos inmobiliarios, Juan Est\u00e9vez y Eduardo Navarro, de la firma Mr. Home, refieren que las inversiones en proyectos habitacionales con fines tur\u00edsticos se han disparado en el pa\u00eds, sobre todo en la zona este (Punta Cana,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Terrenas), adem\u00e1s de Jarabacoa, que son destinos con alta demanda para inversi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1alaron que en la actualidad hay muchos dominicanos que viven en el extranjero y tambi\u00e9n peque\u00f1os inversionistas locales, buscando proyectos innovadores de doble uso, o sea , que puedan usar para vacacionar pero que puedan alquilar con AirBNB&nbsp; y as\u00ed rentabilizar su dinero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al referirse a los cambios que se han generado despu\u00e9s de la pandemia, los expertos en negocios inmobiliarios refieren que hay un fen\u00f3meno y es que muchas personas se han volcado a invertir en propiedades en zonas de alta demanda tur\u00edstica, como apartamentos u otros proyectos innovadores, con doble finalidad: uso propio y tambi\u00e9n para alquilar por Air BnB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agregan que otra tendencia que se vive actualmente son los proyectos conceptualizados como&nbsp; \u201ccondohotel\u201d, muchas veces para ser operados por firmas hoteleras internacionales que quieren establecerse en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos grandes operadores hoteleros intentando entrar al pa\u00eds a trav\u00e9s de este modelo, tenemos algunos proyectos que vienen en camino con esa conceptualizaci\u00f3n\u201d, aseguraron Est\u00e9vez y Navarro al ser consultados por LIST\u00cdN DIARIO.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la pregunta de \u00bfC\u00f3mo ha crecido la demanda de proyectos con caracter\u00edsticas \u201cFriendly y AirBnB\u201d en el pa\u00eds, luego de la reapertura econ\u00f3mica? Los especialistas&nbsp; indicaron que ha crecido bastante, ya que el mercado ha tenido un gran auge a trav\u00e9s de los dominicanos ausentes&nbsp; y los peque\u00f1os inversionistas locales que han encontrado una mayor rentabilidad de inversi\u00f3n&nbsp; en bienes ra\u00edces, las ventajas competitivas que existen en el pa\u00eds con las bajas tasas de inter\u00e9s, la calidad de los proyectos que se est\u00e1n trabajando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodo esto ha permitido que la gente se vuelque hacia invertir en bienes ra\u00edces procurando una rentabilidad del 10, 11 o 12% anual\u201d, exponen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente, el presidente de la Asociaci\u00f3n de Hoteles y Turismo de la Rep\u00fablica Dominicana, Rafael Blanco Tejera, expuso que a la fecha se han aprobado y est\u00e1n en proceso de ejecuci\u00f3n diversos proyectos en las zonas tur\u00edsticas, por alrededor de US$550 millones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La industria tur\u00edstica se vio forzada&nbsp; a&nbsp; reinventarse para impulsar una de las recuperaciones m\u00e1s asombrosas que ha experimentado la econom\u00eda dominicana, con una llegada rec\u00f3rd de turistas de 519,349 en noviembre de este a\u00f1o, sobrepasando las cifras logradas en noviembre del 2019, previo a la pandemia. Es innegable que para alcanzar estos resultados es mucho el trabajo realizado para que hoteles, bares y restaurantes lograr\u00e1n adaptarse a un mundo totalmente transformado con un turista m\u00e1s exigente, m\u00e1s adiestrado tecnol\u00f3gicamente, con un abanico de ofertas disponibles que supera el todo incluido, dispuesto a vivir experiencias menos convencionales y a mejores costos. La industria tur\u00edstica dominicana se dio cuenta a tiempo de la importancia de unirse a los esfuerzos que desde el Gobierno se hac\u00edan para lograr un alto grado de personas vacunadas que permitiera una apertura econ\u00f3mica sostenible y se enfoc\u00f3 en exigir a sus trabajadores las dos dosis de vacuna, como forma certera de atraer a un turista ansioso de libertad pero con temor a enfermarse. Esta industria, que en los meses de abril, mayo, junio y julio del 2020, vio desaparecer practicamente toda su actividad&nbsp; econ\u00f3mica y se sinti\u00f3 tambalear, se dio cuenta a tiempo de que el turismo interno ser\u00eda su \u00fanico soporte, a pesar de las restricciones, y desde ese momento empez\u00f3 a reinventarse, adapt\u00e1ndose a los protocolos, a las restricciones horarias y a un turista criollo con menos recursos, pero en definitiva su tabla de salvaci\u00f3n en medio de la crisis. Igual sucedi\u00f3 en el turismo de ciudad, donde hoteles, bares y restaurantes asumieron nuevas maneras de mantener sus clientes, ofreciendo servicios m\u00e1s personalizados, experiencias m\u00e1s familiares e integrando la tecnolog\u00eda como la mejor opci\u00f3n de un servicio acorde con los protocolos mpuestos por el Covid-19. Reinventarse&nbsp; o&nbsp; acumular p\u00e9rdidas. Reinventarse o perder su posicionamiento en la regi\u00f3n, ese fue el dilema. Se crearon mecanismos de burbujas sanitarias con pruebas PCR y seguimiento de los trabajadores en riesgo, reduciendo as\u00ed los contagios durante la reactivaci\u00f3n del sector. El sector ha recuperado su ritmo y las proyecciones son realmente halag\u00fce\u00f1as para las pr\u00f3ximas temporadas,&nbsp; aunque muchos de sus trabajadores, que esperaron m\u00e1s de un a\u00f1o suspendidos, desesperados por la crisis buscaron otra forma de ganar dinero y no se han reintegrado, lo que consta en un reporte reciente del corresponsal del List\u00edn Diario en la zona Este, Florentino Dur\u00e1n, en el que el presidente de la Asociaci\u00f3n de Hoteles y Proyectos Tur\u00edsticos del Este (Asodeste), Ernesto Veloz, se\u00f1ala que empleados que salieron de los hoteles, no han regresado y que en la actualidad existen cerca de 5,000 plazas vacantes en la zona. Opinan periodistas turisticosDefinitivamente, la industria ha cambiado, sostiene el periodista&nbsp; especializado en turismo, Salvador Batista. Expone que en la actualidad&nbsp; se tiene mucho m\u00e1s cuidado de c\u00f3mo tratar al turista, pues la pandemia dej\u00f3 un visitante m\u00e1s exigente y cuidadoso. Este visitante procura que los establecimientos tengan las medidas protocolares para su protecci\u00f3n,&nbsp; tienen mecanismos digitales para denunciar si les pareci\u00f3 bien o no un destino, hotel o restaurantes, esto ha puesto en jaque a los complejos tur\u00edsticos, explica Batista, puntualizando que&nbsp; los&nbsp; empresarios del sector tur\u00edstico han tenido que hacer millonarias inversiones para no verse opacados ante sus competidores. El turismo ha dado un giro de 180 grados, insiste el comunicador, debido principalmente a la forma de las personas viajar.. Refiere que en el caso de los viajes internacionales muchos se han limitado y realizan sus reservas de manera directa a trav\u00e9s de las plataformas digitales. Sostiene que la intermediaci\u00f3n de las agencias de viaje ha bajado bastante. Indica el eriodista y productor del programa \u201cRecorriendo con Salvador\u201d, que los destinos que buscan los visitantes ya no son los mismos&nbsp; debido a que&nbsp; muchos turistas se han enfocado en destinos abiertos, sobre todo que muestren mucha naturaleza y playas, contrario a tiempos atr\u00e1s que se buscaba muchos destinos culturales. El confinamiento cambi\u00f3 la forma del turista definir sus viajes. La periodista Naivi Fr\u00edas, especializada en turismo, refiere que lo que cambi\u00f3 en la industria es que la gente est\u00e1 valorando m\u00e1s el turismo de experiencia como alternativa al turismo masivo del todo incluido o de los grandes tour y hacer turismo en su propio territorio. \u201cNo es una tendencia en Rep\u00fablica Dominicana, que la gente coja para los pueblos, sino que es una tendencia mundial, conocer sus propios territorios\u201d. Explica que, luego de la pandemia, el turista tiende m\u00e1s a viajes experienciales, en grupos peque\u00f1os y busca alternativas m\u00e1s a la aventura y a la comunidad. \u201cEst\u00e1 pensando m\u00e1s en quedarse en villas, casas de campa\u00f1as, Air BnB y alquiler de plataformas digitales que ofrecen una variedad de opciones que van m\u00e1s all\u00e1 del todo incluido\u201d apunta Fr\u00edas. Destaca que entre los cambios que llegaron para quedarse se encuentran m\u00e1s herramientas que garanticen los protocolos sanitarios, brindar experiencias que no sean masivas. Sostiene que muchos hoteles promueven de manera gratuita el servicio al cuarto para evitar las aglomeraciones en los restaurantes, como opci\u00f3n para clientes que no quieren permanecer en lugares cerrados, por lo que tambi\u00e9n se notan mayores inversiones en hacer m\u00e1s agradable los espacios abiertos. Fr\u00edas, quien produce y conduce el programa radial \u201cP\u00e1rate Ah\u00ed Tours\u201d, se\u00f1al\u00f3 que las nuevas ofertas de hospedajes que se ofrecen a trav\u00e9s de distintas plataformas digitales en principio han creado preocupaci\u00f3n por su impacto en los complejos hoteleros y aunque estos han tenido que \u201csacar sus garras\u201d para mantener su supremac\u00eda, lo que en realidad se ve es que la oferta tur\u00edstica se ha diversificado y eso termina atrayendo un flujo mayor de visitantes. Se\u00f1ala que el reto actual de los hoteles es responder de manera adecuada y eficiente a las nuevas exigencias del viajero de hoy. CIFRAS 4.2MMVisitantes.&nbsp;Al cierre de noviembre, el Ministerio de Turismo contabilizaba la llegada de 4,263,259 visitantes al pa\u00eds. A la fecha se habia recuperado el 73% de los visitantes no residentes, en comparaci\u00f3n al 2019. 27%Turismo familiar.&nbsp;El turismo familiar aport\u00f3 el 27% del turismo en noviembre 2021 con estad\u00eda [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":83660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[460],"tags":[],"class_list":["post-83659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-turismo-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83659"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83659\/revisions"}],"predecessor-version":[{"id":83661,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83659\/revisions\/83661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83660"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}