{"id":83665,"date":"2021-12-10T15:26:45","date_gmt":"2021-12-10T19:26:45","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83665"},"modified":"2021-12-10T15:34:36","modified_gmt":"2021-12-10T19:34:36","slug":"carmen-salinas-fallecio-a-los-82-anos-de-edad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/carmen-salinas-fallecio-a-los-82-anos-de-edad\/","title":{"rendered":"Carmen Salinas falleci\u00f3 a los 82 a\u00f1os de edad"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"862\" height=\"537\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/Carmen-Salinas.jpg\" alt=\"\" class=\"wp-image-83666\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/Carmen-Salinas.jpg 862w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/Carmen-Salinas-300x187.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/Carmen-Salinas-768x478.jpg 768w\" sizes=\"auto, (max-width: 862px) 100vw, 862px\" \/><figcaption>Carmen Salinas, Actriz<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> Ella fue una de las m\u00e1s emblem\u00e1ticas personalidades mexicanas, pues era querida por el p\u00fablico debido a sus ic\u00f3nicos papeles en televisi\u00f3n y su carisma, \u201cLa Corcholata\u201d llevaba en coma desde el pasado 11 de noviembre <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actriz, productora y empresaria\u00a0<strong>Carmen Salinas<\/strong>\u00a0falleci\u00f3 este 9 de diciembre a los 82 a\u00f1os de edad luego de sufrir un derrame cerebral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carmelita Salinas se encontraba internada en un hospital de la&nbsp;<strong>Ciudad de M\u00e9xico<\/strong>&nbsp;desde la madrugada del 11 de noviembre debido a que sufri\u00f3 un severo problema de salud que la llev\u00f3 a estar en terapia intensiva y en coma.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.infobae.com\/new-resizer\/WXrDggvY-NDTVhiLPFfRBNteHt0=\/420x420\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/GQD65OR3J5COTMCSEZE74JWYQM.JPG%20420w\" alt=\"Este es el mensaje que se puede leer en su cuenta oficial (Foto: Instagram\/@carmensalinas_56)\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Este es el mensaje que se puede leer en su cuenta oficial (Foto: Instagram\/@carmensalinas_56)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue a trav\u00e9s de la cuenta oficial del productor<strong>&nbsp;Juan Osorio&nbsp;<\/strong>que se supo del deceso de la famosa \u201cCorcholata\u201d de la&nbsp;<strong>\u00c9poca del Cine de Ficheras en M\u00e9xico.<\/strong>&nbsp;En el comunicado emitido por la familia de la actriz, se puede leer lo siguiente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsta noche ser\u00e1 recordada con una gran tristeza,&nbsp;<strong>\u2066Carmelita Salinas ya est\u00e1 con Dios.&nbsp;<\/strong>Dej\u00e1ndonos su gran legado. QEPD\u201d, escribi\u00f3 el productor. Por otra parte, en la cuenta oficial de la talentosa actriz, su familia coloc\u00f3 un mensaje para honrarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2018Por su dolorosa pasi\u00f3n, ten misericordia de nosotros y del mundo entero\u2019&nbsp;<strong>Con profundo dolor, hacemos de su conocimiento que la primera actriz Carmen Salinas, ha fallecido el d\u00eda de hoy 9 de Diciembre del 2021.\u201d<\/strong>, se lee en la cuenta oficial de Instagram de esta actriz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El deceso de la actriz de producciones como&nbsp;<em>Mar\u00eda la del barrio<\/em>&nbsp;(1975),&nbsp;<em>La misma luna<\/em>&nbsp;(2007) y&nbsp;<em>Mujeres Asesinas 2<\/em><strong>&nbsp;conmocion\u00f3 a sus millones de seguidores<\/strong>, quienes estaban pendientes de su estado de salud desde el momento en que se dio a conocer su hospitalizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La hospitalizaci\u00f3n se dio a conocer el 11 de noviembre<\/strong>\u00a0mediante un comunicado en el que se ley\u00f3:\u00a0<em>\u201c<\/em>La familia Salinas les comparte que la primera actriz Carmen Salinas atraviesa por una dif\u00edcil situaci\u00f3n de salud, raz\u00f3n por la cual permanece en el \u00e1rea de terapia intensiva donde los m\u00e9dicos especialistas la atienden\u201d<em>,<\/em>\u00a0expres\u00f3 su sobrino Gustavo Briones por medio de un anuncio.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/nota-de-luto-carmen-salina.jpg\" alt=\"\" class=\"wp-image-83671\" width=\"453\" height=\"455\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/nota-de-luto-carmen-salina.jpg 378w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/nota-de-luto-carmen-salina-298x300.jpg 298w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/nota-de-luto-carmen-salina-150x150.jpg 150w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carmelita Salinas<\/strong>\u00a0pas\u00f3 varios d\u00edas en coma por un derrame cerebral, de acuerdo con el primer parte m\u00e9dico que dieron a conocer su nieta\u00a0<strong>Carmen Plascencia<\/strong>\u00a0y su sobrino<strong>\u00a0Gustavo Briones<\/strong>. Los familiares de la actriz se\u00f1alaron que su estado de salud era muy grave\u00a0debido a la enfermedad vascular cerebral que sufri\u00f3\u00a0en la noche del mi\u00e9rcoles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cActualmente mi abuelita est\u00e1 en un estado de coma con sus \u00f3rganos est\u00e1n funcionando de manera natural, es decir, ella est\u00e1 haciendo que funcionen.El diagn\u00f3stico es un derrame cerebral y estamos esperando para ver c\u00f3mo progresa\u201d,dijo de forma inicial su nieta Carmen Plasencia ante las c\u00e1maras del matutino&nbsp;<em>Hoy.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.infobae.com\/new-resizer\/ISQO5klmq9oUiU0zwSfbUjkZiBI=\/420x236\/filters:format(webp):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/JLIPMUKMS5EK3BC5TW6RO5IHTU.jpg%20420w\" alt=\"El sobrino y asistente personal de la actriz fue quien solicit\u00f3 la ambulancia y se encarg\u00f3 del internamiento de Salinas Foto: Captura de pantalla\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El sobrino y asistente personal de la actriz fue quien solicit\u00f3 la ambulancia y se encarg\u00f3 del internamiento de Salinas Foto: Captura de pantalla<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carmen Salinas pas\u00f3 sus \u00faltimos d\u00edas en coma, respirando mediante ayuda<\/strong>, pero tal como indic\u00f3 su nieta, el funcionamiento de su coraz\u00f3n y otros \u00f3rganos lo manten\u00eda por su propia cuenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace tres d\u00edas, la familia de la talentosa actriz<strong>hab\u00eda dado a conocer que Carmelita Salinas ya no ten\u00eda un derrame pero segu\u00eda delicada.<\/strong>\u00a0\u201cLa buena noticia es que ya no tiene derrame, es una gran noticia, pero sigue delicada. Le quitan el respirador, est\u00e1 respirando, pero tambi\u00e9n se lo vuelven a poner para que descanse, sigue con sus movimientos\u201d, declar\u00f3 su hija\u00a0<strong>Mar\u00eda Eugenia Plascencia<\/strong>\u00a0para las c\u00e1maras de\u00a0<em>Hoy\u00a0<\/em>en lo que se convirti\u00f3 en\u00a0<strong>uno de sus \u00faltimos partes m\u00e9dicos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oriunda de<strong>&nbsp;Torre\u00f3n, Coahuila<\/strong>, debut\u00f3 en el medio del espect\u00e1culo como imitadora, pues posee un espectacular manejo de la voz y gracias a ello logr\u00f3 cautivar al p\u00fablico de su regi\u00f3n. La actriz particip\u00f3 en concursos de talento para despu\u00e9s integrarse a una estaci\u00f3n de radio local.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/carmen-salinas-cuando-joven.jpg\" alt=\"\" class=\"wp-image-83670\" width=\"439\" height=\"583\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/carmen-salinas-cuando-joven.jpg 376w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/carmen-salinas-cuando-joven-226x300.jpg 226w\" sizes=\"auto, (max-width: 439px) 100vw, 439px\" \/><figcaption> As\u00ed luc\u00eda la actriz cuando era joven (Foto: Twitter\/@CarmenSalinasLo) <\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En 1964, el productor y director Ernesto Alonso le propuso formar parte del elenco de&nbsp;<em><strong>Casa de vecindad<\/strong><\/em>, telenovela con la que incursion\u00f3 en la pantalla chica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carmelita tuvo una de las carreras m\u00e1s nutridas<\/strong>\u00a0en el mundo del espect\u00e1culo: trabaj\u00f3 tanto como actriz como productora de teatro, especialmente de la famosa obra de teatro\u00a0<em>Aventurera<\/em>, tambi\u00e9n ocup\u00f3 un cargo p\u00fablico como diputada local del Partido Revolucionario Institucional (PRI) en el 2015, tiene\u00a0una faceta de empresaria en la industria musical\u00a0y en la comida; a finales de las 90 abri\u00f3 el restaurante\u00a0<em>La casita de las sopas.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.celebritynetworth.com\/richest-celebrities\/actors\/carmen-salinas-net-worth\/\">De acuerdo con el sitio Celebrity Neth Worth<\/a>, especializado en las fortunas de las celebridades,&nbsp;<strong>Salinas consigui\u00f3 un patrimonio neto de USD 20 millones,&nbsp;<\/strong>suma que acumul\u00f3 a lo largo de sus a\u00f1os como figura p\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ella fue una de las m\u00e1s emblem\u00e1ticas personalidades mexicanas, pues era querida por el p\u00fablico debido a sus ic\u00f3nicos papeles en televisi\u00f3n y su carisma, \u201cLa Corcholata\u201d llevaba en coma desde el pasado 11 de noviembre La actriz, productora y empresaria\u00a0Carmen Salinas\u00a0falleci\u00f3 este 9 de diciembre a los 82 a\u00f1os de edad luego de sufrir un derrame cerebral. Carmelita Salinas se encontraba internada en un hospital de la&nbsp;Ciudad de M\u00e9xico&nbsp;desde la madrugada del 11 de noviembre debido a que sufri\u00f3 un severo problema de salud que la llev\u00f3 a estar en terapia intensiva y en coma. Este es el mensaje que se puede leer en su cuenta oficial (Foto: Instagram\/@carmensalinas_56) Fue a trav\u00e9s de la cuenta oficial del productor&nbsp;Juan Osorio&nbsp;que se supo del deceso de la famosa \u201cCorcholata\u201d de la&nbsp;\u00c9poca del Cine de Ficheras en M\u00e9xico.&nbsp;En el comunicado emitido por la familia de la actriz, se puede leer lo siguiente: \u201cEsta noche ser\u00e1 recordada con una gran tristeza,&nbsp;\u2066Carmelita Salinas ya est\u00e1 con Dios.&nbsp;Dej\u00e1ndonos su gran legado. QEPD\u201d, escribi\u00f3 el productor. Por otra parte, en la cuenta oficial de la talentosa actriz, su familia coloc\u00f3 un mensaje para honrarla. \u201c\u2018Por su dolorosa pasi\u00f3n, ten misericordia de nosotros y del mundo entero\u2019&nbsp;Con profundo dolor, hacemos de su conocimiento que la primera actriz Carmen Salinas, ha fallecido el d\u00eda de hoy 9 de Diciembre del 2021.\u201d, se lee en la cuenta oficial de Instagram de esta actriz. El deceso de la actriz de producciones como&nbsp;Mar\u00eda la del barrio&nbsp;(1975),&nbsp;La misma luna&nbsp;(2007) y&nbsp;Mujeres Asesinas 2&nbsp;conmocion\u00f3 a sus millones de seguidores, quienes estaban pendientes de su estado de salud desde el momento en que se dio a conocer su hospitalizaci\u00f3n. La hospitalizaci\u00f3n se dio a conocer el 11 de noviembre\u00a0mediante un comunicado en el que se ley\u00f3:\u00a0\u201cLa familia Salinas les comparte que la primera actriz Carmen Salinas atraviesa por una dif\u00edcil situaci\u00f3n de salud, raz\u00f3n por la cual permanece en el \u00e1rea de terapia intensiva donde los m\u00e9dicos especialistas la atienden\u201d,\u00a0expres\u00f3 su sobrino Gustavo Briones por medio de un anuncio. Carmelita Salinas\u00a0pas\u00f3 varios d\u00edas en coma por un derrame cerebral, de acuerdo con el primer parte m\u00e9dico que dieron a conocer su nieta\u00a0Carmen Plascencia\u00a0y su sobrino\u00a0Gustavo Briones. Los familiares de la actriz se\u00f1alaron que su estado de salud era muy grave\u00a0debido a la enfermedad vascular cerebral que sufri\u00f3\u00a0en la noche del mi\u00e9rcoles. \u201cActualmente mi abuelita est\u00e1 en un estado de coma con sus \u00f3rganos est\u00e1n funcionando de manera natural, es decir, ella est\u00e1 haciendo que funcionen.El diagn\u00f3stico es un derrame cerebral y estamos esperando para ver c\u00f3mo progresa\u201d,dijo de forma inicial su nieta Carmen Plasencia ante las c\u00e1maras del matutino&nbsp;Hoy. El sobrino y asistente personal de la actriz fue quien solicit\u00f3 la ambulancia y se encarg\u00f3 del internamiento de Salinas Foto: Captura de pantalla Carmen Salinas pas\u00f3 sus \u00faltimos d\u00edas en coma, respirando mediante ayuda, pero tal como indic\u00f3 su nieta, el funcionamiento de su coraz\u00f3n y otros \u00f3rganos lo manten\u00eda por su propia cuenta. Hace tres d\u00edas, la familia de la talentosa actrizhab\u00eda dado a conocer que Carmelita Salinas ya no ten\u00eda un derrame pero segu\u00eda delicada.\u00a0\u201cLa buena noticia es que ya no tiene derrame, es una gran noticia, pero sigue delicada. Le quitan el respirador, est\u00e1 respirando, pero tambi\u00e9n se lo vuelven a poner para que descanse, sigue con sus movimientos\u201d, declar\u00f3 su hija\u00a0Mar\u00eda Eugenia Plascencia\u00a0para las c\u00e1maras de\u00a0Hoy\u00a0en lo que se convirti\u00f3 en\u00a0uno de sus \u00faltimos partes m\u00e9dicos. La oriunda de&nbsp;Torre\u00f3n, Coahuila, debut\u00f3 en el medio del espect\u00e1culo como imitadora, pues posee un espectacular manejo de la voz y gracias a ello logr\u00f3 cautivar al p\u00fablico de su regi\u00f3n. La actriz particip\u00f3 en concursos de talento para despu\u00e9s integrarse a una estaci\u00f3n de radio local. En 1964, el productor y director Ernesto Alonso le propuso formar parte del elenco de&nbsp;Casa de vecindad, telenovela con la que incursion\u00f3 en la pantalla chica. Carmelita tuvo una de las carreras m\u00e1s nutridas\u00a0en el mundo del espect\u00e1culo: trabaj\u00f3 tanto como actriz como productora de teatro, especialmente de la famosa obra de teatro\u00a0Aventurera, tambi\u00e9n ocup\u00f3 un cargo p\u00fablico como diputada local del Partido Revolucionario Institucional (PRI) en el 2015, tiene\u00a0una faceta de empresaria en la industria musical\u00a0y en la comida; a finales de las 90 abri\u00f3 el restaurante\u00a0La casita de las sopas. De acuerdo con el sitio Celebrity Neth Worth, especializado en las fortunas de las celebridades,&nbsp;Salinas consigui\u00f3 un patrimonio neto de USD 20 millones,&nbsp;suma que acumul\u00f3 a lo largo de sus a\u00f1os como figura p\u00fablica.<\/p>\n","protected":false},"author":12,"featured_media":83666,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-83665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83665"}],"version-history":[{"count":4,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83665\/revisions"}],"predecessor-version":[{"id":83673,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83665\/revisions\/83673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83666"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}