{"id":83674,"date":"2021-12-10T16:15:43","date_gmt":"2021-12-10T20:15:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83674"},"modified":"2021-12-10T16:15:49","modified_gmt":"2021-12-10T20:15:49","slug":"construiran-linea-de-tren-desde-la-27-hasta-el-aeropuerto-las-americas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/construiran-linea-de-tren-desde-la-27-hasta-el-aeropuerto-las-americas\/","title":{"rendered":"Construir\u00e1n l\u00ednea de tren desde la 27 hasta el Aeropuerto las Am\u00e9ricas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"517\" src=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/metro-de-santo-domingo.jpg\" alt=\"\" class=\"wp-image-83675\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/metro-de-santo-domingo.jpg 785w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/metro-de-santo-domingo-300x198.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/metro-de-santo-domingo-768x506.jpg 768w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><figcaption>Metro de Santo Domingo<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SANTO DOMINGO.- <\/strong>Francia y la Rep\u00fablica Dominicana anunciaron hoy un acuerdo para la construcci\u00f3n de una l\u00ednea de tren que ir\u00eda desde la 27 de febrero hasta el Aeropuerto Internacional de Las Am\u00e9ricas, adem\u00e1s de un Monorriel en la ciudad de Santiago.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los acuerdos incluye adem\u00e1s un contrato de cr\u00e9dito de 86 millones de euros por parte de la Agencia Francesa de Desarrollo que permitir\u00e1 duplicar la longitud de los trenes del metro de Santo Domingo, de la l\u00ednea 1 (alargamiento de 3 a 6 vagones) con el fin de transportar alrededor de 66.000 pasajeros adicionales por d\u00eda laborable en esta l\u00ednea y, en consecuencia, reducir las filas de espera en las horas pico.<strong>Los documentos suscritos estuvieron a cargo del ministro de la Presidencia, Lisandro Macarulla, en representaci\u00f3n del Estado dominicano y el ministro franc\u00e9s de Comercio Exterior, Franck Riester en representaci\u00f3n del estado franc\u00e9s.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas firmas estuvieron enmarcadas en la realizaci\u00f3n de la Semana de Francia organizada por la C\u00e1mara de Comercio e Industria Franco-Dominicana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata primero de un\u00a0convenio\u00a0bilateral entre ambas naciones en donde se comprometen a trabajar en conjunto para el desarrollo de la red de transporte masivo de las ciudades de Santo Domingo y Santiago de los Caballeros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este acuerdo forma parte de un marco estrat\u00e9gico global formalizado en la Hoja de Ruta de Cooperaci\u00f3n 2021-2023 entre el Grupo AFD y la Rep\u00fablica Dominicana, que describe las perspectivas de cooperaci\u00f3n t\u00e9cnica y financiera para acompa\u00f1ar las transiciones ecol\u00f3gicas, clim\u00e1ticas, sociales y econ\u00f3micas del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los acuerdos logrados por el Gobierno Dominicano, con el apoyo del Gobierno Franc\u00e9s, permitir\u00e1n que la Rep\u00fablica Dominicana alcance la mayor cobertura territorial de los sistemas de transporte masivo, aumentando la calidad de vida de los ciudadanos mediante la reducci\u00f3n del gasto de transporte, que representa el 25% de las familias de escasos recursos, y reduciendo la huella de carbono a trav\u00e9s de la implementaci\u00f3n de sistemas sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El seguimiento y la implementaci\u00f3n de estos proyectos est\u00e1n a cargo de la Oficina Para el Desarrollo de Proyectos de Movilidad Urbana e Interurbana que depende del Ministerio de la Presidencia (MINPRE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La firma de estos acuerdos pone de manifiesto la confianza depositada en la experiencia francesa tanto en materia tecnol\u00f3gica como financiera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Semana de Francia se desarrolla esta semana en la capital dominicana bajo el tema de la \u201cCiudad Sostenible\u201d y ha permitido, adem\u00e1s de los temas del transporte urbano, intercambiar sobre los temas de financiaci\u00f3n verde, ciudad inteligente, energ\u00edas renovables y agua, saneamiento y desechos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/eldia.com.do\/construiran-linea-de-tren-desde-la-27-hasta-el-aeropuerto-las-americas\/\">FUENTE<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- Francia y la Rep\u00fablica Dominicana anunciaron hoy un acuerdo para la construcci\u00f3n de una l\u00ednea de tren que ir\u00eda desde la 27 de febrero hasta el Aeropuerto Internacional de Las Am\u00e9ricas, adem\u00e1s de un Monorriel en la ciudad de Santiago.\u00a0 Los acuerdos incluye adem\u00e1s un contrato de cr\u00e9dito de 86 millones de euros por parte de la Agencia Francesa de Desarrollo que permitir\u00e1 duplicar la longitud de los trenes del metro de Santo Domingo, de la l\u00ednea 1 (alargamiento de 3 a 6 vagones) con el fin de transportar alrededor de 66.000 pasajeros adicionales por d\u00eda laborable en esta l\u00ednea y, en consecuencia, reducir las filas de espera en las horas pico.Los documentos suscritos estuvieron a cargo del ministro de la Presidencia, Lisandro Macarulla, en representaci\u00f3n del Estado dominicano y el ministro franc\u00e9s de Comercio Exterior, Franck Riester en representaci\u00f3n del estado franc\u00e9s. Estas firmas estuvieron enmarcadas en la realizaci\u00f3n de la Semana de Francia organizada por la C\u00e1mara de Comercio e Industria Franco-Dominicana. Se trata primero de un\u00a0convenio\u00a0bilateral entre ambas naciones en donde se comprometen a trabajar en conjunto para el desarrollo de la red de transporte masivo de las ciudades de Santo Domingo y Santiago de los Caballeros. Este acuerdo forma parte de un marco estrat\u00e9gico global formalizado en la Hoja de Ruta de Cooperaci\u00f3n 2021-2023 entre el Grupo AFD y la Rep\u00fablica Dominicana, que describe las perspectivas de cooperaci\u00f3n t\u00e9cnica y financiera para acompa\u00f1ar las transiciones ecol\u00f3gicas, clim\u00e1ticas, sociales y econ\u00f3micas del pa\u00eds. Los acuerdos logrados por el Gobierno Dominicano, con el apoyo del Gobierno Franc\u00e9s, permitir\u00e1n que la Rep\u00fablica Dominicana alcance la mayor cobertura territorial de los sistemas de transporte masivo, aumentando la calidad de vida de los ciudadanos mediante la reducci\u00f3n del gasto de transporte, que representa el 25% de las familias de escasos recursos, y reduciendo la huella de carbono a trav\u00e9s de la implementaci\u00f3n de sistemas sostenibles. El seguimiento y la implementaci\u00f3n de estos proyectos est\u00e1n a cargo de la Oficina Para el Desarrollo de Proyectos de Movilidad Urbana e Interurbana que depende del Ministerio de la Presidencia (MINPRE). La firma de estos acuerdos pone de manifiesto la confianza depositada en la experiencia francesa tanto en materia tecnol\u00f3gica como financiera. La Semana de Francia se desarrolla esta semana en la capital dominicana bajo el tema de la \u201cCiudad Sostenible\u201d y ha permitido, adem\u00e1s de los temas del transporte urbano, intercambiar sobre los temas de financiaci\u00f3n verde, ciudad inteligente, energ\u00edas renovables y agua, saneamiento y desechos. FUENTE<\/p>\n","protected":false},"author":12,"featured_media":83675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-83674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83674"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83674\/revisions"}],"predecessor-version":[{"id":83676,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83674\/revisions\/83676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83675"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}