{"id":83694,"date":"2021-12-12T08:47:39","date_gmt":"2021-12-12T12:47:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=83694"},"modified":"2021-12-12T08:47:43","modified_gmt":"2021-12-12T12:47:43","slug":"haiti-defensa-de-la-democracia-e-integracion-economica-los-temas-de-la-alianza-para-el-desarrollo-en-democracia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/haiti-defensa-de-la-democracia-e-integracion-economica-los-temas-de-la-alianza-para-el-desarrollo-en-democracia\/","title":{"rendered":"Haiti, defensa de la democracia e integraci\u00f3n econ\u00f3mica: Los temas de la Alianza para el Desarrollo en Democracia"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/202112112017201.jpeg\" alt=\"\" class=\"wp-image-83695\" width=\"301\" height=\"201\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/202112112017201.jpeg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2021\/12\/202112112017201-300x200.jpeg 300w\" sizes=\"auto, (max-width: 301px) 100vw, 301px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">El reclamo para que la comunidad internacional asuma la b\u00fasqueda de alternativas para una soluci\u00f3n a la crisis de Hait\u00ed, la defensa de los valores democr\u00e1ticos, con el llamado a la libertad de los presos pol\u00edticos en Nicaragua, y la promoci\u00f3n del comercio, adem\u00e1s de la integraci\u00f3n econ\u00f3mica, son los temas centrales de la declaraci\u00f3n de Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los presidentes Carlos Alvarado de Costa Rica; Laurentino Cortizo de Panam\u00e1 y Luis Abinader de Rep\u00fablica Dominicana, al concluir los trabajos del tercer encuentro en el marco de la Alianza para el Desarrollo en Democracia, leyeron una declaraci\u00f3n conjunta en el Malec\u00f3n de Puerto Plata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El documento establece que los tres mandatarios renuevan su compromiso con el estado de derecho, la democracia, el respeto de los derechos humanos y la libertad de expresi\u00f3n, esp\u00edritu fundacional de esta alianza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hait\u00ed<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los presidentes llamaron a la comunidad internacional, en particular a los Estados Unidos, la Uni\u00f3n Europea&nbsp;<strong>y a Canad\u00e1 a brindar todo el apoyo a la Polic\u00eda Nacional Haitiana para mejorar el clima de seguridad en ese pa\u00eds.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Igualmente le hicieron un llamado al Programa de las Naciones Unidas y a la Organizaci\u00f3n Panamericana de la Salud a fortalecer el sistema de salud de Hait\u00ed, con \u00e9nfasis en la atenci\u00f3n materno infantil, la vacunaci\u00f3n contra el Covid y la medicina en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Reiteraron la propuesta presentada en Panam\u00e1 sobre una hoja de ruta para un Plan de Desarrollo Integral para Hait\u00ed,&nbsp;<\/strong>que incluya la pacificaci\u00f3n, mejora de las infraestructuras, la reforestaci\u00f3n y el financiamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Valoraci\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n al di\u00e1logo pol\u00edtico, los mandatarios valoraron su participaci\u00f3n en la Cumbre por la Democracia convocada por el presidente de los Estados Unidos, Joe Biden, en particular la defensa del sistema democr\u00e1tico y sus valores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felicitaron al pueblo hondure\u00f1o, a las autoridades electorales de ese pa\u00eds y a la se\u00f1ora Xiomara Castro de Zelaya, primera mujer electa presidente de ese pa\u00eds por la exitosa jornada electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nicaragua<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con relaci\u00f3n a Nicaragua reiteraron la preocupaci\u00f3n por la situaci\u00f3n de ese pa\u00eds y demandaron la liberaci\u00f3n inmediata de los presos pol\u00edticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Encomendaron a los ministros de relaciones exteriores<strong>&nbsp;dar a conocer los prop\u00f3sitos de la alianza a nivel internacional.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destacaron la relaci\u00f3n s\u00f3lida de los tres pa\u00edses y se congratularon de la firma del memorando de entendimiento que dispone la creaci\u00f3n de un grupo de trabajo ministerial para profundizar sinergias, detectar oportunidades de regionalizaci\u00f3n en las cadenas de valor y fortalecer las relaciones comerciales, as\u00ed como las complementariedades de las econom\u00edas de los pa\u00edses y la creaci\u00f3n de una comisi\u00f3n empresarial de alto nivel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anunciaron que&nbsp;<strong>la pr\u00f3xima reuni\u00f3n de la alianza se realizar\u00e1 en Costa Rica en el primer trimestre del 2022.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los mandatarios recibieron la declaraci\u00f3n de visitantes distinguidos por parte del Ayuntamiento de Puerto Plata, recibiendo las placas conmemorativas del alcalde Diomedes Roque Garc\u00eda y la presidenta de la Sala Capitular, Ang\u00e9lica L\u00f3pez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Edgar Lantigua<\/strong><strong>Puerto Plata, RD.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El reclamo para que la comunidad internacional asuma la b\u00fasqueda de alternativas para una soluci\u00f3n a la crisis de Hait\u00ed, la defensa de los valores democr\u00e1ticos, con el llamado a la libertad de los presos pol\u00edticos en Nicaragua, y la promoci\u00f3n del comercio, adem\u00e1s de la integraci\u00f3n econ\u00f3mica, son los temas centrales de la declaraci\u00f3n de Puerto Plata. Los presidentes Carlos Alvarado de Costa Rica; Laurentino Cortizo de Panam\u00e1 y Luis Abinader de Rep\u00fablica Dominicana, al concluir los trabajos del tercer encuentro en el marco de la Alianza para el Desarrollo en Democracia, leyeron una declaraci\u00f3n conjunta en el Malec\u00f3n de Puerto Plata. El documento establece que los tres mandatarios renuevan su compromiso con el estado de derecho, la democracia, el respeto de los derechos humanos y la libertad de expresi\u00f3n, esp\u00edritu fundacional de esta alianza. Hait\u00ed Los presidentes llamaron a la comunidad internacional, en particular a los Estados Unidos, la Uni\u00f3n Europea&nbsp;y a Canad\u00e1 a brindar todo el apoyo a la Polic\u00eda Nacional Haitiana para mejorar el clima de seguridad en ese pa\u00eds. Igualmente le hicieron un llamado al Programa de las Naciones Unidas y a la Organizaci\u00f3n Panamericana de la Salud a fortalecer el sistema de salud de Hait\u00ed, con \u00e9nfasis en la atenci\u00f3n materno infantil, la vacunaci\u00f3n contra el Covid y la medicina en general. Reiteraron la propuesta presentada en Panam\u00e1 sobre una hoja de ruta para un Plan de Desarrollo Integral para Hait\u00ed,&nbsp;que incluya la pacificaci\u00f3n, mejora de las infraestructuras, la reforestaci\u00f3n y el financiamiento. Valoraci\u00f3n Con relaci\u00f3n al di\u00e1logo pol\u00edtico, los mandatarios valoraron su participaci\u00f3n en la Cumbre por la Democracia convocada por el presidente de los Estados Unidos, Joe Biden, en particular la defensa del sistema democr\u00e1tico y sus valores. Felicitaron al pueblo hondure\u00f1o, a las autoridades electorales de ese pa\u00eds y a la se\u00f1ora Xiomara Castro de Zelaya, primera mujer electa presidente de ese pa\u00eds por la exitosa jornada electoral. Nicaragua Con relaci\u00f3n a Nicaragua reiteraron la preocupaci\u00f3n por la situaci\u00f3n de ese pa\u00eds y demandaron la liberaci\u00f3n inmediata de los presos pol\u00edticos. Encomendaron a los ministros de relaciones exteriores&nbsp;dar a conocer los prop\u00f3sitos de la alianza a nivel internacional. Destacaron la relaci\u00f3n s\u00f3lida de los tres pa\u00edses y se congratularon de la firma del memorando de entendimiento que dispone la creaci\u00f3n de un grupo de trabajo ministerial para profundizar sinergias, detectar oportunidades de regionalizaci\u00f3n en las cadenas de valor y fortalecer las relaciones comerciales, as\u00ed como las complementariedades de las econom\u00edas de los pa\u00edses y la creaci\u00f3n de una comisi\u00f3n empresarial de alto nivel. Anunciaron que&nbsp;la pr\u00f3xima reuni\u00f3n de la alianza se realizar\u00e1 en Costa Rica en el primer trimestre del 2022. Los mandatarios recibieron la declaraci\u00f3n de visitantes distinguidos por parte del Ayuntamiento de Puerto Plata, recibiendo las placas conmemorativas del alcalde Diomedes Roque Garc\u00eda y la presidenta de la Sala Capitular, Ang\u00e9lica L\u00f3pez. Edgar LantiguaPuerto Plata, RD.<\/p>\n","protected":false},"author":9,"featured_media":83695,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-83694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=83694"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83694\/revisions"}],"predecessor-version":[{"id":83696,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/83694\/revisions\/83696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/83695"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=83694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=83694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=83694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}